{"id":101617,"date":"2017-05-15T09:55:34","date_gmt":"2017-05-15T14:55:34","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/2017\/05\/15\/acknowledgements-8-3\/"},"modified":"2024-04-14T04:14:37","modified_gmt":"2024-04-14T09:14:37","slug":"acknowledgements-8-3","status":"publish","type":"post","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/acknowledgements-8-3\/","title":{"rendered":"Acknowledgements"},"content":{"rendered":"<p class=\"wp-block-paragraph\">This report is a collaborative effort based on the input and analysis of the following individuals:<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Primary Researchers<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Scott Keeter, <em>Senior Survey Advisor<\/em><em>\n<\/em>Nick Hatley, <em>Research Assistant<\/em><em>\n<\/em>Courtney Kennedy, <em>Director, Survey Research\n<\/em>Andrew Mercer, <em>Senior Research Methodologist\n<\/em>Arnold Lau, <em>Research Analyst<\/em><em>\n<\/em>Kyley McGeeney, <em>Former <\/em><em>Senior Research Methodologist\n<\/em>Junjie Chen, <em>Former <\/em><em>Intern\n<\/em>Greg Smith, <em>Associate Director of Research<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0<\/strong><strong>Editorial and Graphic Design<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Bill Webster, <em>Information Graphics Designer<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0<\/strong><strong>Communications and Web Publishing<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Rachel Weisel, <em>Communications Manager\n<\/em>Hannah Klein, <em>Communications Associate\n<\/em>Travis Mitchell, <em>Digital Producer, Copy Editor<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>\u00a0<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>This report is a collaborative effort based on the input and analysis of the following individuals: Primary Researchers Scott Keeter, Senior Survey Advisor Nick Hatley, Research Assistant Courtney Kennedy, Director, Survey Research Andrew Mercer, Senior Research Methodologist Arnold Lau, Research Analyst Kyley McGeeney, Former Senior Research Methodologist Junjie Chen, Former Intern Greg Smith, Associate Director [&hellip;]<\/p>\n","protected":false},"author":367,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","apple_news_api_id":"","apple_news_api_revision":"","apple_news_api_created_at":"","apple_news_api_modified_at":"","apple_news_api_share_url":"","apple_news_api_pending":"","apple_news_is_preview":false,"apple_news_is_hidden":false,"relatedPosts":[],"reportMaterials":[],"multiSectionReport":[],"package_parts__enabled":false,"package_parts":[],"datacite_doi":"","datacite_doi_citation":"","_prc_seo_qr_attachment_id":0,"spoken_article_player_enabled":true,"displayBylines":true,"footnotes":"","prc_watchers":[],"_prc_fork_parent":0,"_prc_fork_status":"","_prc_active_fork":0},"categories":[357,358],"tags":[],"bylines":[],"datasets":[],"level_of_effort":[],"primary_audience":[],"information_type":[],"_post_visibility":[],"formats":[458],"_fund_pool":[],"languages":[],"regions-countries":[],"research-teams":[528],"workflow-status":[],"collection":[],"class_list":["post-101617","post","type-post","status-publish","format-standard","hentry","category-survey-methods","category-telephone-surveys","formats-report","research-teams-methods"],"label":"Report","post_parent":101634,"word_count":84,"canonical_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/acknowledgements-8-3\/","art_direction":false,"_embeds":[],"prc_checklist":{"prc-image-alt-text":{"status":"complete","message":"No image blocks in content.","data":null},"prc-about-this-research":{"status":"incomplete","message":"Add an \"About this research\" details block.","data":null},"prc-paragraph-count":{"status":"complete","message":"Found 7 paragraphs.","data":{"count":7}},"prc-internal-link":{"status":"incomplete","message":"Add at least one internal link.","data":{"count":0}}},"watchChildPosts":false,"watchers":[],"table_of_contents":[{"id":101634,"title":"What Low Response Rates Mean for Telephone Surveys","slug":"what-low-response-rates-mean-for-telephone-surveys","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/what-low-response-rates-mean-for-telephone-surveys\/","is_active":false},{"id":101617,"title":"Acknowledgements","slug":"acknowledgements-8-3","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/acknowledgements-8-3\/","is_active":true},{"id":101628,"title":"Methodology","slug":"methodology-6-8","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/methodology-6-8\/","is_active":false}],"report_materials":[],"report_pagination":{"current_post":{"id":101617,"title":"Acknowledgements","slug":"acknowledgements-8-3","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/acknowledgements-8-3\/","is_active":true,"page_num":2},"next_post":{"id":101628,"title":"Methodology","slug":"methodology-6-8","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/methodology-6-8\/","is_active":false,"page_num":3},"previous_post":{"id":101634,"title":"What Low Response Rates Mean for Telephone Surveys","slug":"what-low-response-rates-mean-for-telephone-surveys","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/what-low-response-rates-mean-for-telephone-surveys\/","is_active":false,"page_num":1},"pagination_items":[{"id":101634,"title":"What Low Response Rates Mean for Telephone Surveys","slug":"what-low-response-rates-mean-for-telephone-surveys","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/what-low-response-rates-mean-for-telephone-surveys\/","is_active":false,"page_num":1},{"id":101617,"title":"Acknowledgements","slug":"acknowledgements-8-3","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/acknowledgements-8-3\/","is_active":true,"page_num":2},{"id":101628,"title":"Methodology","slug":"methodology-6-8","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/methods\/2017\/05\/15\/methodology-6-8\/","is_active":false,"page_num":3}]},"parent_info":{"parent_title":"What Low Response Rates Mean for Telephone Surveys","parent_id":101634},"materialsOrdered":[],"chaptersOrdered":[],"partsOrdered":[],"partsEnabled":false,"datacite_doi":"","prc_seo_data":{"title":"Acknowledgements","description":"This report is a collaborative effort based on the input and analysis of the following individuals: Primary Researchers Scott Keeter, Senior Survey Advisor Nick Hatley, Research Assistant Courtney Kennedy, Director,&hellip;","og_title":"Acknowledgements","og_description":"","schema_type":"Article","noindex":false,"canonical_url":"","primary_terms":[],"custom_schema":[],"og_image":0,"indexnow_submitted_at":null,"gsc_index_status":null},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","relatedPostsOrdered":[],"bylinesOrdered":[],"acknowledgementsOrdered":[],"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/101617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=101617"}],"version-history":[{"count":2,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/101617\/revisions"}],"predecessor-version":[{"id":134368,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/101617\/revisions\/134368"}],"wp:attachment":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media?parent=101617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/categories?post=101617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/tags?post=101617"},{"taxonomy":"bylines","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/bylines?post=101617"},{"taxonomy":"datasets","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/datasets?post=101617"},{"taxonomy":"level_of_effort","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/level_of_effort?post=101617"},{"taxonomy":"primary_audience","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/primary_audience?post=101617"},{"taxonomy":"information_type","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/information_type?post=101617"},{"taxonomy":"_post_visibility","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/_post_visibility?post=101617"},{"taxonomy":"formats","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/formats?post=101617"},{"taxonomy":"_fund_pool","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/_fund_pool?post=101617"},{"taxonomy":"languages","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/languages?post=101617"},{"taxonomy":"regions-countries","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/regions-countries?post=101617"},{"taxonomy":"research-teams","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/research-teams?post=101617"},{"taxonomy":"workflow-status","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/workflow-status?post=101617"},{"taxonomy":"collection","embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/collection?post=101617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}