{"id":9920,"date":"2023-06-20T10:40:54","date_gmt":"2023-06-20T15:40:54","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png"},"modified":"2023-06-20T10:40:54","modified_gmt":"2023-06-20T15:40:54","slug":"sr_2023-06-21_border_1-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2023\/06\/21\/americans-remain-critical-of-governments-handling-of-situation-at-us-mexico-border\/sr_2023-06-21_border_1-png\/","title":{"rendered":"Just 23% of Americans say government is doing a good job at U.S.-Mexico border"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-9920","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png'><img loading=\"lazy\" decoding=\"async\" width=\"215\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=215\" class=\"attachment-medium size-medium not-transparent\" alt=\"A chart showing that just 23% of Americans say government is doing a good job at U.S.-Mexico border.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=215,300 215w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=291,405 291w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=200,279 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=260,362 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=310,432 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=420,585 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=160,223 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?resize=320,446 320w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" data-has-transparency=\"false\" data-dominant-color=\"e7e5df\" style=\"--dominant-color: #e7e5df;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A chart showing that just 23% of Americans say government is doing a good job at U.S.-Mexico border.","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":864,"file":"2023\/06\/sr_2023.06.21_border_1.png","filesize":187117,"sizes":{"thumbnail":{"file":"sr_2023.06.21_border_1.png?resize=150,150","width":150,"height":150,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=150&h=150&crop=1"},"medium":{"file":"sr_2023.06.21_border_1.png?resize=215,300","width":215,"height":300,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=215"},"A1":{"file":"sr_2023.06.21_border_1.png?resize=564,317","width":564,"height":317,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=620,634","width":620,"height":634,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"sr_2023.06.21_border_1.png?resize=620,388","width":620,"height":388,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=620,776","width":620,"height":776,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=776&crop=1"},"A2":{"file":"sr_2023.06.21_border_1.png?resize=268,151","width":268,"height":151,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=536,302","width":536,"height":302,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"sr_2023.06.21_border_1.png?resize=620,388","width":620,"height":388,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=620,776","width":620,"height":776,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=776&crop=1"},"A3":{"file":"sr_2023.06.21_border_1.png?resize=194,110","width":194,"height":110,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=388,220","width":388,"height":220,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"sr_2023.06.21_border_1.png?resize=148,84","width":148,"height":84,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=296,168","width":296,"height":168,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=296&h=168&crop=1"},"A4":{"file":"sr_2023.06.21_border_1.png?resize=268,151","width":268,"height":151,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=536,302","width":536,"height":302,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"sr_2023.06.21_border_1.png?resize=620,388","width":620,"height":388,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"sr_2023.06.21_border_1.png?resize=620,776","width":620,"height":776,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=776&crop=1"},"XL":{"file":"sr_2023.06.21_border_1.png?resize=620,405","width":620,"height":405,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"sr_2023.06.21_border_1.png?resize=620,810","width":620,"height":810,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=810&crop=1"},"social":{"file":"sr_2023.06.21_border_1.png?resize=620,628","width":620,"height":628,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=628&crop=1"},"chapter":{"file":"sr_2023.06.21_border_1.png?resize=291,405","width":291,"height":405,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=291"},"200-wide":{"file":"sr_2023.06.21_border_1.png?resize=200,279","width":200,"height":279,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=200"},"260-wide":{"file":"sr_2023.06.21_border_1.png?resize=260,362","width":260,"height":362,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=260"},"310-wide":{"file":"sr_2023.06.21_border_1.png?resize=310,432","width":310,"height":432,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=310"},"420-wide":{"file":"sr_2023.06.21_border_1.png?resize=420,585","width":420,"height":585,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=420"},"75-square":{"file":"sr_2023.06.21_border_1.png?resize=75,75","width":75,"height":75,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=75&h=75&crop=1"},"140-square":{"file":"sr_2023.06.21_border_1.png?resize=140,140","width":140,"height":140,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=140&h=140&crop=1"},"260-square":{"file":"sr_2023.06.21_border_1.png?resize=260,260","width":260,"height":260,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"sr_2023.06.21_border_1.png?resize=160,223","width":160,"height":223,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=160"},"320-portrait":{"file":"sr_2023.06.21_border_1.png?resize=320,446","width":320,"height":446,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=320"},"200-by-133":{"file":"sr_2023.06.21_border_1.png?resize=200,133","width":200,"height":133,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"sr_2023.06.21_border_1.png?resize=620,416","width":620,"height":416,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=620&h=416&crop=1"},"540-by-304":{"file":"sr_2023.06.21_border_1.png?resize=540,304","width":540,"height":304,"filesize":187117,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png?w=540&h=304&crop=1"},"full":{"file":"sr_2023.06.21_border_1.png","width":620,"height":864,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e7e5df","has_transparency":false},"post":8092,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/sr_2023.06.21_border_1.png","filename":"sr_2023.06.21_border_1.png","filesize":187117,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/9920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=9920"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":8092,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/8092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}