{"id":8898,"date":"2023-11-28T08:19:19","date_gmt":"2023-11-28T13:19:19","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png"},"modified":"2023-11-28T08:19:19","modified_gmt":"2023-11-28T13:19:19","slug":"sr_23-11-28_sotnm_3-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2023\/11\/28\/audiences-are-declining-for-traditional-news-media-in-the-us-with-some-exceptions\/sr_23-11-28_sotnm_3-png\/","title":{"rendered":"For U.S. newspapers, estimated circulation revenue now exceeds advertising revenue"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-8898","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_23.11.28_SOTNM_3.png","filesize":126407,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png'><img loading=\"lazy\" decoding=\"async\" width=\"264\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=264\" class=\"attachment-medium size-medium not-transparent\" alt=\"Line chart showing total advertising and circulation revenue of U.S. newspapers, in U.S. dollars, from 1956 through 2022. As of 2022, estimated circulation revenue exceeds advertising revenue, $11.6 billion to $9.8 billion.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=264,300 264w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=768,874 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=356,405 356w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=200,228 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=260,296 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=310,353 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=420,478 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=640,728 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=740,842 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=160,182 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?resize=320,364 320w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" data-has-transparency=\"false\" data-dominant-color=\"f4f3f2\" style=\"--dominant-color: #f4f3f2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Line chart showing total advertising and circulation revenue of U.S. newspapers, in U.S. dollars, from 1956 through 2022. As of 2022, estimated circulation revenue exceeds advertising revenue, $11.6 billion to $9.8 billion.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":956,"file":"2023\/11\/SR_23.11.28_SOTNM_3.png","filesize":126407,"sizes":{"thumbnail":{"file":"SR_23.11.28_SOTNM_3.png?resize=150,150","width":150,"height":150,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=150&h=150&crop=1"},"medium":{"file":"SR_23.11.28_SOTNM_3.png?resize=264,300","width":264,"height":300,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=264"},"medium_large":{"file":"SR_23.11.28_SOTNM_3.png?resize=768,874","width":768,"height":874,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=640"},"A1":{"file":"SR_23.11.28_SOTNM_3.png?resize=564,317","width":564,"height":317,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,634","width":840,"height":634,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_23.11.28_SOTNM_3.png?resize=690,388","width":690,"height":388,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,776","width":840,"height":776,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=776&crop=1"},"A2":{"file":"SR_23.11.28_SOTNM_3.png?resize=268,151","width":268,"height":151,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=536,302","width":536,"height":302,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_23.11.28_SOTNM_3.png?resize=690,388","width":690,"height":388,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,776","width":840,"height":776,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=776&crop=1"},"A3":{"file":"SR_23.11.28_SOTNM_3.png?resize=194,110","width":194,"height":110,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=388,220","width":388,"height":220,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_23.11.28_SOTNM_3.png?resize=148,84","width":148,"height":84,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=296,168","width":296,"height":168,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=296&h=168&crop=1"},"A4":{"file":"SR_23.11.28_SOTNM_3.png?resize=268,151","width":268,"height":151,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=536,302","width":536,"height":302,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_23.11.28_SOTNM_3.png?resize=690,388","width":690,"height":388,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,776","width":840,"height":776,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=776&crop=1"},"XL":{"file":"SR_23.11.28_SOTNM_3.png?resize=720,405","width":720,"height":405,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,810","width":840,"height":810,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=810&crop=1"},"social":{"file":"SR_23.11.28_SOTNM_3.png?resize=840,628","width":840,"height":628,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_23.11.28_SOTNM_3.png?resize=356,405","width":356,"height":405,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=356"},"200-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=200,228","width":200,"height":228,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=200"},"260-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=260,296","width":260,"height":296,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=260"},"310-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=310,353","width":310,"height":353,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=310"},"420-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=420,478","width":420,"height":478,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=420"},"640-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=640,728","width":640,"height":728,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=640"},"740-wide":{"file":"SR_23.11.28_SOTNM_3.png?resize=740,842","width":740,"height":842,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=740"},"75-square":{"file":"SR_23.11.28_SOTNM_3.png?resize=75,75","width":75,"height":75,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_23.11.28_SOTNM_3.png?resize=140,140","width":140,"height":140,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_23.11.28_SOTNM_3.png?resize=260,260","width":260,"height":260,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_23.11.28_SOTNM_3.png?resize=160,182","width":160,"height":182,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=160"},"320-portrait":{"file":"SR_23.11.28_SOTNM_3.png?resize=320,364","width":320,"height":364,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=320"},"200-by-133":{"file":"SR_23.11.28_SOTNM_3.png?resize=200,133","width":200,"height":133,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_23.11.28_SOTNM_3.png?resize=740,416","width":740,"height":416,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_23.11.28_SOTNM_3.png?resize=540,304","width":540,"height":304,"filesize":126407,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png?w=540&h=304&crop=1"},"full":{"file":"SR_23.11.28_SOTNM_3.png","width":840,"height":956,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f4f3f2","has_transparency":false},"post":7818,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.28_SOTNM_3.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"For U.S. newspapers, estimated circulation revenue now exceeds advertising revenue","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/8898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=8898"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7818,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}