{"id":85081,"date":"2015-10-29T16:23:51","date_gmt":"2015-10-29T21:23:51","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png"},"modified":"2015-10-29T16:23:51","modified_gmt":"2015-10-29T21:23:51","slug":"pf-2015-11-03_rls_ii-24-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2015\/11\/03\/chapter-1-importance-of-religion-and-religious-beliefs\/pf-2015-11-03_rls_ii-24-png\/","title":{"rendered":"Religion More Important to Women, Older Adults, Blacks, U.S. Adults With Less Education"},"author":139,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-85081","attachment","type-attachment","status-inherit","hentry"],"filename":"PF-2015-11-03_RLS_II-24.png","filesize":22259,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=300,250 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=486,405 486w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=200,167 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=260,217 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=310,258 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=420,350 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=160,133 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?resize=320,267 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"f0f0f0\" style=\"--dominant-color: #f0f0f0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":640,"height":533,"file":"2015\/11\/PF-2015-11-03_RLS_II-24.png","filesize":22259,"sizes":{"thumbnail":{"file":"PF-2015-11-03_RLS_II-24.png?resize=150,150","width":150,"height":150,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=150&h=150&crop=1"},"medium":{"file":"PF-2015-11-03_RLS_II-24.png?resize=300,250","width":300,"height":250,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=300"},"A1":{"file":"PF-2015-11-03_RLS_II-24.png?resize=564,317","width":564,"height":317,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"PF-2015-11-03_RLS_II-24.png?resize=640,388","width":640,"height":388,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=640&h=388&crop=1"},"A2":{"file":"PF-2015-11-03_RLS_II-24.png?resize=268,151","width":268,"height":151,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF-2015-11-03_RLS_II-24.png?resize=536,302","width":536,"height":302,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PF-2015-11-03_RLS_II-24.png?resize=640,388","width":640,"height":388,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=640&h=388&crop=1"},"A3":{"file":"PF-2015-11-03_RLS_II-24.png?resize=194,110","width":194,"height":110,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF-2015-11-03_RLS_II-24.png?resize=388,220","width":388,"height":220,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF-2015-11-03_RLS_II-24.png?resize=148,84","width":148,"height":84,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF-2015-11-03_RLS_II-24.png?resize=296,168","width":296,"height":168,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=296&h=168&crop=1"},"A4":{"file":"PF-2015-11-03_RLS_II-24.png?resize=268,151","width":268,"height":151,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF-2015-11-03_RLS_II-24.png?resize=536,302","width":536,"height":302,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PF-2015-11-03_RLS_II-24.png?resize=640,388","width":640,"height":388,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=640&h=388&crop=1"},"XL":{"file":"PF-2015-11-03_RLS_II-24.png?resize=640,405","width":640,"height":405,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=640&h=405&crop=1"},"chapter":{"file":"PF-2015-11-03_RLS_II-24.png?resize=486,405","width":486,"height":405,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=486"},"200-wide":{"file":"PF-2015-11-03_RLS_II-24.png?resize=200,167","width":200,"height":167,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=200"},"260-wide":{"file":"PF-2015-11-03_RLS_II-24.png?resize=260,217","width":260,"height":217,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=260"},"310-wide":{"file":"PF-2015-11-03_RLS_II-24.png?resize=310,258","width":310,"height":258,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=310"},"420-wide":{"file":"PF-2015-11-03_RLS_II-24.png?resize=420,350","width":420,"height":350,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=420"},"75-square":{"file":"PF-2015-11-03_RLS_II-24.png?resize=75,75","width":75,"height":75,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=75&h=75&crop=1"},"140-square":{"file":"PF-2015-11-03_RLS_II-24.png?resize=140,140","width":140,"height":140,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=140&h=140&crop=1"},"260-square":{"file":"PF-2015-11-03_RLS_II-24.png?resize=260,260","width":260,"height":260,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF-2015-11-03_RLS_II-24.png?resize=160,133","width":160,"height":133,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=160"},"320-portrait":{"file":"PF-2015-11-03_RLS_II-24.png?resize=320,267","width":320,"height":267,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=320"},"200-by-133":{"file":"PF-2015-11-03_RLS_II-24.png?resize=200,133","width":200,"height":133,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF-2015-11-03_RLS_II-24.png?resize=640,416","width":640,"height":416,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=640&h=416&crop=1"},"540-by-304":{"file":"PF-2015-11-03_RLS_II-24.png?resize=540,304","width":540,"height":304,"filesize":22259,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png?w=540&h=304&crop=1"},"full":{"file":"PF-2015-11-03_RLS_II-24.png","width":640,"height":533,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f0f0f0","has_transparency":false},"post":72151,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2015\/11\/PF-2015-11-03_RLS_II-24.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Religion More Important to Women, Older Adults, Blacks, U.S. Adults With Less Education","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/85081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=85081"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":72151,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/72151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}