{"id":82846,"date":"2019-12-10T14:12:32","date_gmt":"2019-12-10T19:12:32","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png"},"modified":"2019-12-10T14:12:32","modified_gmt":"2019-12-10T19:12:32","slug":"pf_12-12-19_religion-households-01-03-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2019\/12\/12\/household-patterns-by-region\/pf_12-12-19_religion-households-01-03-png\/","title":{"rendered":"North American Christians, \u2018nones\u2019 and Jews have similar sized households"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-82846","attachment","type-attachment","status-inherit","hentry"],"filename":"PF_12.12.19_religion.households-01-03.png","filesize":67032,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"171\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=171\" class=\"attachment-medium size-medium not-transparent\" alt=\"North American Christians, \u2018nones\u2019 and Jews have similar sized households\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png 404w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=171,300 171w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=230,405 230w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=200,351 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=260,457 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=310,545 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=160,281 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?resize=320,562 320w\" sizes=\"auto, (max-width: 171px) 100vw, 171px\" data-has-transparency=\"false\" data-dominant-color=\"e9e9e9\" style=\"--dominant-color: #e9e9e9;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"North American Christians, \u2018nones\u2019 and Jews have similar sized households","media_type":"image","mime_type":"image\/png","media_details":{"width":404,"height":710,"file":"2019\/12\/PF_12.12.19_religion.households-01-03.png","filesize":67032,"sizes":{"thumbnail":{"file":"PF_12.12.19_religion.households-01-03.png?resize=150,150","width":150,"height":150,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=150&h=150&crop=1"},"medium":{"file":"PF_12.12.19_religion.households-01-03.png?resize=171,300","width":171,"height":300,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=171"},"A1":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,317","width":404,"height":317,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=317&crop=1"},"A1-HIDPI":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,634","width":404,"height":634,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=634&crop=1"},"A1-SMALL":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,388","width":404,"height":388,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=388&crop=1"},"A2":{"file":"PF_12.12.19_religion.households-01-03.png?resize=268,151","width":268,"height":151,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,302","width":404,"height":302,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=302&crop=1"},"A2-SMALL":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,388","width":404,"height":388,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=388&crop=1"},"A3":{"file":"PF_12.12.19_religion.households-01-03.png?resize=194,110","width":194,"height":110,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_12.12.19_religion.households-01-03.png?resize=388,220","width":388,"height":220,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_12.12.19_religion.households-01-03.png?resize=148,84","width":148,"height":84,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_12.12.19_religion.households-01-03.png?resize=296,168","width":296,"height":168,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=296&h=168&crop=1"},"A4":{"file":"PF_12.12.19_religion.households-01-03.png?resize=268,151","width":268,"height":151,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,302","width":404,"height":302,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=302&crop=1"},"A4-SMALL":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,388","width":404,"height":388,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=388&crop=1"},"XL":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,405","width":404,"height":405,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=405&crop=1"},"social":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,628","width":404,"height":628,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=628&crop=1"},"chapter":{"file":"PF_12.12.19_religion.households-01-03.png?resize=230,405","width":230,"height":405,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=230"},"200-wide":{"file":"PF_12.12.19_religion.households-01-03.png?resize=200,351","width":200,"height":351,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=200"},"260-wide":{"file":"PF_12.12.19_religion.households-01-03.png?resize=260,457","width":260,"height":457,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=260"},"310-wide":{"file":"PF_12.12.19_religion.households-01-03.png?resize=310,545","width":310,"height":545,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=310"},"75-square":{"file":"PF_12.12.19_religion.households-01-03.png?resize=75,75","width":75,"height":75,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_12.12.19_religion.households-01-03.png?resize=140,140","width":140,"height":140,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_12.12.19_religion.households-01-03.png?resize=260,260","width":260,"height":260,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_12.12.19_religion.households-01-03.png?resize=160,281","width":160,"height":281,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=160"},"320-portrait":{"file":"PF_12.12.19_religion.households-01-03.png?resize=320,562","width":320,"height":562,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=320"},"200-by-133":{"file":"PF_12.12.19_religion.households-01-03.png?resize=200,133","width":200,"height":133,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,416","width":404,"height":416,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=416&crop=1"},"540-by-304":{"file":"PF_12.12.19_religion.households-01-03.png?resize=404,304","width":404,"height":304,"filesize":67032,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png?w=404&h=304&crop=1"},"full":{"file":"PF_12.12.19_religion.households-01-03.png","width":404,"height":710,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e9e9e9","has_transparency":false},"post":71223,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/12\/PF_12.12.19_religion.households-01-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"North American Christians, \u2018nones\u2019 and Jews have similar sized households","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/82846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=82846"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71223,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}