{"id":82448,"date":"2021-06-22T15:46:32","date_gmt":"2021-06-22T20:46:32","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png"},"modified":"2021-06-22T15:46:32","modified_gmt":"2021-06-22T20:46:32","slug":"pf_06-29-21_india-07-8-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2021\/06\/29\/religious-practices-2\/pf_06-29-21_india-07-8-png\/","title":{"rendered":"Muslims in India least likely to have made a religious pilgrimage"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-82448","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png'><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=95\" class=\"attachment-medium size-medium not-transparent\" alt=\"Muslims in India least likely to have made a religious pilgrimage\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png 408w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=95,300 95w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=323,1024 323w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=128,405 128w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=200,633 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=260,823 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=310,982 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=101,320 101w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?resize=202,640 202w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" data-has-transparency=\"false\" data-dominant-color=\"ededed\" style=\"--dominant-color: #ededed;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Muslims in India least likely to have made a religious pilgrimage","media_type":"image","mime_type":"image\/png","media_details":{"width":408,"height":1292,"file":"2021\/06\/PF_06.29.21_India-07-8.png","filesize":146805,"sizes":{"thumbnail":{"file":"PF_06.29.21_India-07-8.png?resize=150,150","width":150,"height":150,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=150&h=150&crop=1"},"medium":{"file":"PF_06.29.21_India-07-8.png?resize=95,300","width":95,"height":300,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=95"},"large":{"file":"PF_06.29.21_India-07-8.png?resize=323,1024","width":323,"height":1024,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=323"},"A1":{"file":"PF_06.29.21_India-07-8.png?resize=408,317","width":408,"height":317,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=317&crop=1"},"A1-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,634","width":408,"height":634,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=634&crop=1"},"A1-SMALL":{"file":"PF_06.29.21_India-07-8.png?resize=408,388","width":408,"height":388,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,776","width":408,"height":776,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=776&crop=1"},"A2":{"file":"PF_06.29.21_India-07-8.png?resize=268,151","width":268,"height":151,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,302","width":408,"height":302,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=302&crop=1"},"A2-SMALL":{"file":"PF_06.29.21_India-07-8.png?resize=408,388","width":408,"height":388,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,776","width":408,"height":776,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=776&crop=1"},"A3":{"file":"PF_06.29.21_India-07-8.png?resize=194,110","width":194,"height":110,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=388,220","width":388,"height":220,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_06.29.21_India-07-8.png?resize=148,84","width":148,"height":84,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=296,168","width":296,"height":168,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=296&h=168&crop=1"},"A4":{"file":"PF_06.29.21_India-07-8.png?resize=268,151","width":268,"height":151,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,302","width":408,"height":302,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=302&crop=1"},"A4-SMALL":{"file":"PF_06.29.21_India-07-8.png?resize=408,388","width":408,"height":388,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,776","width":408,"height":776,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=776&crop=1"},"XL":{"file":"PF_06.29.21_India-07-8.png?resize=408,405","width":408,"height":405,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=405&crop=1"},"XL-HIDPI":{"file":"PF_06.29.21_India-07-8.png?resize=408,810","width":408,"height":810,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=810&crop=1"},"social":{"file":"PF_06.29.21_India-07-8.png?resize=408,628","width":408,"height":628,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=628&crop=1"},"chapter":{"file":"PF_06.29.21_India-07-8.png?resize=128,405","width":128,"height":405,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=128"},"200-wide":{"file":"PF_06.29.21_India-07-8.png?resize=200,633","width":200,"height":633,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=200"},"260-wide":{"file":"PF_06.29.21_India-07-8.png?resize=260,823","width":260,"height":823,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=260"},"310-wide":{"file":"PF_06.29.21_India-07-8.png?resize=310,982","width":310,"height":982,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=310"},"75-square":{"file":"PF_06.29.21_India-07-8.png?resize=75,75","width":75,"height":75,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_06.29.21_India-07-8.png?resize=140,140","width":140,"height":140,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_06.29.21_India-07-8.png?resize=260,260","width":260,"height":260,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_06.29.21_India-07-8.png?resize=101,320","width":101,"height":320,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=101"},"320-portrait":{"file":"PF_06.29.21_India-07-8.png?resize=202,640","width":202,"height":640,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=202"},"200-by-133":{"file":"PF_06.29.21_India-07-8.png?resize=200,133","width":200,"height":133,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_06.29.21_India-07-8.png?resize=408,416","width":408,"height":416,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=416&crop=1"},"540-by-304":{"file":"PF_06.29.21_India-07-8.png?resize=408,304","width":408,"height":304,"filesize":146805,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png?w=408&h=304&crop=1"},"full":{"file":"PF_06.29.21_India-07-8.png","width":408,"height":1292,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ededed","has_transparency":false},"post":71104,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-07-8.png","filename":"PF_06.29.21_India-07-8.png","filesize":146805,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/82448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=82448"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71104,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}