{"id":82358,"date":"2020-09-04T11:15:29","date_gmt":"2020-09-04T16:15:29","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png"},"modified":"2020-09-04T11:15:29","modified_gmt":"2020-09-04T16:15:29","slug":"pf_09-10-20_religion-teens-02-9-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2020\/09\/10\/religious-beliefs-among-american-adolescents\/pf_09-10-20_religion-teens-02-9-png\/","title":{"rendered":"Plurality of teens, parents say there may be truth in many religions"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-82358","attachment","type-attachment","status-inherit","hentry"],"filename":"PF_09.10.20_religion.teens-02-9.png","filesize":147515,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png'><img loading=\"lazy\" decoding=\"async\" width=\"258\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=258\" class=\"attachment-medium size-medium not-transparent\" alt=\"Plurality of teens, parents say there may be truth in many religions\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png 618w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=258,300 258w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=348,405 348w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=200,233 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=260,303 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=310,361 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=420,489 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=160,186 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?resize=320,373 320w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" data-has-transparency=\"false\" data-dominant-color=\"ececec\" style=\"--dominant-color: #ececec;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Plurality of teens, parents say there may be truth in many religions","media_type":"image","mime_type":"image\/png","media_details":{"width":618,"height":720,"file":"2020\/09\/PF_09.10.20_religion.teens-02-9.png","filesize":147515,"sizes":{"thumbnail":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=150,150","width":150,"height":150,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=150&h=150&crop=1"},"medium":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=258,300","width":258,"height":300,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=258"},"A1":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=564,317","width":564,"height":317,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,634","width":618,"height":634,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=634&crop=1"},"A1-SMALL":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,388","width":618,"height":388,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=388&crop=1"},"A2":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=268,151","width":268,"height":151,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=536,302","width":536,"height":302,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,388","width":618,"height":388,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=388&crop=1"},"A3":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=194,110","width":194,"height":110,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=388,220","width":388,"height":220,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=148,84","width":148,"height":84,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=296,168","width":296,"height":168,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=296&h=168&crop=1"},"A4":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=268,151","width":268,"height":151,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=536,302","width":536,"height":302,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,388","width":618,"height":388,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=388&crop=1"},"XL":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,405","width":618,"height":405,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=405&crop=1"},"social":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,628","width":618,"height":628,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=628&crop=1"},"chapter":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=348,405","width":348,"height":405,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=348"},"200-wide":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=200,233","width":200,"height":233,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=200"},"260-wide":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=260,303","width":260,"height":303,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=260"},"310-wide":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=310,361","width":310,"height":361,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=310"},"420-wide":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=420,489","width":420,"height":489,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=420"},"75-square":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=75,75","width":75,"height":75,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=140,140","width":140,"height":140,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=260,260","width":260,"height":260,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=160,186","width":160,"height":186,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=160"},"320-portrait":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=320,373","width":320,"height":373,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=320"},"200-by-133":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=200,133","width":200,"height":133,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=618,416","width":618,"height":416,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=618&h=416&crop=1"},"540-by-304":{"file":"PF_09.10.20_religion.teens-02-9.png?resize=540,304","width":540,"height":304,"filesize":147515,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png?w=540&h=304&crop=1"},"full":{"file":"PF_09.10.20_religion.teens-02-9.png","width":618,"height":720,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ececec","has_transparency":false},"post":71095,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PF_09.10.20_religion.teens-02-9.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Plurality of teens, parents say there may be truth in many religions","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/82358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=82358"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71095,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}