{"id":82267,"date":"2021-06-22T10:58:23","date_gmt":"2021-06-22T15:58:23","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png"},"modified":"2021-06-22T10:58:23","modified_gmt":"2021-06-22T15:58:23","slug":"pf_06-29-21_india-02-3-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2021\/06\/29\/diversity-and-pluralism\/pf_06-29-21_india-02-3-png\/","title":{"rendered":"More Sikhs than members of other religious groups see common ground among religious groups in India"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-82267","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png'><img loading=\"lazy\" decoding=\"async\" width=\"124\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=124\" class=\"attachment-medium size-medium not-transparent\" alt=\"More Sikhs than members of other religious groups see common ground among religious groups in India\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=124,300 124w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=423,1024 423w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=167,405 167w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=200,485 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=260,630 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=310,751 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=420,1017 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=132,320 132w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?resize=264,640 264w\" sizes=\"auto, (max-width: 124px) 100vw, 124px\" data-has-transparency=\"false\" data-dominant-color=\"ebebeb\" style=\"--dominant-color: #ebebeb;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"More Sikhs than members of other religious groups see common ground among religious groups in India","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":1502,"file":"2021\/06\/PF_06.29.21_India-02-3.png","filesize":278630,"sizes":{"thumbnail":{"file":"PF_06.29.21_India-02-3.png?resize=150,150","width":150,"height":150,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=150&h=150&crop=1"},"medium":{"file":"PF_06.29.21_India-02-3.png?resize=124,300","width":124,"height":300,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=124"},"large":{"file":"PF_06.29.21_India-02-3.png?resize=423,1024","width":423,"height":1024,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=423"},"A1":{"file":"PF_06.29.21_India-02-3.png?resize=564,317","width":564,"height":317,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=620,634","width":620,"height":634,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PF_06.29.21_India-02-3.png?resize=620,388","width":620,"height":388,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=620,776","width":620,"height":776,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=776&crop=1"},"A2":{"file":"PF_06.29.21_India-02-3.png?resize=268,151","width":268,"height":151,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=536,302","width":536,"height":302,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PF_06.29.21_India-02-3.png?resize=620,388","width":620,"height":388,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=620,776","width":620,"height":776,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=776&crop=1"},"A3":{"file":"PF_06.29.21_India-02-3.png?resize=194,110","width":194,"height":110,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=388,220","width":388,"height":220,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_06.29.21_India-02-3.png?resize=148,84","width":148,"height":84,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=296,168","width":296,"height":168,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=296&h=168&crop=1"},"A4":{"file":"PF_06.29.21_India-02-3.png?resize=268,151","width":268,"height":151,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=536,302","width":536,"height":302,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PF_06.29.21_India-02-3.png?resize=620,388","width":620,"height":388,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=620,776","width":620,"height":776,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=776&crop=1"},"XL":{"file":"PF_06.29.21_India-02-3.png?resize=620,405","width":620,"height":405,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"PF_06.29.21_India-02-3.png?resize=620,810","width":620,"height":810,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=810&crop=1"},"social":{"file":"PF_06.29.21_India-02-3.png?resize=620,628","width":620,"height":628,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=628&crop=1"},"chapter":{"file":"PF_06.29.21_India-02-3.png?resize=167,405","width":167,"height":405,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=167"},"200-wide":{"file":"PF_06.29.21_India-02-3.png?resize=200,485","width":200,"height":485,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=200"},"260-wide":{"file":"PF_06.29.21_India-02-3.png?resize=260,630","width":260,"height":630,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=260"},"310-wide":{"file":"PF_06.29.21_India-02-3.png?resize=310,751","width":310,"height":751,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=310"},"420-wide":{"file":"PF_06.29.21_India-02-3.png?resize=420,1017","width":420,"height":1017,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=420"},"75-square":{"file":"PF_06.29.21_India-02-3.png?resize=75,75","width":75,"height":75,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_06.29.21_India-02-3.png?resize=140,140","width":140,"height":140,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_06.29.21_India-02-3.png?resize=260,260","width":260,"height":260,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_06.29.21_India-02-3.png?resize=132,320","width":132,"height":320,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=132"},"320-portrait":{"file":"PF_06.29.21_India-02-3.png?resize=264,640","width":264,"height":640,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=264"},"200-by-133":{"file":"PF_06.29.21_India-02-3.png?resize=200,133","width":200,"height":133,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_06.29.21_India-02-3.png?resize=620,416","width":620,"height":416,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PF_06.29.21_India-02-3.png?resize=540,304","width":540,"height":304,"filesize":278630,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png?w=540&h=304&crop=1"},"full":{"file":"PF_06.29.21_India-02-3.png","width":620,"height":1502,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ebebeb","has_transparency":false},"post":71016,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/06\/PF_06.29.21_India-02-3.png","filename":"PF_06.29.21_India-02-3.png","filesize":278630,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/82267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=82267"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71016,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}