{"id":82248,"date":"2021-07-02T09:40:45","date_gmt":"2021-07-02T14:40:45","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png"},"modified":"2021-07-02T09:40:45","modified_gmt":"2021-07-02T14:40:45","slug":"pdl_07-08-21_sermons-0-2-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/pastors-often-discussed-election-pandemic-and-racism-in-fall-of-2020\/pdl_07-08-21_sermons-0-2-png\/","title":{"rendered":"Sermons mentioning the pandemic often did so multiple times"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-82248","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":70988,"title":"Pastors Often Discussed Election, Pandemic and Racism in Fall of 2020","slug":"pastors-often-discussed-election-pandemic-and-racism-in-fall-of-2020","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/pastors-often-discussed-election-pandemic-and-racism-in-fall-of-2020\/","is_active":false},{"id":70972,"title":"Acknowledgments","slug":"acknowledgments-55-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/acknowledgments-55-2\/","is_active":false},{"id":70957,"title":"Appendix A: Congregations that share sermons online are disproportionately evangelical and have larger audiences; sermons are longer than in 2019 study","slug":"appendix-a-congregations-that-share-sermons-online-are-disproportionately-evangelical-and-have-larger-audiences-sermons-are-longer-than-in-2019-study","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/appendix-a-congregations-that-share-sermons-online-are-disproportionately-evangelical-and-have-larger-audiences-sermons-are-longer-than-in-2019-study\/","is_active":false},{"id":70939,"title":"Appendix B: Words or phrases most disproportionately used by clergy of each group","slug":"appendix-b-words-or-phrases-most-disproportionately-used-by-clergy-of-each-group","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/appendix-b-words-or-phrases-most-disproportionately-used-by-clergy-of-each-group\/","is_active":false},{"id":70949,"title":"Methodology","slug":"methodology-40-4","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/07\/08\/methodology-40-4\/","is_active":false}],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"156\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Sermons mentioning the pandemic often did so multiple times\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png 1278w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=300,156 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=768,400 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=1024,534 1024w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=1200,628 1200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=777,405 777w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=200,104 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=260,135 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=310,162 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=420,219 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=640,334 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=740,386 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=160,83 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?resize=320,167 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"f3f3f3\" style=\"--dominant-color: #f3f3f3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Sermons mentioning the pandemic often did so multiple times","media_type":"image","mime_type":"image\/png","media_details":{"width":1278,"height":666,"file":"2021\/07\/PDL_07.08.21_sermons-0-2.png","filesize":262470,"sizes":{"thumbnail":{"file":"PDL_07.08.21_sermons-0-2.png?resize=150,150","width":150,"height":150,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=150&h=150&crop=1"},"medium":{"file":"PDL_07.08.21_sermons-0-2.png?resize=300,156","width":300,"height":156,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=300"},"medium_large":{"file":"PDL_07.08.21_sermons-0-2.png?resize=768,400","width":768,"height":400,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=640"},"large":{"file":"PDL_07.08.21_sermons-0-2.png?resize=1024,534","width":1024,"height":534,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=640"},"A1":{"file":"PDL_07.08.21_sermons-0-2.png?resize=564,317","width":564,"height":317,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PDL_07.08.21_sermons-0-2.png?resize=1128,634","width":1128,"height":634,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"PDL_07.08.21_sermons-0-2.png?resize=690,388","width":690,"height":388,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=690&h=388&crop=1"},"A2":{"file":"PDL_07.08.21_sermons-0-2.png?resize=268,151","width":268,"height":151,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PDL_07.08.21_sermons-0-2.png?resize=536,302","width":536,"height":302,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PDL_07.08.21_sermons-0-2.png?resize=690,388","width":690,"height":388,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=690&h=388&crop=1"},"A3":{"file":"PDL_07.08.21_sermons-0-2.png?resize=194,110","width":194,"height":110,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PDL_07.08.21_sermons-0-2.png?resize=388,220","width":388,"height":220,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PDL_07.08.21_sermons-0-2.png?resize=148,84","width":148,"height":84,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PDL_07.08.21_sermons-0-2.png?resize=296,168","width":296,"height":168,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=296&h=168&crop=1"},"A4":{"file":"PDL_07.08.21_sermons-0-2.png?resize=268,151","width":268,"height":151,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PDL_07.08.21_sermons-0-2.png?resize=536,302","width":536,"height":302,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PDL_07.08.21_sermons-0-2.png?resize=690,388","width":690,"height":388,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=690&h=388&crop=1"},"XL":{"file":"PDL_07.08.21_sermons-0-2.png?resize=720,405","width":720,"height":405,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=720&h=405&crop=1"},"social":{"file":"PDL_07.08.21_sermons-0-2.png?resize=1200,628","width":1200,"height":628,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=1200&h=628&crop=1"},"chapter":{"file":"PDL_07.08.21_sermons-0-2.png?resize=777,405","width":777,"height":405,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=777"},"200-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=200,104","width":200,"height":104,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=200"},"260-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=260,135","width":260,"height":135,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=260"},"310-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=310,162","width":310,"height":162,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=310"},"420-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=420,219","width":420,"height":219,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=420"},"640-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=640,334","width":640,"height":334,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=640"},"740-wide":{"file":"PDL_07.08.21_sermons-0-2.png?resize=740,386","width":740,"height":386,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=740"},"75-square":{"file":"PDL_07.08.21_sermons-0-2.png?resize=75,75","width":75,"height":75,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=75&h=75&crop=1"},"140-square":{"file":"PDL_07.08.21_sermons-0-2.png?resize=140,140","width":140,"height":140,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=140&h=140&crop=1"},"260-square":{"file":"PDL_07.08.21_sermons-0-2.png?resize=260,260","width":260,"height":260,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PDL_07.08.21_sermons-0-2.png?resize=160,83","width":160,"height":83,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=160"},"320-portrait":{"file":"PDL_07.08.21_sermons-0-2.png?resize=320,167","width":320,"height":167,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=320"},"200-by-133":{"file":"PDL_07.08.21_sermons-0-2.png?resize=200,133","width":200,"height":133,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PDL_07.08.21_sermons-0-2.png?resize=740,416","width":740,"height":416,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PDL_07.08.21_sermons-0-2.png?resize=540,304","width":540,"height":304,"filesize":262470,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png?w=540&h=304&crop=1"},"full":{"file":"PDL_07.08.21_sermons-0-2.png","width":1278,"height":666,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f3f3f3","has_transparency":false},"post":70988,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/07\/PDL_07.08.21_sermons-0-2.png","filename":"PDL_07.08.21_sermons-0-2.png","filesize":262470,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/82248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=82248"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":70988,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/70988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}