{"id":80861,"date":"2023-09-07T11:47:08","date_gmt":"2023-09-07T16:47:08","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png"},"modified":"2023-09-07T11:47:08","modified_gmt":"2023-09-07T16:47:08","slug":"pr_2023-09-12_se-asia_7_09-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2023\/09\/12\/religion-and-politics-2\/pr_2023-09-12_se-asia_7_09-png\/","title":{"rendered":"Most Thai, Cambodian adults favor legal same-sex marriage"},"author":648,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-80861","attachment","type-attachment","status-inherit","hentry"],"filename":"pr_2023.09.12_se-asia_7_09.png","filesize":219728,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"133\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A table showing that Most Thai and Cambodian adults favor legal same-sex marriage\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=300,133 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=768,341 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=1024,454 1024w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=913,405 913w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=200,89 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=260,115 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=310,138 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=420,186 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=640,284 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=740,328 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=160,71 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?resize=320,142 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"ededed\" style=\"--dominant-color: #ededed;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A table showing that Most Thai and Cambodian adults favor legal same-sex marriage","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":568,"file":"2023\/09\/pr_2023.09.12_se-asia_7_09.png","filesize":219728,"sizes":{"thumbnail":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=150,150","width":150,"height":150,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=150&h=150&crop=1"},"medium":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=300,133","width":300,"height":133,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=300"},"medium_large":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=768,341","width":768,"height":341,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=640"},"large":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=1024,454","width":1024,"height":454,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=640"},"A1":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=564,317","width":564,"height":317,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=1128,568","width":1128,"height":568,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=1128&h=568&crop=1"},"A1-SMALL":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=690,388","width":690,"height":388,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=690&h=388&crop=1"},"A2":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=268,151","width":268,"height":151,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=536,302","width":536,"height":302,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=690,388","width":690,"height":388,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=690&h=388&crop=1"},"A3":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=194,110","width":194,"height":110,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=388,220","width":388,"height":220,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=148,84","width":148,"height":84,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=296,168","width":296,"height":168,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=296&h=168&crop=1"},"A4":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=268,151","width":268,"height":151,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=536,302","width":536,"height":302,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=690,388","width":690,"height":388,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=690&h=388&crop=1"},"XL":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=720,405","width":720,"height":405,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=720&h=405&crop=1"},"social":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=1200,568","width":1200,"height":568,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=1200&h=568&crop=1"},"chapter":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=913,405","width":913,"height":405,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=913"},"200-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=200,89","width":200,"height":89,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=200"},"260-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=260,115","width":260,"height":115,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=260"},"310-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=310,138","width":310,"height":138,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=310"},"420-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=420,186","width":420,"height":186,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=420"},"640-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=640,284","width":640,"height":284,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=640"},"740-wide":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=740,328","width":740,"height":328,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=740"},"75-square":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=75,75","width":75,"height":75,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=75&h=75&crop=1"},"140-square":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=140,140","width":140,"height":140,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=140&h=140&crop=1"},"260-square":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=260,260","width":260,"height":260,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=260&h=260&crop=1"},"160-portrait":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=160,71","width":160,"height":71,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=160"},"320-portrait":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=320,142","width":320,"height":142,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=320"},"200-by-133":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=200,133","width":200,"height":133,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=200&h=133&crop=1"},"740-by-416":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=740,416","width":740,"height":416,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=740&h=416&crop=1"},"540-by-304":{"file":"pr_2023.09.12_se-asia_7_09.png?resize=540,304","width":540,"height":304,"filesize":219728,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png?w=540&h=304&crop=1"},"full":{"file":"pr_2023.09.12_se-asia_7_09.png","width":1200,"height":533,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ededed","has_transparency":false},"post":69717,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/pr_2023.09.12_se-asia_7_09.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Most Thai, Cambodian adults favor legal same-sex marriage","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/80861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=80861"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":69717,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/69717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}