{"id":80762,"date":"2023-12-05T11:15:20","date_gmt":"2023-12-05T16:15:20","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png"},"modified":"2023-12-05T11:15:20","modified_gmt":"2023-12-05T16:15:20","slug":"pr_2023-12-07_spirituality_4-04-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2023\/12\/07\/spiritual-experiences\/pr_2023-12-07_spirituality_4-04-png\/","title":{"rendered":"30% of U.S. adults say they have encountered a spirit or unseen spiritual force"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-80762","attachment","type-attachment","status-inherit","hentry"],"filename":"PR_2023.12.07_spirituality_4-04.png","filesize":170097,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png'><img loading=\"lazy\" decoding=\"async\" width=\"266\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=266\" class=\"attachment-medium size-medium not-transparent\" alt=\"Table shows 30% of U.S. adults say they have encountered a spirit or unseen spiritual force\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=266,300 266w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=768,866 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=908,1024 908w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=359,405 359w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=200,226 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=260,293 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=310,350 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=420,474 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=640,722 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=740,835 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=160,181 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?resize=320,361 320w\" sizes=\"auto, (max-width: 266px) 100vw, 266px\" data-has-transparency=\"false\" data-dominant-color=\"f6f6f6\" style=\"--dominant-color: #f6f6f6;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Table shows 30% of U.S. adults say they have encountered a spirit or unseen spiritual force","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":1444,"file":"2023\/12\/PR_2023.12.07_spirituality_4-04.png","filesize":170097,"sizes":{"thumbnail":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=150,150","width":150,"height":150,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=150&h=150&crop=1"},"medium":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=266,300","width":266,"height":300,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=266"},"medium_large":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=768,866","width":768,"height":866,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=640"},"large":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=908,1024","width":908,"height":1024,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=640"},"A1":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=564,317","width":564,"height":317,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1128,634","width":1128,"height":634,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=690,388","width":690,"height":388,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1280,776","width":1280,"height":776,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1280&h=776&crop=1"},"A2":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=268,151","width":268,"height":151,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=536,302","width":536,"height":302,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=690,388","width":690,"height":388,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1280,776","width":1280,"height":776,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1280&h=776&crop=1"},"A3":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=194,110","width":194,"height":110,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=388,220","width":388,"height":220,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=148,84","width":148,"height":84,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=296,168","width":296,"height":168,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=296&h=168&crop=1"},"A4":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=268,151","width":268,"height":151,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=536,302","width":536,"height":302,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=690,388","width":690,"height":388,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1280,776","width":1280,"height":776,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1280&h=776&crop=1"},"XL":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=720,405","width":720,"height":405,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1280,810","width":1280,"height":810,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1280&h=810&crop=1"},"social":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=1200,628","width":1200,"height":628,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=1200&h=628&crop=1"},"chapter":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=359,405","width":359,"height":405,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=359"},"200-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=200,226","width":200,"height":226,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=200"},"260-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=260,293","width":260,"height":293,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=260"},"310-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=310,350","width":310,"height":350,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=310"},"420-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=420,474","width":420,"height":474,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=420"},"640-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=640,722","width":640,"height":722,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=640"},"740-wide":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=740,835","width":740,"height":835,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=740"},"75-square":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=75,75","width":75,"height":75,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=75&h=75&crop=1"},"140-square":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=140,140","width":140,"height":140,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=140&h=140&crop=1"},"260-square":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=260,260","width":260,"height":260,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=160,181","width":160,"height":181,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=160"},"320-portrait":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=320,361","width":320,"height":361,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=320"},"200-by-133":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=200,133","width":200,"height":133,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=740,416","width":740,"height":416,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PR_2023.12.07_spirituality_4-04.png?resize=540,304","width":540,"height":304,"filesize":170097,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png?w=540&h=304&crop=1"},"full":{"file":"PR_2023.12.07_spirituality_4-04.png","width":1200,"height":1354,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f6f6f6","has_transparency":false},"post":69584,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-04.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"30% of U.S. adults say they have encountered a spirit or unseen spiritual force","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/80762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=80762"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":69584,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/69584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}