{"id":70690,"date":"2012-09-20T12:14:56","date_gmt":"2012-09-20T17:14:56","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png"},"modified":"2012-09-20T12:14:56","modified_gmt":"2012-09-20T17:14:56","slug":"pp_12-09-19_horseracesept-slideshow_02_europe1-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2012\/09\/21\/slideshow-obama-ahead-of-romney-on-most-issues\/pp_12-09-19_horseracesept-slideshow_02_europe1-png\/","title":{"rendered":"Obama Ahead by 8 Points Among Likely Voters"},"author":130,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-70690","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png","filesize":19060,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"215\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png 560w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=300,215 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=200,143 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=260,186 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=310,222 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=420,301 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=160,115 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=320,229 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"e4ddde\" style=\"--dominant-color: #e4ddde;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":560,"height":401,"file":"2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png","filesize":19060,"sizes":{"thumbnail":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=150,150","width":150,"height":150,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=150&h=150&crop=1"},"medium":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=300,215","width":300,"height":215,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=300"},"A1":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=560,317","width":560,"height":317,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=560&h=317&crop=1"},"A1-SMALL":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=560,388","width":560,"height":388,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=560&h=388&crop=1"},"A2":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=268,151","width":268,"height":151,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=536,302","width":536,"height":302,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=560,388","width":560,"height":388,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=560&h=388&crop=1"},"A3":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=194,110","width":194,"height":110,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=388,220","width":388,"height":220,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=148,84","width":148,"height":84,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=296,168","width":296,"height":168,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=296&h=168&crop=1"},"A4":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=268,151","width":268,"height":151,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=536,302","width":536,"height":302,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=560,388","width":560,"height":388,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=560&h=388&crop=1"},"200-wide":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=200,143","width":200,"height":143,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=200"},"260-wide":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=260,186","width":260,"height":186,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=260"},"310-wide":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=310,222","width":310,"height":222,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=310"},"420-wide":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=420,301","width":420,"height":301,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=420"},"75-square":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=75,75","width":75,"height":75,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=140,140","width":140,"height":140,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=260,260","width":260,"height":260,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=160,115","width":160,"height":115,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=160"},"320-portrait":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=320,229","width":320,"height":229,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=320"},"200-by-133":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=200,133","width":200,"height":133,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=200&h=133&crop=1"},"540-by-304":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png?resize=540,304","width":540,"height":304,"filesize":19060,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png?w=540&h=304&crop=1"},"full":{"file":"PP_12.09.19_horseraceSept-slideshow_02_europe1.png","width":560,"height":401,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e4ddde","has_transparency":false},"post":56479,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2012\/09\/PP_12.09.19_horseraceSept-slideshow_02_europe1.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Obama Ahead by 8 Points Among Likely Voters","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/70690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=70690"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":56479,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/56479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}