{"id":60995,"date":"2019-01-22T11:56:37","date_gmt":"2019-01-22T16:56:37","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png"},"modified":"2019-01-22T11:56:37","modified_gmt":"2019-01-22T16:56:37","slug":"screen-shot-2019-01-22-at-11-26-05-am-png-2","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2019\/01\/16\/most-border-wall-opponents-supporters-say-shutdown-concessions-are-unacceptable\/screen-shot-2019-01-22-at-11-26-05-am-png-2\/","title":{"rendered":"Majority of public opposes substantial expansion of U.S-Mexico border wall"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-60995","attachment","type-attachment","status-inherit","hentry"],"filename":"Screen-Shot-2019-01-22-at-11.26.05-AM.png","filesize":106793,"_embeds":[],"table_of_contents":[{"id":47801,"title":"Most Border Wall Opponents, Supporters Say Shutdown Concessions Are Unacceptable","slug":"most-border-wall-opponents-supporters-say-shutdown-concessions-are-unacceptable","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2019\/01\/16\/most-border-wall-opponents-supporters-say-shutdown-concessions-are-unacceptable\/","is_active":false},{"id":47790,"title":"Methodology","slug":"methodology-213","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2019\/01\/16\/methodology-213\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=200\" class=\"attachment-medium size-medium not-transparent\" alt=\"Majority of public opposes substantial expansion of U.S-Mexico border wall\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png 628w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=200,299 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=271,405 271w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=260,389 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=310,464 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=420,629 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=160,239 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=320,479 320w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-has-transparency=\"false\" data-dominant-color=\"eae9e2\" style=\"--dominant-color: #eae9e2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Majority of public opposes substantial expansion of U.S-Mexico border wall","media_type":"image","mime_type":"image\/png","media_details":{"width":628,"height":940,"file":"2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png","filesize":106793,"sizes":{"thumbnail":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=150,150","width":150,"height":150,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=150&h=150&crop=1"},"medium":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=200,300","width":200,"height":300,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=200"},"A1":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=564,317","width":564,"height":317,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,634","width":628,"height":634,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=634&crop=1"},"A1-SMALL":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,388","width":628,"height":388,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,776","width":628,"height":776,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=776&crop=1"},"A2":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=268,151","width":268,"height":151,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=536,302","width":536,"height":302,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,388","width":628,"height":388,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,776","width":628,"height":776,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=776&crop=1"},"A3":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=194,110","width":194,"height":110,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=388,220","width":388,"height":220,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=148,84","width":148,"height":84,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=296,168","width":296,"height":168,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=296&h=168&crop=1"},"A4":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=268,151","width":268,"height":151,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=536,302","width":536,"height":302,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,388","width":628,"height":388,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,776","width":628,"height":776,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=776&crop=1"},"XL":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,405","width":628,"height":405,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=405&crop=1"},"XL-HIDPI":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,810","width":628,"height":810,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=810&crop=1"},"social":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,628","width":628,"height":628,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=628&crop=1"},"chapter":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=271,405","width":271,"height":405,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=271"},"200-wide":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=200,299","width":200,"height":299,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=200"},"260-wide":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=260,389","width":260,"height":389,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=260"},"310-wide":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=310,464","width":310,"height":464,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=310"},"420-wide":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=420,629","width":420,"height":629,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=420"},"75-square":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=75,75","width":75,"height":75,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=75&h=75&crop=1"},"140-square":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=140,140","width":140,"height":140,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=140&h=140&crop=1"},"260-square":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=260,260","width":260,"height":260,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=260&h=260&crop=1"},"160-portrait":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=160,239","width":160,"height":239,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=160"},"320-portrait":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=320,479","width":320,"height":479,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=320"},"200-by-133":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=200,133","width":200,"height":133,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=200&h=133&crop=1"},"740-by-416":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=628,416","width":628,"height":416,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=628&h=416&crop=1"},"540-by-304":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png?resize=540,304","width":540,"height":304,"filesize":106793,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png?w=540&h=304&crop=1"},"full":{"file":"Screen-Shot-2019-01-22-at-11.26.05-AM.png","width":628,"height":940,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eae9e2","has_transparency":false},"post":47801,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/Screen-Shot-2019-01-22-at-11.26.05-AM.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Majority of public opposes substantial expansion of U.S-Mexico border wall","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/60995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=60995"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":47801,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/47801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}