{"id":50627,"date":"2016-05-10T10:28:03","date_gmt":"2016-05-10T15:28:03","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png"},"modified":"2016-05-10T10:28:03","modified_gmt":"2016-05-10T15:28:03","slug":"st_2016-05-12_middle-class-geo-ch1-01-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/americas-shrinking-middle-class-a-close-look-at-changes-within-metropolitan-areas\/st_2016-05-12_middle-class-geo-ch1-01-png\/","title":{"rendered":"Who is middle income?"},"author":359,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-50627","attachment","type-attachment","status-inherit","hentry"],"filename":"ST_2016.05.12_middle-class-geo-ch1-01.png","filesize":26334,"_embeds":[],"table_of_contents":[{"id":39698,"title":"America\u2019s Shrinking Middle Class:  A Close Look at Changes Within Metropolitan Areas","slug":"americas-shrinking-middle-class-a-close-look-at-changes-within-metropolitan-areas","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/americas-shrinking-middle-class-a-close-look-at-changes-within-metropolitan-areas\/","is_active":false},{"id":39711,"title":"1. The American middle class loses ground nationally","slug":"1-the-american-middle-class-loses-ground-nationally","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/1-the-american-middle-class-loses-ground-nationally\/","is_active":false},{"id":39747,"title":"2. The relative size of income tiers and their financial status varied greatly across U.S. metropolitan areas in 2014","slug":"2-the-relative-size-of-income-tiers-and-their-financial-status-varied-greatly-across-u-s-metropolitan-areas-in-2014","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/2-the-relative-size-of-income-tiers-and-their-financial-status-varied-greatly-across-u-s-metropolitan-areas-in-2014\/","is_active":false},{"id":39733,"title":"3. The middle class shrank and incomes fell in most metropolitan areas from 2000 to 2014","slug":"3-the-middle-class-shrank-and-incomes-fell-in-most-metropolitan-areas-from-2000-to-2014","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/3-the-middle-class-shrank-and-incomes-fell-in-most-metropolitan-areas-from-2000-to-2014\/","is_active":false},{"id":39724,"title":"Acknowledgments","slug":"acknowledgments-4-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/acknowledgments-4-2\/","is_active":false},{"id":39783,"title":"Methodology","slug":"methodology-4-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/methodology-4-2\/","is_active":false},{"id":39769,"title":"Appendix A: References","slug":"appendix-a-references-3","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/appendix-a-references-3\/","is_active":false},{"id":39760,"title":"Appendix B: Detailed tables and maps","slug":"appendix-b-detailed-tables-and-maps","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2016\/05\/11\/appendix-b-detailed-tables-and-maps\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"119\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=119\" class=\"attachment-medium size-medium not-transparent\" alt=\"Who is middle income?\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png 230w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?resize=119,300 119w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?resize=161,405 161w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?resize=200,503 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?resize=127,320 127w\" sizes=\"auto, (max-width: 119px) 100vw, 119px\" data-has-transparency=\"false\" data-dominant-color=\"f1eee6\" style=\"--dominant-color: #f1eee6;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Who is middle income?","media_type":"image","mime_type":"image\/png","media_details":{"width":230,"height":578,"file":"2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png","filesize":26334,"sizes":{"thumbnail":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=150,150","width":150,"height":150,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=150&h=150&crop=1"},"medium":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=119,300","width":119,"height":300,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=119"},"A1":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,317","width":230,"height":317,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=317&crop=1"},"A1-SMALL":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,388","width":230,"height":388,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=388&crop=1"},"A2":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,151","width":230,"height":151,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=151&crop=1"},"A2-HIDPI":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,302","width":230,"height":302,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=302&crop=1"},"A2-SMALL":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,388","width":230,"height":388,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=388&crop=1"},"A3":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=194,110","width":194,"height":110,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,220","width":230,"height":220,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=220&crop=1"},"A3-SMALL":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=148,84","width":148,"height":84,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,168","width":230,"height":168,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=168&crop=1"},"A4":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,151","width":230,"height":151,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=151&crop=1"},"A4-HIDPI":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,302","width":230,"height":302,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=302&crop=1"},"A4-SMALL":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,388","width":230,"height":388,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=388&crop=1"},"XL":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,405","width":230,"height":405,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=405&crop=1"},"chapter":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=161,405","width":161,"height":405,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=161"},"200-wide":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=200,503","width":200,"height":503,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=200"},"75-square":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=75,75","width":75,"height":75,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=75&h=75&crop=1"},"140-square":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=140,140","width":140,"height":140,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=140&h=140&crop=1"},"260-square":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,260","width":230,"height":260,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=260&crop=1"},"160-portrait":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=127,320","width":127,"height":320,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=127"},"200-by-133":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=200,133","width":200,"height":133,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,416","width":230,"height":416,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=416&crop=1"},"540-by-304":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png?resize=230,304","width":230,"height":304,"filesize":26334,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png?w=230&h=304&crop=1"},"full":{"file":"ST_2016.05.12_middle-class-geo-ch1-01.png","width":230,"height":578,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1eee6","has_transparency":false},"post":39698,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/05\/ST_2016.05.12_middle-class-geo-ch1-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Who is middle income?","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/50627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/359"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=50627"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39698,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}