{"id":50344,"date":"2017-01-06T15:08:33","date_gmt":"2017-01-06T20:08:33","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png"},"modified":"2017-01-06T15:08:33","modified_gmt":"2017-01-06T20:08:33","slug":"psdt_01-11-17-police-04-04-png-2","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/police-fatal-encounters-and-ensuing-protests\/psdt_01-11-17-police-04-04-png-2\/","title":{"rendered":"Black and white officers disagree over extent to which protests are motivated by desire to hold police accountable"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-50344","attachment","type-attachment","status-inherit","hentry"],"filename":"PSDT_01.11.17.police-04-04.png","filesize":22218,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=150\" class=\"attachment-medium size-medium not-transparent\" alt=\"Black and white officers disagree over extent to which protests are motivated by desire to hold police accountable\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?resize=150,300 150w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?resize=202,405 202w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?resize=200,401 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?resize=260,522 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?resize=160,320 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-has-transparency=\"false\" data-dominant-color=\"d8e0de\" style=\"--dominant-color: #d8e0de;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Black and white officers disagree over extent to which protests are motivated by desire to hold police accountable","media_type":"image","mime_type":"image\/png","media_details":{"width":310,"height":622,"file":"2017\/01\/PSDT_01.11.17.police-04-04.png","filesize":22218,"sizes":{"thumbnail":{"file":"PSDT_01.11.17.police-04-04.png?resize=150,150","width":150,"height":150,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_01.11.17.police-04-04.png?resize=150,300","width":150,"height":300,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=150"},"A1":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,317","width":310,"height":317,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=317&crop=1"},"A1-SMALL":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,388","width":310,"height":388,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=388&crop=1"},"A2":{"file":"PSDT_01.11.17.police-04-04.png?resize=268,151","width":268,"height":151,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,302","width":310,"height":302,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,388","width":310,"height":388,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=388&crop=1"},"A3":{"file":"PSDT_01.11.17.police-04-04.png?resize=194,110","width":194,"height":110,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,220","width":310,"height":220,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_01.11.17.police-04-04.png?resize=148,84","width":148,"height":84,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_01.11.17.police-04-04.png?resize=296,168","width":296,"height":168,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_01.11.17.police-04-04.png?resize=268,151","width":268,"height":151,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,302","width":310,"height":302,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,388","width":310,"height":388,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=388&crop=1"},"XL":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,405","width":310,"height":405,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=405&crop=1"},"chapter":{"file":"PSDT_01.11.17.police-04-04.png?resize=202,405","width":202,"height":405,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=202"},"200-wide":{"file":"PSDT_01.11.17.police-04-04.png?resize=200,401","width":200,"height":401,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=200"},"260-wide":{"file":"PSDT_01.11.17.police-04-04.png?resize=260,522","width":260,"height":522,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=260"},"75-square":{"file":"PSDT_01.11.17.police-04-04.png?resize=75,75","width":75,"height":75,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_01.11.17.police-04-04.png?resize=140,140","width":140,"height":140,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_01.11.17.police-04-04.png?resize=260,260","width":260,"height":260,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_01.11.17.police-04-04.png?resize=160,320","width":160,"height":320,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=160"},"200-by-133":{"file":"PSDT_01.11.17.police-04-04.png?resize=200,133","width":200,"height":133,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,416","width":310,"height":416,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=416&crop=1"},"540-by-304":{"file":"PSDT_01.11.17.police-04-04.png?resize=310,304","width":310,"height":304,"filesize":22218,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png?w=310&h=304&crop=1"},"full":{"file":"PSDT_01.11.17.police-04-04.png","width":310,"height":622,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d8e0de","has_transparency":false},"post":39636,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-04-04.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Black and white officers disagree over extent to which protests are motivated by desire to hold police accountable","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/50344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=50344"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39636,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}