{"id":50268,"date":"2017-01-06T14:12:51","date_gmt":"2017-01-06T19:12:51","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png"},"modified":"2017-01-06T14:12:51","modified_gmt":"2017-01-06T19:12:51","slug":"psdt_01-11-17-police-00-03-png-2","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/behind-the-badge\/psdt_01-11-17-police-00-03-png-2\/","title":{"rendered":"Most white, Latino officers say fatal encounters between blacks and police are isolated incidents; majority of black officers disagree"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-50268","attachment","type-attachment","status-inherit","hentry"],"filename":"PSDT_01.11.17.police-00-03.png","filesize":17219,"_embeds":[],"table_of_contents":[{"id":39665,"title":"Behind the Badge","slug":"behind-the-badge","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/behind-the-badge\/","is_active":false},{"id":39597,"title":"1. Police culture","slug":"police-culture","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/police-culture\/","is_active":false},{"id":39611,"title":"2. Inside America\u2019s police departments","slug":"inside-americas-police-departments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/inside-americas-police-departments\/","is_active":false},{"id":39642,"title":"3. Police and the community","slug":"police-and-the-community","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/police-and-the-community\/","is_active":false},{"id":39636,"title":"4. Police, fatal encounters and ensuing protests","slug":"police-fatal-encounters-and-ensuing-protests","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/police-fatal-encounters-and-ensuing-protests\/","is_active":false},{"id":39622,"title":"5. Reimagining the police through training and reforms","slug":"reimagining-the-police-through-training-and-reforms","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/reimagining-the-police-through-training-and-reforms\/","is_active":false},{"id":39649,"title":"6. Police views, public views","slug":"police-views-public-views","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/police-views-public-views\/","is_active":false},{"id":39657,"title":"Acknowledgments","slug":"acknowledgments-10-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/acknowledgments-10-2\/","is_active":false},{"id":39680,"title":"Methodology","slug":"behind-the-badge-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/01\/11\/behind-the-badge-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=213\" class=\"attachment-medium size-medium not-transparent\" alt=\"Most white, Latino officers say fatal encounters between blacks and police are isolated incidents; majority of black officers disagree\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png 311w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?resize=213,300 213w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?resize=287,405 287w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?resize=200,282 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?resize=260,367 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?resize=160,226 160w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" data-has-transparency=\"false\" data-dominant-color=\"e4e3db\" style=\"--dominant-color: #e4e3db;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Most white, Latino officers say fatal encounters between blacks and police are isolated incidents; majority of black officers disagree","media_type":"image","mime_type":"image\/png","media_details":{"width":311,"height":439,"file":"2017\/01\/PSDT_01.11.17.police-00-03.png","filesize":17219,"sizes":{"thumbnail":{"file":"PSDT_01.11.17.police-00-03.png?resize=150,150","width":150,"height":150,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_01.11.17.police-00-03.png?resize=213,300","width":213,"height":300,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=213"},"A1":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,317","width":311,"height":317,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=317&crop=1"},"A1-SMALL":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,388","width":311,"height":388,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=388&crop=1"},"A2":{"file":"PSDT_01.11.17.police-00-03.png?resize=268,151","width":268,"height":151,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,302","width":311,"height":302,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,388","width":311,"height":388,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=388&crop=1"},"A3":{"file":"PSDT_01.11.17.police-00-03.png?resize=194,110","width":194,"height":110,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,220","width":311,"height":220,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_01.11.17.police-00-03.png?resize=148,84","width":148,"height":84,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_01.11.17.police-00-03.png?resize=296,168","width":296,"height":168,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_01.11.17.police-00-03.png?resize=268,151","width":268,"height":151,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,302","width":311,"height":302,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,388","width":311,"height":388,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=388&crop=1"},"XL":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,405","width":311,"height":405,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=405&crop=1"},"chapter":{"file":"PSDT_01.11.17.police-00-03.png?resize=287,405","width":287,"height":405,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=287"},"200-wide":{"file":"PSDT_01.11.17.police-00-03.png?resize=200,282","width":200,"height":282,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=200"},"260-wide":{"file":"PSDT_01.11.17.police-00-03.png?resize=260,367","width":260,"height":367,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=260"},"75-square":{"file":"PSDT_01.11.17.police-00-03.png?resize=75,75","width":75,"height":75,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_01.11.17.police-00-03.png?resize=140,140","width":140,"height":140,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_01.11.17.police-00-03.png?resize=260,260","width":260,"height":260,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_01.11.17.police-00-03.png?resize=160,226","width":160,"height":226,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=160"},"200-by-133":{"file":"PSDT_01.11.17.police-00-03.png?resize=200,133","width":200,"height":133,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,416","width":311,"height":416,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=416&crop=1"},"540-by-304":{"file":"PSDT_01.11.17.police-00-03.png?resize=311,304","width":311,"height":304,"filesize":17219,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png?w=311&h=304&crop=1"},"full":{"file":"PSDT_01.11.17.police-00-03.png","width":311,"height":439,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e4e3db","has_transparency":false},"post":39665,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/01\/PSDT_01.11.17.police-00-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Most white, Latino officers say fatal encounters between blacks and police are isolated incidents; majority of black officers disagree","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/50268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=50268"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39665,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}