{"id":49971,"date":"2017-11-30T17:01:11","date_gmt":"2017-11-30T22:01:11","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png"},"modified":"2017-11-30T17:01:11","modified_gmt":"2017-11-30T22:01:11","slug":"pst_12-05-17-gender-02-01-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2017\/12\/05\/americans-see-different-expectations-for-men-and-women\/pst_12-05-17-gender-02-01-png\/","title":{"rendered":"Large gaps in the public\u2019s view of the types of pressure men and women face"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-49971","attachment","type-attachment","status-inherit","hentry"],"filename":"PST_12.05.17.gender-02-01.png","filesize":8726,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"245\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=245\" class=\"attachment-medium size-medium not-transparent\" alt=\"Large gaps in the public\u2019s view of the types of pressure men and women face\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png 309w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?resize=245,300 245w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?resize=200,245 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?resize=260,319 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?resize=160,196 160w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\" data-has-transparency=\"false\" data-dominant-color=\"dae3e1\" style=\"--dominant-color: #dae3e1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Large gaps in the public\u2019s view of the types of pressure men and women face","media_type":"image","mime_type":"image\/png","media_details":{"width":309,"height":379,"file":"2017\/11\/PST_12.05.17.gender-02-01.png","filesize":8726,"sizes":{"thumbnail":{"file":"PST_12.05.17.gender-02-01.png?resize=150,150","width":150,"height":150,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=150&h=150&crop=1"},"medium":{"file":"PST_12.05.17.gender-02-01.png?resize=245,300","width":245,"height":300,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=245"},"A1":{"file":"PST_12.05.17.gender-02-01.png?resize=309,317","width":309,"height":317,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=309&h=317&crop=1"},"A2":{"file":"PST_12.05.17.gender-02-01.png?resize=268,151","width":268,"height":151,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PST_12.05.17.gender-02-01.png?resize=309,302","width":309,"height":302,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=309&h=302&crop=1"},"A3":{"file":"PST_12.05.17.gender-02-01.png?resize=194,110","width":194,"height":110,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PST_12.05.17.gender-02-01.png?resize=309,220","width":309,"height":220,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=309&h=220&crop=1"},"A3-SMALL":{"file":"PST_12.05.17.gender-02-01.png?resize=148,84","width":148,"height":84,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PST_12.05.17.gender-02-01.png?resize=296,168","width":296,"height":168,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=296&h=168&crop=1"},"A4":{"file":"PST_12.05.17.gender-02-01.png?resize=268,151","width":268,"height":151,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PST_12.05.17.gender-02-01.png?resize=309,302","width":309,"height":302,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=309&h=302&crop=1"},"200-wide":{"file":"PST_12.05.17.gender-02-01.png?resize=200,245","width":200,"height":245,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=200"},"260-wide":{"file":"PST_12.05.17.gender-02-01.png?resize=260,319","width":260,"height":319,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=260"},"75-square":{"file":"PST_12.05.17.gender-02-01.png?resize=75,75","width":75,"height":75,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PST_12.05.17.gender-02-01.png?resize=140,140","width":140,"height":140,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PST_12.05.17.gender-02-01.png?resize=260,260","width":260,"height":260,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PST_12.05.17.gender-02-01.png?resize=160,196","width":160,"height":196,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=160"},"200-by-133":{"file":"PST_12.05.17.gender-02-01.png?resize=200,133","width":200,"height":133,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=200&h=133&crop=1"},"540-by-304":{"file":"PST_12.05.17.gender-02-01.png?resize=309,304","width":309,"height":304,"filesize":8726,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png?w=309&h=304&crop=1"},"full":{"file":"PST_12.05.17.gender-02-01.png","width":309,"height":379,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"dae3e1","has_transparency":false},"post":39681,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PST_12.05.17.gender-02-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Large gaps in the public\u2019s view of the types of pressure men and women face","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/49971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=49971"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39681,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}