{"id":49491,"date":"2019-01-14T16:27:34","date_gmt":"2019-01-14T21:27:34","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png"},"modified":"2019-01-14T16:27:34","modified_gmt":"2019-01-14T21:27:34","slug":"psdt_1-17-19_generations-14-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2019\/01\/17\/generation-z-looks-a-lot-like-millennials-on-key-social-and-political-issues\/psdt_1-17-19_generations-14-png\/","title":{"rendered":"About half of Gen Zers, Millennials say society isn\u2019t accepting enough of people who don\u2019t identify as a man or woman"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-49491","attachment","type-attachment","status-inherit","hentry"],"filename":"PSDT_1.17.19_generations-14.png","filesize":70974,"_embeds":[],"table_of_contents":[{"id":39445,"title":"Generation Z Looks a Lot Like Millennials on Key Social and Political Issues","slug":"generation-z-looks-a-lot-like-millennials-on-key-social-and-political-issues","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2019\/01\/17\/generation-z-looks-a-lot-like-millennials-on-key-social-and-political-issues\/","is_active":false},{"id":39432,"title":"Acknowledgments","slug":"acknowledgments-24","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2019\/01\/17\/acknowledgments-24\/","is_active":false},{"id":39465,"title":"Methodology","slug":"generations-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2019\/01\/17\/generations-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"206\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=206\" class=\"attachment-medium size-medium not-transparent\" alt=\"About half of Gen Zers, Millennials say society isn\u2019t accepting enough of people who don\u2019t identify as a man or woman\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png 616w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=206,300 206w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=278,405 278w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=200,292 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=260,379 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=310,452 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=420,613 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=160,234 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?resize=320,467 320w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" data-has-transparency=\"false\" data-dominant-color=\"d5e0dd\" style=\"--dominant-color: #d5e0dd;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"About half of Gen Zers, Millennials say society isn\u2019t accepting enough of people who don\u2019t identify as a man or woman","media_type":"image","mime_type":"image\/png","media_details":{"width":616,"height":899,"file":"2019\/01\/PSDT_1.17.19_generations-14.png","filesize":70974,"sizes":{"thumbnail":{"file":"PSDT_1.17.19_generations-14.png?resize=150,150","width":150,"height":150,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_1.17.19_generations-14.png?resize=206,300","width":206,"height":300,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=206"},"A1":{"file":"PSDT_1.17.19_generations-14.png?resize=564,317","width":564,"height":317,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=616,634","width":616,"height":634,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=634&crop=1"},"A1-SMALL":{"file":"PSDT_1.17.19_generations-14.png?resize=616,388","width":616,"height":388,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=616,776","width":616,"height":776,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=776&crop=1"},"A2":{"file":"PSDT_1.17.19_generations-14.png?resize=268,151","width":268,"height":151,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=536,302","width":536,"height":302,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_1.17.19_generations-14.png?resize=616,388","width":616,"height":388,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=616,776","width":616,"height":776,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=776&crop=1"},"A3":{"file":"PSDT_1.17.19_generations-14.png?resize=194,110","width":194,"height":110,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=388,220","width":388,"height":220,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_1.17.19_generations-14.png?resize=148,84","width":148,"height":84,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=296,168","width":296,"height":168,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_1.17.19_generations-14.png?resize=268,151","width":268,"height":151,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=536,302","width":536,"height":302,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_1.17.19_generations-14.png?resize=616,388","width":616,"height":388,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=616,776","width":616,"height":776,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=776&crop=1"},"XL":{"file":"PSDT_1.17.19_generations-14.png?resize=616,405","width":616,"height":405,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=405&crop=1"},"XL-HIDPI":{"file":"PSDT_1.17.19_generations-14.png?resize=616,810","width":616,"height":810,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=810&crop=1"},"social":{"file":"PSDT_1.17.19_generations-14.png?resize=616,628","width":616,"height":628,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=628&crop=1"},"chapter":{"file":"PSDT_1.17.19_generations-14.png?resize=278,405","width":278,"height":405,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=278"},"200-wide":{"file":"PSDT_1.17.19_generations-14.png?resize=200,292","width":200,"height":292,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=200"},"260-wide":{"file":"PSDT_1.17.19_generations-14.png?resize=260,379","width":260,"height":379,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=260"},"310-wide":{"file":"PSDT_1.17.19_generations-14.png?resize=310,452","width":310,"height":452,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=310"},"420-wide":{"file":"PSDT_1.17.19_generations-14.png?resize=420,613","width":420,"height":613,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=420"},"75-square":{"file":"PSDT_1.17.19_generations-14.png?resize=75,75","width":75,"height":75,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_1.17.19_generations-14.png?resize=140,140","width":140,"height":140,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_1.17.19_generations-14.png?resize=260,260","width":260,"height":260,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_1.17.19_generations-14.png?resize=160,234","width":160,"height":234,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=160"},"320-portrait":{"file":"PSDT_1.17.19_generations-14.png?resize=320,467","width":320,"height":467,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=320"},"200-by-133":{"file":"PSDT_1.17.19_generations-14.png?resize=200,133","width":200,"height":133,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_1.17.19_generations-14.png?resize=616,416","width":616,"height":416,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=616&h=416&crop=1"},"540-by-304":{"file":"PSDT_1.17.19_generations-14.png?resize=540,304","width":540,"height":304,"filesize":70974,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png?w=540&h=304&crop=1"},"full":{"file":"PSDT_1.17.19_generations-14.png","width":616,"height":899,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d5e0dd","has_transparency":false},"post":39445,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/PSDT_1.17.19_generations-14.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"About half of Gen Zers, Millennials say society isn\u2019t accepting enough of people who don\u2019t identify as a man or woman","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/49491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=49491"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39445,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}