{"id":49265,"date":"2017-06-20T10:46:24","date_gmt":"2017-06-20T15:46:24","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png"},"modified":"2017-06-20T10:46:24","modified_gmt":"2017-06-20T15:46:24","slug":"psdt_2017-06-22-guns-05-08-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2017\/06\/22\/views-on-gun-policy\/psdt_2017-06-22-guns-05-08-png\/","title":{"rendered":"Wide differences between Republican gun owners, non-gun owners on several policies"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-49265","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png'><img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=244\" class=\"attachment-medium size-medium not-transparent\" alt=\"Wide differences between Republican gun owners, non-gun owners on several policies\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=244,300 244w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=330,405 330w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=200,246 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=260,319 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=310,381 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=160,197 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?resize=320,393 320w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" data-has-transparency=\"false\" data-dominant-color=\"efefef\" style=\"--dominant-color: #efefef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Wide differences between Republican gun owners, non-gun owners on several policies","media_type":"image","mime_type":"image\/png","media_details":{"width":420,"height":516,"file":"2017\/06\/PSDT_2017.06.22.guns-05-08.png","filesize":24055,"sizes":{"thumbnail":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=150,150","width":150,"height":150,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=244,300","width":244,"height":300,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=244"},"A1":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,317","width":420,"height":317,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=317&crop=1"},"A1-SMALL":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,388","width":420,"height":388,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=388&crop=1"},"A2":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=268,151","width":268,"height":151,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,302","width":420,"height":302,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,388","width":420,"height":388,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=388&crop=1"},"A3":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=194,110","width":194,"height":110,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=388,220","width":388,"height":220,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=148,84","width":148,"height":84,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=296,168","width":296,"height":168,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=268,151","width":268,"height":151,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,302","width":420,"height":302,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,388","width":420,"height":388,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=388&crop=1"},"XL":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,405","width":420,"height":405,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=405&crop=1"},"chapter":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=330,405","width":330,"height":405,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=330"},"200-wide":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=200,246","width":200,"height":246,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=200"},"260-wide":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=260,319","width":260,"height":319,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=260"},"310-wide":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=310,381","width":310,"height":381,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=310"},"75-square":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=75,75","width":75,"height":75,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=140,140","width":140,"height":140,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=260,260","width":260,"height":260,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=160,197","width":160,"height":197,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=160"},"320-portrait":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=320,393","width":320,"height":393,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=320"},"200-by-133":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=200,133","width":200,"height":133,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,416","width":420,"height":416,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=416&crop=1"},"540-by-304":{"file":"PSDT_2017.06.22.guns-05-08.png?resize=420,304","width":420,"height":304,"filesize":24055,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png?w=420&h=304&crop=1"},"full":{"file":"PSDT_2017.06.22.guns-05-08.png","width":420,"height":516,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"efefef","has_transparency":false},"post":39599,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-08.png","filename":"PSDT_2017.06.22.guns-05-08.png","filesize":24055,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/49265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=49265"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39599,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}