{"id":49225,"date":"2017-06-20T10:46:03","date_gmt":"2017-06-20T15:46:03","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png"},"modified":"2017-06-20T10:46:03","modified_gmt":"2017-06-20T15:46:03","slug":"psdt_2017-06-22-guns-05-01-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2017\/06\/22\/views-on-gun-policy\/psdt_2017-06-22-guns-05-01-png\/","title":{"rendered":"Republicans say protecting right to own guns is more important"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-49225","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"228\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=228\" class=\"attachment-medium size-medium not-transparent\" alt=\"Republicans say protecting right to own guns is more important\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?resize=228,300 228w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?resize=308,405 308w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?resize=200,263 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?resize=260,342 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?resize=160,211 160w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" data-has-transparency=\"false\" data-dominant-color=\"f1efef\" style=\"--dominant-color: #f1efef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Republicans say protecting right to own guns is more important","media_type":"image","mime_type":"image\/png","media_details":{"width":310,"height":408,"file":"2017\/06\/PSDT_2017.06.22.guns-05-01.png","filesize":19539,"sizes":{"thumbnail":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=150,150","width":150,"height":150,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=228,300","width":228,"height":300,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=228"},"A1":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,317","width":310,"height":317,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=317&crop=1"},"A1-SMALL":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,388","width":310,"height":388,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=388&crop=1"},"A2":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=268,151","width":268,"height":151,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,302","width":310,"height":302,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,388","width":310,"height":388,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=388&crop=1"},"A3":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=194,110","width":194,"height":110,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,220","width":310,"height":220,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=148,84","width":148,"height":84,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=296,168","width":296,"height":168,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=268,151","width":268,"height":151,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,302","width":310,"height":302,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,388","width":310,"height":388,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=388&crop=1"},"XL":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,405","width":310,"height":405,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=405&crop=1"},"chapter":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=308,405","width":308,"height":405,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=308"},"200-wide":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=200,263","width":200,"height":263,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=200"},"260-wide":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=260,342","width":260,"height":342,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=260"},"75-square":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=75,75","width":75,"height":75,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=140,140","width":140,"height":140,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=260,260","width":260,"height":260,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=160,211","width":160,"height":211,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=160"},"200-by-133":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=200,133","width":200,"height":133,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=200&h=133&crop=1"},"540-by-304":{"file":"PSDT_2017.06.22.guns-05-01.png?resize=310,304","width":310,"height":304,"filesize":19539,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png?w=310&h=304&crop=1"},"full":{"file":"PSDT_2017.06.22.guns-05-01.png","width":310,"height":408,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1efef","has_transparency":false},"post":39599,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/06\/PSDT_2017.06.22.guns-05-01.png","filename":"PSDT_2017.06.22.guns-05-01.png","filesize":19539,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/49225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=49225"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39599,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}