{"id":48031,"date":"2020-10-05T10:01:48","date_gmt":"2020-10-05T15:01:48","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png"},"modified":"2020-10-05T10:01:48","modified_gmt":"2020-10-05T15:01:48","slug":"psdt_010-06-20_race-update-9-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change\/psdt_010-06-20_race-update-9-png\/","title":{"rendered":"Black adults are more likely than other racial or ethnic groups to say they\u2019ve done a lot recently to educate themselves about racial inequality"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-48031","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":39172,"title":"Amid National Reckoning, Americans Divided on Whether Increased Focus on Race Will Lead to Major Policy Change","slug":"amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change\/","is_active":false},{"id":39153,"title":"Acknowledgments","slug":"acknowledgments-47","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/acknowledgments-47\/","is_active":false},{"id":39138,"title":"Methodology","slug":"methodology-39-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/methodology-39-2\/","is_active":false}],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png'><img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=280\" class=\"attachment-medium size-medium not-transparent\" alt=\"Black adults are more likely than other racial or ethnic groups to say they\u2019ve done a lot recently to educate themselves about racial inequality\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png 836w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=280,300 280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=768,823 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=378,405 378w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=200,214 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=260,279 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=310,332 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=420,450 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=640,686 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=740,793 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=160,171 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?resize=320,343 320w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" data-has-transparency=\"false\" data-dominant-color=\"e9e9e6\" style=\"--dominant-color: #e9e9e6;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Black adults are more likely than other racial or ethnic groups to say they\u2019ve done a lot recently to educate themselves about racial inequality","media_type":"image","mime_type":"image\/png","media_details":{"width":836,"height":896,"file":"2020\/10\/PSDT_010.06.20_race.update-9.png","filesize":255684,"sizes":{"thumbnail":{"file":"PSDT_010.06.20_race.update-9.png?resize=150,150","width":150,"height":150,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_010.06.20_race.update-9.png?resize=280,300","width":280,"height":300,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=280"},"medium_large":{"file":"PSDT_010.06.20_race.update-9.png?resize=768,823","width":768,"height":823,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=640"},"A1":{"file":"PSDT_010.06.20_race.update-9.png?resize=564,317","width":564,"height":317,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,634","width":836,"height":634,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=634&crop=1"},"A1-SMALL":{"file":"PSDT_010.06.20_race.update-9.png?resize=690,388","width":690,"height":388,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,776","width":836,"height":776,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=776&crop=1"},"A2":{"file":"PSDT_010.06.20_race.update-9.png?resize=268,151","width":268,"height":151,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=536,302","width":536,"height":302,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_010.06.20_race.update-9.png?resize=690,388","width":690,"height":388,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,776","width":836,"height":776,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=776&crop=1"},"A3":{"file":"PSDT_010.06.20_race.update-9.png?resize=194,110","width":194,"height":110,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=388,220","width":388,"height":220,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_010.06.20_race.update-9.png?resize=148,84","width":148,"height":84,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=296,168","width":296,"height":168,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_010.06.20_race.update-9.png?resize=268,151","width":268,"height":151,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=536,302","width":536,"height":302,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_010.06.20_race.update-9.png?resize=690,388","width":690,"height":388,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,776","width":836,"height":776,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=776&crop=1"},"XL":{"file":"PSDT_010.06.20_race.update-9.png?resize=720,405","width":720,"height":405,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,810","width":836,"height":810,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=810&crop=1"},"social":{"file":"PSDT_010.06.20_race.update-9.png?resize=836,628","width":836,"height":628,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=836&h=628&crop=1"},"chapter":{"file":"PSDT_010.06.20_race.update-9.png?resize=378,405","width":378,"height":405,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=378"},"200-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=200,214","width":200,"height":214,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=200"},"260-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=260,279","width":260,"height":279,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=260"},"310-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=310,332","width":310,"height":332,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=310"},"420-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=420,450","width":420,"height":450,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=420"},"640-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=640,686","width":640,"height":686,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=640"},"740-wide":{"file":"PSDT_010.06.20_race.update-9.png?resize=740,793","width":740,"height":793,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=740"},"75-square":{"file":"PSDT_010.06.20_race.update-9.png?resize=75,75","width":75,"height":75,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_010.06.20_race.update-9.png?resize=140,140","width":140,"height":140,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_010.06.20_race.update-9.png?resize=260,260","width":260,"height":260,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_010.06.20_race.update-9.png?resize=160,171","width":160,"height":171,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=160"},"320-portrait":{"file":"PSDT_010.06.20_race.update-9.png?resize=320,343","width":320,"height":343,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=320"},"200-by-133":{"file":"PSDT_010.06.20_race.update-9.png?resize=200,133","width":200,"height":133,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_010.06.20_race.update-9.png?resize=740,416","width":740,"height":416,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PSDT_010.06.20_race.update-9.png?resize=540,304","width":540,"height":304,"filesize":255684,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png?w=540&h=304&crop=1"},"full":{"file":"PSDT_010.06.20_race.update-9.png","width":836,"height":896,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e9e9e6","has_transparency":false},"post":39172,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-9.png","filename":"PSDT_010.06.20_race.update-9.png","filesize":255684,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/48031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=48031"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39172,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}