{"id":47973,"date":"2020-10-05T10:02:20","date_gmt":"2020-10-05T15:02:20","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png"},"modified":"2020-10-05T10:02:20","modified_gmt":"2020-10-05T15:02:20","slug":"psdt_010-06-20_race-update-18-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change\/psdt_010-06-20_race-update-18-png\/","title":{"rendered":"Republicans are more likely than Democrats to cite \u2018colorblindness\u2019 as doing a lot to reduce racial inequality"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-47973","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":39172,"title":"Amid National Reckoning, Americans Divided on Whether Increased Focus on Race Will Lead to Major Policy Change","slug":"amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/amid-national-reckoning-americans-divided-on-whether-increased-focus-on-race-will-lead-to-major-policy-change\/","is_active":false},{"id":39153,"title":"Acknowledgments","slug":"acknowledgments-47","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/acknowledgments-47\/","is_active":false},{"id":39138,"title":"Methodology","slug":"methodology-39-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2020\/10\/06\/methodology-39-2\/","is_active":false}],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png'><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=201\" class=\"attachment-medium size-medium not-transparent\" alt=\"Republicans are more likely than Democrats to cite \u2018colorblindness\u2019 as doing a lot to reduce racial inequality\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png 626w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=201,300 201w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=271,405 271w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=200,298 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=260,388 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=310,463 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=420,627 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=160,239 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?resize=320,477 320w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" data-has-transparency=\"false\" data-dominant-color=\"e7e7e7\" style=\"--dominant-color: #e7e7e7;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Republicans are more likely than Democrats to cite \u2018colorblindness\u2019 as doing a lot to reduce racial inequality","media_type":"image","mime_type":"image\/png","media_details":{"width":626,"height":934,"file":"2020\/10\/PSDT_010.06.20_race.update-18.png","filesize":234163,"sizes":{"thumbnail":{"file":"PSDT_010.06.20_race.update-18.png?resize=150,150","width":150,"height":150,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=150&h=150&crop=1"},"medium":{"file":"PSDT_010.06.20_race.update-18.png?resize=201,300","width":201,"height":300,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=201"},"A1":{"file":"PSDT_010.06.20_race.update-18.png?resize=564,317","width":564,"height":317,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,634","width":626,"height":634,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=634&crop=1"},"A1-SMALL":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,388","width":626,"height":388,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,776","width":626,"height":776,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=776&crop=1"},"A2":{"file":"PSDT_010.06.20_race.update-18.png?resize=268,151","width":268,"height":151,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=536,302","width":536,"height":302,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,388","width":626,"height":388,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,776","width":626,"height":776,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=776&crop=1"},"A3":{"file":"PSDT_010.06.20_race.update-18.png?resize=194,110","width":194,"height":110,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=388,220","width":388,"height":220,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PSDT_010.06.20_race.update-18.png?resize=148,84","width":148,"height":84,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=296,168","width":296,"height":168,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=296&h=168&crop=1"},"A4":{"file":"PSDT_010.06.20_race.update-18.png?resize=268,151","width":268,"height":151,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=536,302","width":536,"height":302,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,388","width":626,"height":388,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,776","width":626,"height":776,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=776&crop=1"},"XL":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,405","width":626,"height":405,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=405&crop=1"},"XL-HIDPI":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,810","width":626,"height":810,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=810&crop=1"},"social":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,628","width":626,"height":628,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=628&crop=1"},"chapter":{"file":"PSDT_010.06.20_race.update-18.png?resize=271,405","width":271,"height":405,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=271"},"200-wide":{"file":"PSDT_010.06.20_race.update-18.png?resize=200,298","width":200,"height":298,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=200"},"260-wide":{"file":"PSDT_010.06.20_race.update-18.png?resize=260,388","width":260,"height":388,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=260"},"310-wide":{"file":"PSDT_010.06.20_race.update-18.png?resize=310,463","width":310,"height":463,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=310"},"420-wide":{"file":"PSDT_010.06.20_race.update-18.png?resize=420,627","width":420,"height":627,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=420"},"75-square":{"file":"PSDT_010.06.20_race.update-18.png?resize=75,75","width":75,"height":75,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=75&h=75&crop=1"},"140-square":{"file":"PSDT_010.06.20_race.update-18.png?resize=140,140","width":140,"height":140,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=140&h=140&crop=1"},"260-square":{"file":"PSDT_010.06.20_race.update-18.png?resize=260,260","width":260,"height":260,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PSDT_010.06.20_race.update-18.png?resize=160,239","width":160,"height":239,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=160"},"320-portrait":{"file":"PSDT_010.06.20_race.update-18.png?resize=320,477","width":320,"height":477,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=320"},"200-by-133":{"file":"PSDT_010.06.20_race.update-18.png?resize=200,133","width":200,"height":133,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PSDT_010.06.20_race.update-18.png?resize=626,416","width":626,"height":416,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=626&h=416&crop=1"},"540-by-304":{"file":"PSDT_010.06.20_race.update-18.png?resize=540,304","width":540,"height":304,"filesize":234163,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png?w=540&h=304&crop=1"},"full":{"file":"PSDT_010.06.20_race.update-18.png","width":626,"height":934,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e7e7e7","has_transparency":false},"post":39172,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/10\/PSDT_010.06.20_race.update-18.png","filename":"PSDT_010.06.20_race.update-18.png","filesize":234163,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/47973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=47973"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39172,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}