{"id":35940,"date":"2021-03-04T08:00:06","date_gmt":"2021-03-04T13:00:06","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png"},"modified":"2021-03-04T08:00:06","modified_gmt":"2021-03-04T13:00:06","slug":"pg_2021-03-04_us-views-china_0-18-1-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/03\/04\/most-americans-support-tough-stance-toward-china-on-human-rights-economic-issues\/pg_2021-03-04_us-views-china_0-18-1-png\/","title":{"rendered":"More than half of Americans say China and U.S. have handled COVID-19 poorly"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-35940","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":28265,"title":"Most Americans Support Tough Stance Toward China on Human Rights, Economic Issues","slug":"most-americans-support-tough-stance-toward-china-on-human-rights-economic-issues","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/03\/04\/most-americans-support-tough-stance-toward-china-on-human-rights-economic-issues\/","is_active":false},{"id":28249,"title":"Acknowledgments","slug":"u-s-views-of-china-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/03\/04\/u-s-views-of-china-acknowledgments\/","is_active":false},{"id":28259,"title":"Methodology","slug":"u-s-views-of-china-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/03\/04\/u-s-views-of-china-methodology\/","is_active":false}],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"282\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=282\" class=\"attachment-medium size-medium not-transparent\" alt=\"More than half of Americans say China and U.S. have handled COVID-19 poorly\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=282,300 282w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=380,405 380w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=200,213 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=260,277 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=310,330 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=420,447 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=160,170 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?resize=320,341 320w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" data-has-transparency=\"false\" data-dominant-color=\"d3d8d7\" style=\"--dominant-color: #d3d8d7;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"More than half of Americans say China and U.S. have handled COVID-19 poorly","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":660,"file":"2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png","filesize":80717,"sizes":{"thumbnail":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=150,150","width":150,"height":150,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=150&h=150&crop=1"},"medium":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=282,300","width":282,"height":300,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=282"},"A1":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=564,317","width":564,"height":317,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,634","width":620,"height":634,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,388","width":620,"height":388,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=388&crop=1"},"A2":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=268,151","width":268,"height":151,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=536,302","width":536,"height":302,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,388","width":620,"height":388,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=388&crop=1"},"A3":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=194,110","width":194,"height":110,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=388,220","width":388,"height":220,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=148,84","width":148,"height":84,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=296,168","width":296,"height":168,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=296&h=168&crop=1"},"A4":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=268,151","width":268,"height":151,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=536,302","width":536,"height":302,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,388","width":620,"height":388,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=388&crop=1"},"XL":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,405","width":620,"height":405,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=405&crop=1"},"social":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,628","width":620,"height":628,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=628&crop=1"},"chapter":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=380,405","width":380,"height":405,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=380"},"200-wide":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=200,213","width":200,"height":213,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=200"},"260-wide":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=260,277","width":260,"height":277,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=260"},"310-wide":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=310,330","width":310,"height":330,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=310"},"420-wide":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=420,447","width":420,"height":447,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=420"},"75-square":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=75,75","width":75,"height":75,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=75&h=75&crop=1"},"140-square":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=140,140","width":140,"height":140,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=140&h=140&crop=1"},"260-square":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=260,260","width":260,"height":260,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=160,170","width":160,"height":170,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=160"},"320-portrait":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=320,341","width":320,"height":341,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=320"},"200-by-133":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=200,133","width":200,"height":133,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=620,416","width":620,"height":416,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PG_2021.03.04_us-views-china_0-18-1.png?resize=540,304","width":540,"height":304,"filesize":80717,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png?w=540&h=304&crop=1"},"full":{"file":"PG_2021.03.04_us-views-china_0-18-1.png","width":620,"height":660,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d3d8d7","has_transparency":false},"post":28265,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PG_2021.03.04_us-views-china_0-18-1.png","filename":"PG_2021.03.04_us-views-china_0-18-1.png","filesize":80717,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/35940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=35940"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":28265,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/28265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}