{"id":35588,"date":"2021-01-12T16:23:47","date_gmt":"2021-01-12T21:23:47","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png"},"modified":"2021-01-12T16:23:47","modified_gmt":"2021-01-12T21:23:47","slug":"pg_2021-01-13_global-legislators_0-07-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/01\/13\/legislators-in-uk-canada-and-australia-express-post-election-enthusiasm-for-biden-administration-on-twitter\/pg_2021-01-13_global-legislators_0-07-png\/","title":{"rendered":"As U.S. election approached, many legislators in three ally nations tweeted about the U.S."},"author":578,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-35588","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":28217,"title":"Legislators in UK, Canada and Australia Express Post-election Enthusiasm for Biden Administration on Twitter","slug":"legislators-in-uk-canada-and-australia-express-post-election-enthusiasm-for-biden-administration-on-twitter","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/01\/13\/legislators-in-uk-canada-and-australia-express-post-election-enthusiasm-for-biden-administration-on-twitter\/","is_active":false},{"id":28209,"title":"Acknowledgments","slug":"global-legislators-2020-election-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/01\/13\/global-legislators-2020-election-acknowledgments\/","is_active":false},{"id":28199,"title":"Methodology","slug":"global-legislators-2020-election-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/data-labs\/2021\/01\/13\/global-legislators-2020-election-methodology\/","is_active":false}],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png'><img loading=\"lazy\" decoding=\"async\" width=\"274\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=274\" class=\"attachment-medium size-medium not-transparent\" alt=\"As U.S. election approached, many legislators in three ally nations tweeted about the U.S.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=274,300 274w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=768,841 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=370,405 370w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=200,219 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=260,285 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=310,340 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=420,460 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=640,701 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=740,810 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=160,175 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?resize=320,350 320w\" sizes=\"auto, (max-width: 274px) 100vw, 274px\" data-has-transparency=\"false\" data-dominant-color=\"ecece5\" style=\"--dominant-color: #ecece5;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"As U.S. election approached, many legislators in three ally nations tweeted about the U.S.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":920,"file":"2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png","filesize":94867,"sizes":{"thumbnail":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=150,150","width":150,"height":150,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=150&h=150&crop=1"},"medium":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=274,300","width":274,"height":300,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=274"},"medium_large":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=768,841","width":768,"height":841,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=640"},"A1":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=564,317","width":564,"height":317,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,634","width":840,"height":634,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=690,388","width":690,"height":388,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,776","width":840,"height":776,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=776&crop=1"},"A2":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=268,151","width":268,"height":151,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=536,302","width":536,"height":302,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=690,388","width":690,"height":388,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,776","width":840,"height":776,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=776&crop=1"},"A3":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=194,110","width":194,"height":110,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=388,220","width":388,"height":220,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=148,84","width":148,"height":84,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=296,168","width":296,"height":168,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=296&h=168&crop=1"},"A4":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=268,151","width":268,"height":151,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=536,302","width":536,"height":302,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=690,388","width":690,"height":388,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,776","width":840,"height":776,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=776&crop=1"},"XL":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=720,405","width":720,"height":405,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,810","width":840,"height":810,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=810&crop=1"},"social":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=840,628","width":840,"height":628,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=840&h=628&crop=1"},"chapter":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=370,405","width":370,"height":405,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=370"},"200-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=200,219","width":200,"height":219,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=200"},"260-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=260,285","width":260,"height":285,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=260"},"310-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=310,340","width":310,"height":340,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=310"},"420-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=420,460","width":420,"height":460,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=420"},"640-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=640,701","width":640,"height":701,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=640"},"740-wide":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=740,810","width":740,"height":810,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=740"},"75-square":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=75,75","width":75,"height":75,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=75&h=75&crop=1"},"140-square":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=140,140","width":140,"height":140,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=140&h=140&crop=1"},"260-square":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=260,260","width":260,"height":260,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=160,175","width":160,"height":175,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=160"},"320-portrait":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=320,350","width":320,"height":350,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=320"},"200-by-133":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=200,133","width":200,"height":133,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=740,416","width":740,"height":416,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PG_2021.01.13_Global-Legislators_0-07.png?resize=540,304","width":540,"height":304,"filesize":94867,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png?w=540&h=304&crop=1"},"full":{"file":"PG_2021.01.13_Global-Legislators_0-07.png","width":840,"height":920,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ecece5","has_transparency":false},"post":28217,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PG_2021.01.13_Global-Legislators_0-07.png","filename":"PG_2021.01.13_Global-Legislators_0-07.png","filesize":94867,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/35588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/578"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=35588"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":28217,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/28217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}