{"id":35353,"date":"2021-09-13T15:02:55","date_gmt":"2021-09-13T20:02:55","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png"},"modified":"2021-09-13T15:02:55","modified_gmt":"2021-09-13T20:02:55","slug":"pg_2021-09-14_climate_0-24-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/09\/14\/in-response-to-climate-change-citizens-in-advanced-economies-are-willing-to-alter-how-they-live-and-work\/pg_2021-09-14_climate_0-24-png\/","title":{"rendered":"Advanced economies disapprove of how China is handling global climate change"},"author":578,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-35353","attachment","type-attachment","status-inherit","hentry"],"filename":"PG_2021.09.14_Climate_0-24.png","filesize":154929,"_embeds":[],"table_of_contents":[{"id":28123,"title":"In Response to Climate Change, Citizens in Advanced Economies Are Willing To Alter How They Live and Work","slug":"in-response-to-climate-change-citizens-in-advanced-economies-are-willing-to-alter-how-they-live-and-work","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/09\/14\/in-response-to-climate-change-citizens-in-advanced-economies-are-willing-to-alter-how-they-live-and-work\/","is_active":false},{"id":28135,"title":"Acknowledgments","slug":"climate-change-spring-2021-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/09\/14\/climate-change-spring-2021-acknowledgments\/","is_active":false},{"id":28144,"title":"Methodology","slug":"climate-change-spring-2021-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2021\/09\/14\/climate-change-spring-2021-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=212\" class=\"attachment-medium size-medium not-transparent\" alt=\"Advanced economies disapprove of how China is handling global climate change\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=212,300 212w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=768,1084 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=725,1024 725w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=287,405 287w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=200,282 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=260,367 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=310,438 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=420,593 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=640,904 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=740,1045 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=160,226 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?resize=320,452 320w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" data-has-transparency=\"false\" data-dominant-color=\"d7dde3\" style=\"--dominant-color: #d7dde3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Advanced economies disapprove of how China is handling global climate change","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1186,"file":"2021\/09\/PG_2021.09.14_Climate_0-24.png","filesize":154929,"sizes":{"thumbnail":{"file":"PG_2021.09.14_Climate_0-24.png?resize=150,150","width":150,"height":150,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=150&h=150&crop=1"},"medium":{"file":"PG_2021.09.14_Climate_0-24.png?resize=212,300","width":212,"height":300,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=212"},"medium_large":{"file":"PG_2021.09.14_Climate_0-24.png?resize=768,1084","width":768,"height":1084,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=640"},"large":{"file":"PG_2021.09.14_Climate_0-24.png?resize=725,1024","width":725,"height":1024,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=640"},"A1":{"file":"PG_2021.09.14_Climate_0-24.png?resize=564,317","width":564,"height":317,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,634","width":840,"height":634,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PG_2021.09.14_Climate_0-24.png?resize=690,388","width":690,"height":388,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,776","width":840,"height":776,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=776&crop=1"},"A2":{"file":"PG_2021.09.14_Climate_0-24.png?resize=268,151","width":268,"height":151,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=536,302","width":536,"height":302,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PG_2021.09.14_Climate_0-24.png?resize=690,388","width":690,"height":388,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,776","width":840,"height":776,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=776&crop=1"},"A3":{"file":"PG_2021.09.14_Climate_0-24.png?resize=194,110","width":194,"height":110,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=388,220","width":388,"height":220,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PG_2021.09.14_Climate_0-24.png?resize=148,84","width":148,"height":84,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=296,168","width":296,"height":168,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=296&h=168&crop=1"},"A4":{"file":"PG_2021.09.14_Climate_0-24.png?resize=268,151","width":268,"height":151,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=536,302","width":536,"height":302,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PG_2021.09.14_Climate_0-24.png?resize=690,388","width":690,"height":388,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,776","width":840,"height":776,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=776&crop=1"},"XL":{"file":"PG_2021.09.14_Climate_0-24.png?resize=720,405","width":720,"height":405,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,810","width":840,"height":810,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=810&crop=1"},"social":{"file":"PG_2021.09.14_Climate_0-24.png?resize=840,628","width":840,"height":628,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=840&h=628&crop=1"},"chapter":{"file":"PG_2021.09.14_Climate_0-24.png?resize=287,405","width":287,"height":405,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=287"},"200-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=200,282","width":200,"height":282,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=200"},"260-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=260,367","width":260,"height":367,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=260"},"310-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=310,438","width":310,"height":438,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=310"},"420-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=420,593","width":420,"height":593,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=420"},"640-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=640,904","width":640,"height":904,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=640"},"740-wide":{"file":"PG_2021.09.14_Climate_0-24.png?resize=740,1045","width":740,"height":1045,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=740"},"75-square":{"file":"PG_2021.09.14_Climate_0-24.png?resize=75,75","width":75,"height":75,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=75&h=75&crop=1"},"140-square":{"file":"PG_2021.09.14_Climate_0-24.png?resize=140,140","width":140,"height":140,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=140&h=140&crop=1"},"260-square":{"file":"PG_2021.09.14_Climate_0-24.png?resize=260,260","width":260,"height":260,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PG_2021.09.14_Climate_0-24.png?resize=160,226","width":160,"height":226,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=160"},"320-portrait":{"file":"PG_2021.09.14_Climate_0-24.png?resize=320,452","width":320,"height":452,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=320"},"200-by-133":{"file":"PG_2021.09.14_Climate_0-24.png?resize=200,133","width":200,"height":133,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PG_2021.09.14_Climate_0-24.png?resize=740,416","width":740,"height":416,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PG_2021.09.14_Climate_0-24.png?resize=540,304","width":540,"height":304,"filesize":154929,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png?w=540&h=304&crop=1"},"full":{"file":"PG_2021.09.14_Climate_0-24.png","width":840,"height":1186,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d7dde3","has_transparency":false},"post":28123,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PG_2021.09.14_Climate_0-24.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Advanced economies disapprove of how China is handling global climate change","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/35353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/578"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=35353"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":28123,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/28123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}