{"id":34819,"date":"2023-07-07T14:43:10","date_gmt":"2023-07-07T19:43:10","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png"},"modified":"2023-07-07T14:43:10","modified_gmt":"2023-07-07T19:43:10","slug":"gap_2023-07-10_russia-nato_m-06-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2023\/07\/10\/spring-2023-russia-nato-ukraine-methodology\/gap_2023-07-10_russia-nato_m-06-png\/","title":{"rendered":"Cumulative response rate as of ATP Wave 124"},"author":578,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-34819","attachment","type-attachment","status-inherit","hentry"],"filename":"gap_2023.07.10_russia-nato_M-06.png","filesize":123791,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"151\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Table showing cumulative response rate as of ATP Wave 124\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=300,151 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=768,386 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=806,405 806w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=200,100 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=260,131 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=310,156 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=420,211 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=640,322 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=740,372 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=160,80 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?resize=320,161 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"eeeeee\" style=\"--dominant-color: #eeeeee;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Table showing cumulative response rate as of ATP Wave 124","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":422,"file":"2023\/07\/gap_2023.07.10_russia-nato_M-06.png","filesize":123791,"sizes":{"thumbnail":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=150,150","width":150,"height":150,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=150&h=150&crop=1"},"medium":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=300,151","width":300,"height":151,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=300"},"medium_large":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=768,386","width":768,"height":386,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=640"},"A1":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=564,317","width":564,"height":317,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=690,388","width":690,"height":388,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=690&h=388&crop=1"},"A2":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=268,151","width":268,"height":151,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=536,302","width":536,"height":302,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=690,388","width":690,"height":388,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=690&h=388&crop=1"},"A3":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=194,110","width":194,"height":110,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=388,220","width":388,"height":220,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=148,84","width":148,"height":84,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=296,168","width":296,"height":168,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=296&h=168&crop=1"},"A4":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=268,151","width":268,"height":151,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=536,302","width":536,"height":302,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=690,388","width":690,"height":388,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=690&h=388&crop=1"},"XL":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=720,405","width":720,"height":405,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=720&h=405&crop=1"},"chapter":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=806,405","width":806,"height":405,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=806"},"200-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=200,100","width":200,"height":100,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=200"},"260-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=260,131","width":260,"height":131,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=260"},"310-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=310,156","width":310,"height":156,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=310"},"420-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=420,211","width":420,"height":211,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=420"},"640-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=640,322","width":640,"height":322,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=640"},"740-wide":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=740,372","width":740,"height":372,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=740"},"75-square":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=75,75","width":75,"height":75,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=75&h=75&crop=1"},"140-square":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=140,140","width":140,"height":140,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=140&h=140&crop=1"},"260-square":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=260,260","width":260,"height":260,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=260&h=260&crop=1"},"160-portrait":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=160,80","width":160,"height":80,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=160"},"320-portrait":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=320,161","width":320,"height":161,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=320"},"200-by-133":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=200,133","width":200,"height":133,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=200&h=133&crop=1"},"740-by-416":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=740,416","width":740,"height":416,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=740&h=416&crop=1"},"540-by-304":{"file":"gap_2023.07.10_russia-nato_M-06.png?resize=540,304","width":540,"height":304,"filesize":123791,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png?w=540&h=304&crop=1"},"full":{"file":"gap_2023.07.10_russia-nato_M-06.png","width":840,"height":422,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eeeeee","has_transparency":false},"post":27929,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/07\/gap_2023.07.10_russia-nato_M-06.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Cumulative response rate as of ATP Wave 124","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/34819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/578"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=34819"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":27929,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/27929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}