{"id":319942,"date":"2026-06-22T08:49:00","date_gmt":"2026-06-22T12:49:00","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png"},"modified":"2026-06-22T08:59:14","modified_gmt":"2026-06-22T12:59:14","slug":"pg_2026-06-22_us-image-2026_a_a_05","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2026\/06\/23\/appendix-a-detailed-tables-us-image-2026\/pg_2026-06-22_us-image-2026_a_a_05\/","title":{"rendered":"Opinions of Trump\u2019s foreign policies in 36 countries around the world"},"author":648,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-319942","attachment","type-attachment","status-inherit","hentry"],"filename":"pg_2026.06.22_us-image-2026_a_a_05.png","filesize":820750,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png'><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=220\" class=\"attachment-medium size-medium not-transparent\" alt=\"A table showing Opinions of Trump\u2019s foreign policies in 36 countries around the world\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=220,300 220w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=768,1046 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=752,1024 752w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=1127,1536 1127w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=297,405 297w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=200,273 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=260,354 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=310,422 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=420,572 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=640,872 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=740,1008 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=160,218 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?resize=320,436 320w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" data-has-transparency=\"false\" data-dominant-color=\"f5f5f5\" style=\"--dominant-color: #f5f5f5;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A table showing Opinions of Trump\u2019s foreign policies in 36 countries around the world","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":1744,"file":"2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png","filesize":820750,"sizes":{"thumbnail":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=150,150","width":150,"height":150,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=150&h=150&crop=1"},"medium":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=220,300","width":220,"height":300,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=220"},"medium_large":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=768,1046","width":768,"height":1046,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=640"},"large":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=752,1024","width":752,"height":1024,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=640"},"1536x1536":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1127,1536","width":1127,"height":1536,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1127"},"A1":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=564,317","width":564,"height":317,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1128,634","width":1128,"height":634,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=690,388","width":690,"height":388,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1280,776","width":1280,"height":776,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1280&h=776&crop=1"},"A2":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=268,151","width":268,"height":151,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=536,302","width":536,"height":302,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=690,388","width":690,"height":388,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1280,776","width":1280,"height":776,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1280&h=776&crop=1"},"A3":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=194,110","width":194,"height":110,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=388,220","width":388,"height":220,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=148,84","width":148,"height":84,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=296,168","width":296,"height":168,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=296&h=168&crop=1"},"A4":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=268,151","width":268,"height":151,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=536,302","width":536,"height":302,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=690,388","width":690,"height":388,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1280,776","width":1280,"height":776,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1280&h=776&crop=1"},"XL":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=720,405","width":720,"height":405,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1280,810","width":1280,"height":810,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1280&h=810&crop=1"},"social":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=1200,628","width":1200,"height":628,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=1200&h=628&crop=1"},"chapter":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=297,405","width":297,"height":405,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=297"},"200-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=200,273","width":200,"height":273,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=200"},"260-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=260,354","width":260,"height":354,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=260"},"310-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=310,422","width":310,"height":422,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=310"},"420-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=420,572","width":420,"height":572,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=420"},"640-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=640,872","width":640,"height":872,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=640"},"740-wide":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=740,1008","width":740,"height":1008,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=740"},"75-square":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=75,75","width":75,"height":75,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=75&h=75&crop=1"},"140-square":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=140,140","width":140,"height":140,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=140&h=140&crop=1"},"260-square":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=260,260","width":260,"height":260,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=260&h=260&crop=1"},"160-portrait":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=160,218","width":160,"height":218,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=160"},"320-portrait":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=320,436","width":320,"height":436,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=320"},"200-by-133":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=200,133","width":200,"height":133,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=200&h=133&crop=1"},"740-by-416":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=740,416","width":740,"height":416,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=740&h=416&crop=1"},"540-by-304":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png?resize=540,304","width":540,"height":304,"filesize":820750,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png?w=540&h=304&crop=1"},"full":{"file":"pg_2026.06.22_us-image-2026_a_a_05.png","width":1200,"height":1635,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[],"alt":""},"dominant_color":"f5f5f5","has_transparency":false},"post":319117,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/06\/pg_2026.06.22_us-image-2026_a_a_05.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Opinions of Trump\u2019s foreign policies in 36 countries around the world","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/319942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=319942"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":319117,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/319117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}