{"id":290302,"date":"2026-03-02T13:37:35","date_gmt":"2026-03-02T18:37:35","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png"},"modified":"2026-03-02T13:37:35","modified_gmt":"2026-03-02T18:37:35","slug":"1moralitybeliefgod420px2x-9","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/chart\/americans-have-become-less-likely-to-say-belief-in-god-is-needed-to-be-moral\/1moralitybeliefgod420px2x-9\/","title":{"rendered":"1moralityBeliefGod420px@2x"},"author":174,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-290302","attachment","type-attachment","status-inherit","hentry"],"filename":"1moralityBeliefGod420px@2x_bdcc31.png","filesize":48131,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=300,221 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=768,567 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=549,405 549w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=200,148 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=260,192 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=310,229 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=420,310 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=640,472 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=740,546 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=160,118 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?resize=320,236 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"f7f9f8\" style=\"--dominant-color: #f7f9f8;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":620,"file":"2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png","filesize":48131,"sizes":{"thumbnail":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=150,150","width":150,"height":150,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=150&h=150&crop=1"},"medium":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=300,221","width":300,"height":221,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=300"},"medium_large":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=768,567","width":768,"height":567,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=640"},"A1":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=564,317","width":564,"height":317,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=690,388","width":690,"height":388,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=690&h=388&crop=1"},"A2":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=268,151","width":268,"height":151,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=536,302","width":536,"height":302,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=690,388","width":690,"height":388,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=690&h=388&crop=1"},"A3":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=194,110","width":194,"height":110,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=388,220","width":388,"height":220,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=148,84","width":148,"height":84,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=296,168","width":296,"height":168,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=296&h=168&crop=1"},"A4":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=268,151","width":268,"height":151,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=536,302","width":536,"height":302,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=690,388","width":690,"height":388,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=690&h=388&crop=1"},"XL":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=720,405","width":720,"height":405,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=720&h=405&crop=1"},"chapter":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=549,405","width":549,"height":405,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=549"},"200-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=200,148","width":200,"height":148,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=200"},"260-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=260,192","width":260,"height":192,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=260"},"310-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=310,229","width":310,"height":229,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=310"},"420-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=420,310","width":420,"height":310,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=420"},"640-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=640,472","width":640,"height":472,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=640"},"740-wide":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=740,546","width":740,"height":546,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=740"},"75-square":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=75,75","width":75,"height":75,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=75&h=75&crop=1"},"140-square":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=140,140","width":140,"height":140,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=140&h=140&crop=1"},"260-square":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=260,260","width":260,"height":260,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=260&h=260&crop=1"},"160-portrait":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=160,118","width":160,"height":118,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=160"},"320-portrait":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=320,236","width":320,"height":236,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=320"},"200-by-133":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=200,133","width":200,"height":133,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=200&h=133&crop=1"},"740-by-416":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=740,416","width":740,"height":416,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=740&h=416&crop=1"},"540-by-304":{"file":"1moralityBeliefGod420px@2x_bdcc31.png?resize=540,304","width":540,"height":304,"filesize":48131,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png?w=540&h=304&crop=1"},"full":{"file":"1moralityBeliefGod420px@2x_bdcc31.png","width":840,"height":620,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f7f9f8","has_transparency":false},"post":290150,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2026\/03\/1moralityBeliefGod420px@2x_bdcc31.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"1moralityBeliefGod420px@2x","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/290302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=290302"}],"wp:attached-to":[{"embeddable":true,"post_type":"chart","id":290150,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/chart\/290150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}