{"id":278936,"date":"2025-11-10T07:54:03","date_gmt":"2025-11-10T12:54:03","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png"},"modified":"2025-11-13T13:29:02","modified_gmt":"2025-11-13T18:29:02","slug":"sr_25-11-10_100-people_1","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2025\/11\/13\/if-the-u-s-had-100-people-charting-americans-religious-affiliations\/sr_25-11-10_100-people_1\/","title":{"rendered":"The U.S. as 100 people: 62 Christians, 29 religious \u2018nones,\u2019 2 Jews and 1 Muslim"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-278936","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_25.11.10_100-people_1.png","filesize":822860,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png'><img loading=\"lazy\" decoding=\"async\" width=\"172\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=172\" class=\"attachment-medium size-medium not-transparent\" alt=\"A chart showing the U.S. as 100 people: 62 Christians, 29 religious \u2018nones,\u2019 2 Jews and 1 Muslim.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=172,300 172w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=768,1342 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=586,1024 586w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=232,405 232w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=200,350 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=260,454 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=310,542 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=420,734 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=640,1118 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=740,1293 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=160,280 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?resize=320,559 320w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" data-has-transparency=\"false\" data-dominant-color=\"f2f0f0\" style=\"--dominant-color: #f2f0f0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A chart showing the U.S. as 100 people: 62 Christians, 29 religious \u2018nones,\u2019 2 Jews and 1 Muslim.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1468,"file":"2025\/11\/SR_25.11.10_100-people_1.png","filesize":822860,"sizes":{"thumbnail":{"file":"SR_25.11.10_100-people_1.png?resize=150,150","width":150,"height":150,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=150&h=150&crop=1"},"medium":{"file":"SR_25.11.10_100-people_1.png?resize=172,300","width":172,"height":300,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=172"},"medium_large":{"file":"SR_25.11.10_100-people_1.png?resize=768,1342","width":768,"height":1342,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=640"},"large":{"file":"SR_25.11.10_100-people_1.png?resize=586,1024","width":586,"height":1024,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=586"},"A1":{"file":"SR_25.11.10_100-people_1.png?resize=564,317","width":564,"height":317,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=840,634","width":840,"height":634,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_25.11.10_100-people_1.png?resize=690,388","width":690,"height":388,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=840,776","width":840,"height":776,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=776&crop=1"},"A2":{"file":"SR_25.11.10_100-people_1.png?resize=268,151","width":268,"height":151,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=536,302","width":536,"height":302,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_25.11.10_100-people_1.png?resize=690,388","width":690,"height":388,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=840,776","width":840,"height":776,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=776&crop=1"},"A3":{"file":"SR_25.11.10_100-people_1.png?resize=194,110","width":194,"height":110,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=388,220","width":388,"height":220,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_25.11.10_100-people_1.png?resize=148,84","width":148,"height":84,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=296,168","width":296,"height":168,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=296&h=168&crop=1"},"A4":{"file":"SR_25.11.10_100-people_1.png?resize=268,151","width":268,"height":151,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=536,302","width":536,"height":302,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_25.11.10_100-people_1.png?resize=690,388","width":690,"height":388,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=840,776","width":840,"height":776,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=776&crop=1"},"XL":{"file":"SR_25.11.10_100-people_1.png?resize=720,405","width":720,"height":405,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_25.11.10_100-people_1.png?resize=840,810","width":840,"height":810,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=810&crop=1"},"social":{"file":"SR_25.11.10_100-people_1.png?resize=840,628","width":840,"height":628,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_25.11.10_100-people_1.png?resize=232,405","width":232,"height":405,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=232"},"200-wide":{"file":"SR_25.11.10_100-people_1.png?resize=200,350","width":200,"height":350,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=200"},"260-wide":{"file":"SR_25.11.10_100-people_1.png?resize=260,454","width":260,"height":454,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=260"},"310-wide":{"file":"SR_25.11.10_100-people_1.png?resize=310,542","width":310,"height":542,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=310"},"420-wide":{"file":"SR_25.11.10_100-people_1.png?resize=420,734","width":420,"height":734,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=420"},"640-wide":{"file":"SR_25.11.10_100-people_1.png?resize=640,1118","width":640,"height":1118,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=640"},"740-wide":{"file":"SR_25.11.10_100-people_1.png?resize=740,1293","width":740,"height":1293,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=740"},"75-square":{"file":"SR_25.11.10_100-people_1.png?resize=75,75","width":75,"height":75,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_25.11.10_100-people_1.png?resize=140,140","width":140,"height":140,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_25.11.10_100-people_1.png?resize=260,260","width":260,"height":260,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_25.11.10_100-people_1.png?resize=160,280","width":160,"height":280,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=160"},"320-portrait":{"file":"SR_25.11.10_100-people_1.png?resize=320,559","width":320,"height":559,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=320"},"200-by-133":{"file":"SR_25.11.10_100-people_1.png?resize=200,133","width":200,"height":133,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_25.11.10_100-people_1.png?resize=740,416","width":740,"height":416,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_25.11.10_100-people_1.png?resize=540,304","width":540,"height":304,"filesize":822860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png?w=540&h=304&crop=1"},"full":{"file":"SR_25.11.10_100-people_1.png","width":840,"height":1468,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f2f0f0","has_transparency":false},"post":12336,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/11\/SR_25.11.10_100-people_1.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"The U.S. as 100 people: 62 Christians, 29 religious \u2018nones,\u2019 2 Jews and 1 Muslim","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/278936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=278936"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":12336,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/12336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}