{"id":270119,"date":"2025-07-15T11:37:04","date_gmt":"2025-07-15T15:37:04","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png"},"modified":"2025-07-15T12:27:09","modified_gmt":"2025-07-15T16:27:09","slug":"sr_25-07-16_cellphone-ban_5","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2025\/07\/16\/americans-support-for-school-cellphone-bans-has-ticked-up-since-last-year\/sr_25-07-16_cellphone-ban_5\/","title":{"rendered":"Younger adults and Black adults are the most worried that cellphone regulations in schools will go too far"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-270119","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png'><img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=268\" class=\"attachment-medium size-medium not-transparent\" alt=\"A diverging bar chart showing that younger adults and Black adults are the most worried that cellphone regulations in schools will go too far.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=268,300 268w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=768,859 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=362,405 362w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=200,224 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=260,291 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=310,347 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=420,470 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=640,716 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=740,828 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=160,179 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?resize=320,358 320w\" sizes=\"auto, (max-width: 268px) 100vw, 268px\" data-has-transparency=\"false\" data-dominant-color=\"e0e3e0\" style=\"--dominant-color: #e0e3e0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A diverging bar chart showing that younger adults and Black adults are the most worried that cellphone regulations in schools will go too far.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":940,"file":"2025\/07\/SR_25.07.16_cellphone-ban_5.png","filesize":404252,"sizes":{"thumbnail":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=150,150","width":150,"height":150,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=150&h=150&crop=1"},"medium":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=268,300","width":268,"height":300,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=268"},"medium_large":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=768,859","width":768,"height":859,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=640"},"A1":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=564,317","width":564,"height":317,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,634","width":840,"height":634,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=690,388","width":690,"height":388,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,776","width":840,"height":776,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=776&crop=1"},"A2":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=268,151","width":268,"height":151,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=536,302","width":536,"height":302,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=690,388","width":690,"height":388,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,776","width":840,"height":776,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=776&crop=1"},"A3":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=194,110","width":194,"height":110,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=388,220","width":388,"height":220,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=148,84","width":148,"height":84,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=296,168","width":296,"height":168,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=296&h=168&crop=1"},"A4":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=268,151","width":268,"height":151,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=536,302","width":536,"height":302,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=690,388","width":690,"height":388,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,776","width":840,"height":776,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=776&crop=1"},"XL":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=720,405","width":720,"height":405,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,810","width":840,"height":810,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=810&crop=1"},"social":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=840,628","width":840,"height":628,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=362,405","width":362,"height":405,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=362"},"200-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=200,224","width":200,"height":224,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=200"},"260-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=260,291","width":260,"height":291,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=260"},"310-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=310,347","width":310,"height":347,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=310"},"420-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=420,470","width":420,"height":470,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=420"},"640-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=640,716","width":640,"height":716,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=640"},"740-wide":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=740,828","width":740,"height":828,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=740"},"75-square":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=75,75","width":75,"height":75,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=140,140","width":140,"height":140,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=260,260","width":260,"height":260,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=160,179","width":160,"height":179,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=160"},"320-portrait":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=320,358","width":320,"height":358,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=320"},"200-by-133":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=200,133","width":200,"height":133,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=740,416","width":740,"height":416,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_25.07.16_cellphone-ban_5.png?resize=540,304","width":540,"height":304,"filesize":404252,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png?w=540&h=304&crop=1"},"full":{"file":"SR_25.07.16_cellphone-ban_5.png","width":840,"height":940,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e0e3e0","has_transparency":false},"post":270113,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/SR_25.07.16_cellphone-ban_5.png","filename":"SR_25.07.16_cellphone-ban_5.png","filesize":404252,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/270119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=270119"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":270113,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/270113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}