{"id":269963,"date":"2025-07-14T13:16:57","date_gmt":"2025-07-14T17:16:57","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png"},"modified":"2025-07-14T13:21:20","modified_gmt":"2025-07-14T17:21:20","slug":"pg_2025-07-15_global-views-china-2025_0_03","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/international-views-of-china-turn-slightly-more-positive\/pg_2025-07-15_global-views-china-2025_0_03\/","title":{"rendered":"In most countries surveyed, people prioritize economic ties with the U.S. over China"},"author":648,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-269963","attachment","type-attachment","status-inherit","hentry"],"filename":"pg_2025.07.15_global-views-china-2025_0_03.png","filesize":567925,"_embeds":[],"table_of_contents":[{"id":269886,"title":"International Views of China Turn Slightly More Positive","slug":"international-views-of-china-turn-slightly-more-positive","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/international-views-of-china-turn-slightly-more-positive\/","is_active":false},{"id":269894,"title":"1.\u00a0\u00a0Views of China and Xi Jinping","slug":"views-of-china-and-xi-jinping-2025","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/views-of-china-and-xi-jinping-2025\/","is_active":false},{"id":269898,"title":"2. China\u2019s economic power and economic relations","slug":"chinas-economic-power-and-economic-relations","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/chinas-economic-power-and-economic-relations\/","is_active":false},{"id":269901,"title":"3. Views of China in middle-income countries","slug":"views-of-china-in-middle-income-countries","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/views-of-china-in-middle-income-countries\/","is_active":false},{"id":269906,"title":"4. Where China is seen as an ally or threat","slug":"where-china-is-seen-as-an-ally-or-threat","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/where-china-is-seen-as-an-ally-or-threat\/","is_active":false},{"id":269911,"title":"Appendix A: Global Attitudes Survey fieldwork timeline","slug":"appendix-a-global-attitudes-survey-fieldwork-timeline-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/appendix-a-global-attitudes-survey-fieldwork-timeline-2\/","is_active":false},{"id":269916,"title":"Appendix B: How people in middle-income countries see bilateral issues with the U.S. and China (detailed tables)","slug":"appendix-b-how-people-in-middle-income-countries-see-bilateral-issues-with-the-u-s-and-china-detailed-tables","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/appendix-b-how-people-in-middle-income-countries-see-bilateral-issues-with-the-u-s-and-china-detailed-tables\/","is_active":false},{"id":269923,"title":"Acknowledgments","slug":"acknowledgments-global-views-china-2025","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/acknowledgments-global-views-china-2025\/","is_active":false},{"id":269920,"title":"Methodology","slug":"methodology-global-views-china-2025","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/global\/2025\/07\/15\/methodology-global-views-china-2025\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png'><img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=159\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that In most countries surveyed, people prioritize economic ties with the U.S. over China\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=159,300 159w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=768,1452 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=542,1024 542w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=812,1536 812w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=214,405 214w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=200,378 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=260,492 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=310,586 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=420,794 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=640,1210 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=740,1399 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=160,302 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?resize=320,605 320w\" sizes=\"auto, (max-width: 159px) 100vw, 159px\" data-has-transparency=\"false\" data-dominant-color=\"b9c5b2\" style=\"--dominant-color: #b9c5b2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that In most countries surveyed, people prioritize economic ties with the U.S. over China","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1588,"file":"2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png","filesize":567925,"sizes":{"thumbnail":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=150,150","width":150,"height":150,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=150&h=150&crop=1"},"medium":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=159,300","width":159,"height":300,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=159"},"medium_large":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=768,1452","width":768,"height":1452,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=640"},"large":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=542,1024","width":542,"height":1024,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=542"},"1536x1536":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=812,1536","width":812,"height":1536,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=812"},"A1":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=564,317","width":564,"height":317,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,634","width":840,"height":634,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=690,388","width":690,"height":388,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,776","width":840,"height":776,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=776&crop=1"},"A2":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=268,151","width":268,"height":151,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=536,302","width":536,"height":302,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=690,388","width":690,"height":388,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,776","width":840,"height":776,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=776&crop=1"},"A3":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=194,110","width":194,"height":110,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=388,220","width":388,"height":220,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=148,84","width":148,"height":84,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=296,168","width":296,"height":168,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=296&h=168&crop=1"},"A4":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=268,151","width":268,"height":151,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=536,302","width":536,"height":302,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=690,388","width":690,"height":388,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,776","width":840,"height":776,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=776&crop=1"},"XL":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=720,405","width":720,"height":405,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,810","width":840,"height":810,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=810&crop=1"},"social":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=840,628","width":840,"height":628,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=840&h=628&crop=1"},"chapter":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=214,405","width":214,"height":405,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=214"},"200-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=200,378","width":200,"height":378,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=200"},"260-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=260,492","width":260,"height":492,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=260"},"310-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=310,586","width":310,"height":586,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=310"},"420-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=420,794","width":420,"height":794,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=420"},"640-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=640,1210","width":640,"height":1210,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=640"},"740-wide":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=740,1399","width":740,"height":1399,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=740"},"75-square":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=75,75","width":75,"height":75,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=75&h=75&crop=1"},"140-square":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=140,140","width":140,"height":140,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=140&h=140&crop=1"},"260-square":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=260,260","width":260,"height":260,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=160,302","width":160,"height":302,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=160"},"320-portrait":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=320,605","width":320,"height":605,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=320"},"200-by-133":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=200,133","width":200,"height":133,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=740,416","width":740,"height":416,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=740&h=416&crop=1"},"540-by-304":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png?resize=540,304","width":540,"height":304,"filesize":567925,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png?w=540&h=304&crop=1"},"full":{"file":"pg_2025.07.15_global-views-china-2025_0_03.png","width":840,"height":1588,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"b9c5b2","has_transparency":false},"post":269886,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/07\/pg_2025.07.15_global-views-china-2025_0_03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"In most countries surveyed, people prioritize economic ties with the U.S. over China","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/269963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=269963"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":269886,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/269886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}