{"id":269176,"date":"2025-06-30T09:15:57","date_gmt":"2025-06-30T13:15:57","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png"},"modified":"2025-06-30T09:19:55","modified_gmt":"2025-06-30T13:19:55","slug":"sr_25-06-30_satisfaction-with-democracy_1","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2025\/06\/30\/dissatisfaction-with-democracy-remains-widespread-in-many-nations\/sr_25-06-30_satisfaction-with-democracy_1\/","title":{"rendered":"Dissatisfaction with democracy far outweighs satisfaction across 12 countries surveyed since 2017"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-269176","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_25.06.30_satisfaction-with-democracy_1.png","filesize":221194,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png'><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=259\" class=\"attachment-medium size-medium not-transparent\" alt=\"A line chart showing that dissatisfaction with democracy far outweighs satisfaction across 12 countries surveyed since 2017.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=259,300 259w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=768,889 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=350,405 350w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=200,231 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=260,301 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=310,359 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=420,486 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=640,741 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=740,856 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=160,185 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?resize=320,370 320w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" data-has-transparency=\"false\" data-dominant-color=\"f2f3f2\" style=\"--dominant-color: #f2f3f2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A line chart showing that dissatisfaction with democracy far outweighs satisfaction across 12 countries surveyed since 2017.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":972,"file":"2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png","filesize":221194,"sizes":{"thumbnail":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=150,150","width":150,"height":150,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=150&h=150&crop=1"},"medium":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=259,300","width":259,"height":300,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=259"},"medium_large":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=768,889","width":768,"height":889,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=640"},"A1":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=564,317","width":564,"height":317,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,634","width":840,"height":634,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=690,388","width":690,"height":388,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,776","width":840,"height":776,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=776&crop=1"},"A2":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=268,151","width":268,"height":151,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=536,302","width":536,"height":302,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=690,388","width":690,"height":388,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,776","width":840,"height":776,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=776&crop=1"},"A3":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=194,110","width":194,"height":110,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=388,220","width":388,"height":220,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=148,84","width":148,"height":84,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=296,168","width":296,"height":168,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=296&h=168&crop=1"},"A4":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=268,151","width":268,"height":151,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=536,302","width":536,"height":302,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=690,388","width":690,"height":388,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,776","width":840,"height":776,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=776&crop=1"},"XL":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=720,405","width":720,"height":405,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,810","width":840,"height":810,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=810&crop=1"},"social":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=840,628","width":840,"height":628,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=350,405","width":350,"height":405,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=350"},"200-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=200,231","width":200,"height":231,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=200"},"260-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=260,301","width":260,"height":301,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=260"},"310-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=310,359","width":310,"height":359,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=310"},"420-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=420,486","width":420,"height":486,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=420"},"640-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=640,741","width":640,"height":741,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=640"},"740-wide":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=740,856","width":740,"height":856,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=740"},"75-square":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=75,75","width":75,"height":75,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=140,140","width":140,"height":140,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=260,260","width":260,"height":260,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=160,185","width":160,"height":185,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=160"},"320-portrait":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=320,370","width":320,"height":370,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=320"},"200-by-133":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=200,133","width":200,"height":133,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=740,416","width":740,"height":416,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png?resize=540,304","width":540,"height":304,"filesize":221194,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png?w=540&h=304&crop=1"},"full":{"file":"SR_25.06.30_satisfaction-with-democracy_1.png","width":840,"height":972,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f2f3f2","has_transparency":false},"post":269172,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.30_satisfaction-with-democracy_1.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Dissatisfaction with democracy far outweighs satisfaction across 12 countries surveyed since 2017","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/269176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=269176"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":269172,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/269172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}