{"id":262147,"date":"2025-06-11T15:52:25","date_gmt":"2025-06-11T19:52:25","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png"},"modified":"2025-06-11T15:56:55","modified_gmt":"2025-06-11T19:56:55","slug":"sr_25-06-12_health-topics_3","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2025\/06\/12\/from-weight-loss-drugs-to-raw-milk-americans-hear-more-often-about-some-health-topics-than-others\/sr_25-06-12_health-topics_3\/","title":{"rendered":"Younger women are just as likely as older women  to say they hear a lot about cosmetic treatments to reduce the signs of aging, like Botox"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-262147","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_25.06.12_health-topics_3.png","filesize":338831,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png'><img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=296\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that younger women are just as likely as older women to say they hear a lot about cosmetic treatments to reduce the signs of aging, like Botox.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=296,300 296w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=768,779 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=399,405 399w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=200,203 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=260,264 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=310,314 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=420,426 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=640,649 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=740,751 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=75,75 75w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=160,162 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?resize=320,325 320w\" sizes=\"auto, (max-width: 296px) 100vw, 296px\" data-has-transparency=\"false\" data-dominant-color=\"d6ddd7\" style=\"--dominant-color: #d6ddd7;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that younger women are just as likely as older women to say they hear a lot about cosmetic treatments to reduce the signs of aging, like Botox.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":852,"file":"2025\/06\/SR_25.06.12_health-topics_3.png","filesize":338831,"sizes":{"thumbnail":{"file":"SR_25.06.12_health-topics_3.png?resize=150,150","width":150,"height":150,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=150&h=150&crop=1"},"medium":{"file":"SR_25.06.12_health-topics_3.png?resize=296,300","width":296,"height":300,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=296"},"medium_large":{"file":"SR_25.06.12_health-topics_3.png?resize=768,779","width":768,"height":779,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=640"},"A1":{"file":"SR_25.06.12_health-topics_3.png?resize=564,317","width":564,"height":317,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=840,634","width":840,"height":634,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_25.06.12_health-topics_3.png?resize=690,388","width":690,"height":388,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=840,776","width":840,"height":776,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=776&crop=1"},"A2":{"file":"SR_25.06.12_health-topics_3.png?resize=268,151","width":268,"height":151,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=536,302","width":536,"height":302,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_25.06.12_health-topics_3.png?resize=690,388","width":690,"height":388,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=840,776","width":840,"height":776,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=776&crop=1"},"A3":{"file":"SR_25.06.12_health-topics_3.png?resize=194,110","width":194,"height":110,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=388,220","width":388,"height":220,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_25.06.12_health-topics_3.png?resize=148,84","width":148,"height":84,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=296,168","width":296,"height":168,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=296&h=168&crop=1"},"A4":{"file":"SR_25.06.12_health-topics_3.png?resize=268,151","width":268,"height":151,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=536,302","width":536,"height":302,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_25.06.12_health-topics_3.png?resize=690,388","width":690,"height":388,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=840,776","width":840,"height":776,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=776&crop=1"},"XL":{"file":"SR_25.06.12_health-topics_3.png?resize=720,405","width":720,"height":405,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_25.06.12_health-topics_3.png?resize=840,810","width":840,"height":810,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=810&crop=1"},"social":{"file":"SR_25.06.12_health-topics_3.png?resize=840,628","width":840,"height":628,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_25.06.12_health-topics_3.png?resize=399,405","width":399,"height":405,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=399"},"200-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=200,203","width":200,"height":203,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=200"},"260-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=260,264","width":260,"height":264,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=260"},"310-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=310,314","width":310,"height":314,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=310"},"420-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=420,426","width":420,"height":426,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=420"},"640-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=640,649","width":640,"height":649,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=640"},"740-wide":{"file":"SR_25.06.12_health-topics_3.png?resize=740,751","width":740,"height":751,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=740"},"75-square":{"file":"SR_25.06.12_health-topics_3.png?resize=75,75","width":75,"height":75,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_25.06.12_health-topics_3.png?resize=140,140","width":140,"height":140,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_25.06.12_health-topics_3.png?resize=260,260","width":260,"height":260,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_25.06.12_health-topics_3.png?resize=160,162","width":160,"height":162,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=160"},"320-portrait":{"file":"SR_25.06.12_health-topics_3.png?resize=320,325","width":320,"height":325,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=320"},"200-by-133":{"file":"SR_25.06.12_health-topics_3.png?resize=200,133","width":200,"height":133,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_25.06.12_health-topics_3.png?resize=740,416","width":740,"height":416,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_25.06.12_health-topics_3.png?resize=540,304","width":540,"height":304,"filesize":338831,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png?w=540&h=304&crop=1"},"full":{"file":"SR_25.06.12_health-topics_3.png","width":840,"height":852,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d6ddd7","has_transparency":false},"post":262145,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/SR_25.06.12_health-topics_3.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Younger women are just as likely as older women  to say they hear a lot about cosmetic treatments to reduce the signs of aging, like Botox","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/262147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=262147"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":262145,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/262145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}