{"id":261922,"date":"2025-06-10T11:41:04","date_gmt":"2025-06-10T15:41:04","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png"},"modified":"2025-06-10T11:45:35","modified_gmt":"2025-06-10T15:45:35","slug":"st_2025-6-12_lgbtq-couples_00-05","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2025\/06\/12\/rising-number-of-u-s-households-are-headed-by-married-same-sex-couples\/st_2025-6-12_lgbtq-couples_00-05\/","title":{"rendered":"Same-sex married couples with 2 men have the highest household incomes"},"author":581,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-261922","attachment","type-attachment","status-inherit","hentry"],"filename":"ST_2025.6.12_lgbtq-couples_00-05.png","filesize":155411,"_embeds":[],"table_of_contents":[{"id":261680,"title":"Rising Number of U.S. Households Are Headed by Married Same-Sex Couples","slug":"rising-number-of-u-s-households-are-headed-by-married-same-sex-couples","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2025\/06\/12\/rising-number-of-u-s-households-are-headed-by-married-same-sex-couples\/","is_active":false},{"id":261783,"title":"Acknowledgments","slug":"same-sex-couples-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2025\/06\/12\/same-sex-couples-acknowledgments\/","is_active":false},{"id":261786,"title":"Methodology","slug":"same-sex-couples-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2025\/06\/12\/same-sex-couples-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png'><img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=257\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Same-sex married couples with 2 men have the highest household incomes\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=257,300 257w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=347,405 347w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=200,234 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=260,304 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=310,362 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=420,490 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=160,187 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?resize=320,374 320w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" data-has-transparency=\"false\" data-dominant-color=\"e5e9e8\" style=\"--dominant-color: #e5e9e8;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Same-sex married couples with 2 men have the highest household incomes","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":724,"file":"2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png","filesize":155411,"sizes":{"thumbnail":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=150,150","width":150,"height":150,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=150&h=150&crop=1"},"medium":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=257,300","width":257,"height":300,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=257"},"A1":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=564,317","width":564,"height":317,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,634","width":620,"height":634,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,388","width":620,"height":388,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=388&crop=1"},"A2":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=268,151","width":268,"height":151,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=536,302","width":536,"height":302,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,388","width":620,"height":388,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=388&crop=1"},"A3":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=194,110","width":194,"height":110,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=388,220","width":388,"height":220,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=148,84","width":148,"height":84,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=296,168","width":296,"height":168,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=296&h=168&crop=1"},"A4":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=268,151","width":268,"height":151,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=536,302","width":536,"height":302,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,388","width":620,"height":388,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=388&crop=1"},"XL":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,405","width":620,"height":405,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=405&crop=1"},"social":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,628","width":620,"height":628,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=628&crop=1"},"chapter":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=347,405","width":347,"height":405,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=347"},"200-wide":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=200,234","width":200,"height":234,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=200"},"260-wide":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=260,304","width":260,"height":304,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=260"},"310-wide":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=310,362","width":310,"height":362,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=310"},"420-wide":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=420,490","width":420,"height":490,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=420"},"75-square":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=75,75","width":75,"height":75,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=75&h=75&crop=1"},"140-square":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=140,140","width":140,"height":140,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=140&h=140&crop=1"},"260-square":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=260,260","width":260,"height":260,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=260&h=260&crop=1"},"160-portrait":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=160,187","width":160,"height":187,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=160"},"320-portrait":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=320,374","width":320,"height":374,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=320"},"200-by-133":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=200,133","width":200,"height":133,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=200&h=133&crop=1"},"740-by-416":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=620,416","width":620,"height":416,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=620&h=416&crop=1"},"540-by-304":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png?resize=540,304","width":540,"height":304,"filesize":155411,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png?w=540&h=304&crop=1"},"full":{"file":"ST_2025.6.12_lgbtq-couples_00-05.png","width":620,"height":724,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e5e9e8","has_transparency":false},"post":261680,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/06\/ST_2025.6.12_lgbtq-couples_00-05.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Same-sex married couples with 2 men have the highest household incomes","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/261922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=261922"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":261680,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/261680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}