{"id":237970,"date":"2025-05-07T12:24:04","date_gmt":"2025-05-07T16:24:04","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png"},"modified":"2025-05-07T12:24:04","modified_gmt":"2025-05-07T16:24:04","slug":"sr_25-05-08_neighbors_2","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2025\/05\/08\/how-connected-do-americans-feel-to-their-neighbors\/sr_25-05-08_neighbors_2\/","title":{"rendered":"More Americans say their neighbors share their race or ethnicity than their education level or political views"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-237970","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A horizontal stacked bar chart showing that more Americans say their neighbors share their race or ethnicity than their education level or political views.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=300,208 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=768,531 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=586,405 586w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=200,138 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=260,180 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=310,214 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=420,291 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=640,443 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=740,512 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=160,111 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?resize=320,221 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"dcdfde\" style=\"--dominant-color: #dcdfde;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A horizontal stacked bar chart showing that more Americans say their neighbors share their race or ethnicity than their education level or political views.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":581,"file":"2025\/05\/SR_25.05.08_neighbors_2.png","filesize":119671,"sizes":{"thumbnail":{"file":"SR_25.05.08_neighbors_2.png?resize=150,150","width":150,"height":150,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=150&h=150&crop=1"},"medium":{"file":"SR_25.05.08_neighbors_2.png?resize=300,208","width":300,"height":208,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=300"},"medium_large":{"file":"SR_25.05.08_neighbors_2.png?resize=768,531","width":768,"height":531,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=640"},"A1":{"file":"SR_25.05.08_neighbors_2.png?resize=564,317","width":564,"height":317,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"SR_25.05.08_neighbors_2.png?resize=690,388","width":690,"height":388,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=690&h=388&crop=1"},"A2":{"file":"SR_25.05.08_neighbors_2.png?resize=268,151","width":268,"height":151,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_25.05.08_neighbors_2.png?resize=536,302","width":536,"height":302,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_25.05.08_neighbors_2.png?resize=690,388","width":690,"height":388,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=690&h=388&crop=1"},"A3":{"file":"SR_25.05.08_neighbors_2.png?resize=194,110","width":194,"height":110,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_25.05.08_neighbors_2.png?resize=388,220","width":388,"height":220,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_25.05.08_neighbors_2.png?resize=148,84","width":148,"height":84,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_25.05.08_neighbors_2.png?resize=296,168","width":296,"height":168,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=296&h=168&crop=1"},"A4":{"file":"SR_25.05.08_neighbors_2.png?resize=268,151","width":268,"height":151,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_25.05.08_neighbors_2.png?resize=536,302","width":536,"height":302,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_25.05.08_neighbors_2.png?resize=690,388","width":690,"height":388,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=690&h=388&crop=1"},"XL":{"file":"SR_25.05.08_neighbors_2.png?resize=720,405","width":720,"height":405,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=720&h=405&crop=1"},"chapter":{"file":"SR_25.05.08_neighbors_2.png?resize=586,405","width":586,"height":405,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=586"},"200-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=200,138","width":200,"height":138,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=200"},"260-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=260,180","width":260,"height":180,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=260"},"310-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=310,214","width":310,"height":214,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=310"},"420-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=420,291","width":420,"height":291,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=420"},"640-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=640,443","width":640,"height":443,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=640"},"740-wide":{"file":"SR_25.05.08_neighbors_2.png?resize=740,512","width":740,"height":512,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=740"},"75-square":{"file":"SR_25.05.08_neighbors_2.png?resize=75,75","width":75,"height":75,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_25.05.08_neighbors_2.png?resize=140,140","width":140,"height":140,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_25.05.08_neighbors_2.png?resize=260,260","width":260,"height":260,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_25.05.08_neighbors_2.png?resize=160,111","width":160,"height":111,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=160"},"320-portrait":{"file":"SR_25.05.08_neighbors_2.png?resize=320,221","width":320,"height":221,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=320"},"200-by-133":{"file":"SR_25.05.08_neighbors_2.png?resize=200,133","width":200,"height":133,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_25.05.08_neighbors_2.png?resize=740,416","width":740,"height":416,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_25.05.08_neighbors_2.png?resize=540,304","width":540,"height":304,"filesize":119671,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png?w=540&h=304&crop=1"},"full":{"file":"SR_25.05.08_neighbors_2.png","width":840,"height":581,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"dcdfde","has_transparency":false},"post":231182,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/05\/SR_25.05.08_neighbors_2.png","filename":"SR_25.05.08_neighbors_2.png","filesize":119671,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/237970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=237970"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":231182,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/231182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}