{"id":20320,"date":"2019-10-16T12:02:53","date_gmt":"2019-10-16T17:02:53","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png"},"modified":"2019-10-16T12:02:53","modified_gmt":"2019-10-16T17:02:53","slug":"ft_19-10-08_gunupdate_1-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2019\/10\/16\/share-of-americans-who-favor-stricter-gun-laws-has-increased-since-2017\/ft_19-10-08_gunupdate_1-png\/","title":{"rendered":"FT_19.10.08_GunUpdate_1"},"author":386,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-20320","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[],"datacite_doi":"","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png'><img loading=\"lazy\" decoding=\"async\" width=\"293\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=293\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=293,300 293w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=768,786 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=396,405 396w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=200,205 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=260,266 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=310,317 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=420,430 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=640,655 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=740,758 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=160,164 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?resize=320,328 320w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" data-has-transparency=\"false\" data-dominant-color=\"f3f3f3\" style=\"--dominant-color: #f3f3f3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":860,"file":"2019\/10\/FT_19.10.08_GunUpdate_1.png","filesize":70212,"sizes":{"thumbnail":{"file":"FT_19.10.08_GunUpdate_1.png?resize=150,150","width":150,"height":150,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=150&h=150&crop=1"},"medium":{"file":"FT_19.10.08_GunUpdate_1.png?resize=293,300","width":293,"height":300,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=293"},"medium_large":{"file":"FT_19.10.08_GunUpdate_1.png?resize=768,786","width":768,"height":786,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=640"},"A1":{"file":"FT_19.10.08_GunUpdate_1.png?resize=564,317","width":564,"height":317,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,634","width":840,"height":634,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"FT_19.10.08_GunUpdate_1.png?resize=690,388","width":690,"height":388,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,776","width":840,"height":776,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=776&crop=1"},"A2":{"file":"FT_19.10.08_GunUpdate_1.png?resize=268,151","width":268,"height":151,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=536,302","width":536,"height":302,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"FT_19.10.08_GunUpdate_1.png?resize=690,388","width":690,"height":388,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,776","width":840,"height":776,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=776&crop=1"},"A3":{"file":"FT_19.10.08_GunUpdate_1.png?resize=194,110","width":194,"height":110,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=388,220","width":388,"height":220,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"FT_19.10.08_GunUpdate_1.png?resize=148,84","width":148,"height":84,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=296,168","width":296,"height":168,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=296&h=168&crop=1"},"A4":{"file":"FT_19.10.08_GunUpdate_1.png?resize=268,151","width":268,"height":151,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=536,302","width":536,"height":302,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"FT_19.10.08_GunUpdate_1.png?resize=690,388","width":690,"height":388,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,776","width":840,"height":776,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=776&crop=1"},"XL":{"file":"FT_19.10.08_GunUpdate_1.png?resize=720,405","width":720,"height":405,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,810","width":840,"height":810,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=810&crop=1"},"social":{"file":"FT_19.10.08_GunUpdate_1.png?resize=840,628","width":840,"height":628,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=840&h=628&crop=1"},"chapter":{"file":"FT_19.10.08_GunUpdate_1.png?resize=396,405","width":396,"height":405,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=396"},"200-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=200,205","width":200,"height":205,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=200"},"260-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=260,266","width":260,"height":266,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=260"},"310-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=310,317","width":310,"height":317,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=310"},"420-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=420,430","width":420,"height":430,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=420"},"640-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=640,655","width":640,"height":655,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=640"},"740-wide":{"file":"FT_19.10.08_GunUpdate_1.png?resize=740,758","width":740,"height":758,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=740"},"75-square":{"file":"FT_19.10.08_GunUpdate_1.png?resize=75,75","width":75,"height":75,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=75&h=75&crop=1"},"140-square":{"file":"FT_19.10.08_GunUpdate_1.png?resize=140,140","width":140,"height":140,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=140&h=140&crop=1"},"260-square":{"file":"FT_19.10.08_GunUpdate_1.png?resize=260,260","width":260,"height":260,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"FT_19.10.08_GunUpdate_1.png?resize=160,164","width":160,"height":164,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=160"},"320-portrait":{"file":"FT_19.10.08_GunUpdate_1.png?resize=320,328","width":320,"height":328,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=320"},"200-by-133":{"file":"FT_19.10.08_GunUpdate_1.png?resize=200,133","width":200,"height":133,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"FT_19.10.08_GunUpdate_1.png?resize=740,416","width":740,"height":416,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=740&h=416&crop=1"},"540-by-304":{"file":"FT_19.10.08_GunUpdate_1.png?resize=540,304","width":540,"height":304,"filesize":70212,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png?w=540&h=304&crop=1"},"full":{"file":"FT_19.10.08_GunUpdate_1.png","width":840,"height":860,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f3f3f3","has_transparency":false},"post":10463,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/10\/FT_19.10.08_GunUpdate_1.png","filename":"FT_19.10.08_GunUpdate_1.png","filesize":70212,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/20320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=20320"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":10463,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/10463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}