{"id":199451,"date":"2025-02-10T09:58:02","date_gmt":"2025-02-10T14:58:02","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png"},"modified":"2025-02-11T14:55:21","modified_gmt":"2025-02-11T19:55:21","slug":"prc_2025-02-12_covid-5-year_1-02","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2025\/02\/12\/americans-views-on-covid-19-risk-and-the-countrys-response-to-health-emergencies\/prc_2025-02-12_covid-5-year_1-02\/","title":{"rendered":"60% of Democrats worry we\u2019re not taking COVID-19 seriously enough, 76% of Republicans disagree"},"author":377,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-199451","attachment","type-attachment","status-inherit","hentry"],"filename":"PRC_2025.02.12_covid-5-year_1-02.png","filesize":171809,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=200\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that 60% of Democrats worry we\u2019re not taking COVID-19 seriously enough, 76% of Republicans disagree\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=200,300 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=768,1152 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=683,1024 683w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=270,405 270w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=260,390 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=310,465 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=420,630 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=640,960 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=740,1110 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=160,240 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?resize=320,480 320w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-has-transparency=\"false\" data-dominant-color=\"cdd4d0\" style=\"--dominant-color: #cdd4d0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that 60% of Democrats worry we\u2019re not taking COVID-19 seriously enough, 76% of Republicans disagree","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1260,"file":"2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png","filesize":171809,"sizes":{"thumbnail":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=150,150","width":150,"height":150,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=150&h=150&crop=1"},"medium":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=200,300","width":200,"height":300,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=200"},"medium_large":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=768,1152","width":768,"height":1152,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=640"},"large":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=683,1024","width":683,"height":1024,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=640"},"A1":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=564,317","width":564,"height":317,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,634","width":840,"height":634,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=690,388","width":690,"height":388,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,776","width":840,"height":776,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=776&crop=1"},"A2":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=268,151","width":268,"height":151,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=536,302","width":536,"height":302,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=690,388","width":690,"height":388,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,776","width":840,"height":776,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=776&crop=1"},"A3":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=194,110","width":194,"height":110,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=388,220","width":388,"height":220,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=148,84","width":148,"height":84,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=296,168","width":296,"height":168,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=296&h=168&crop=1"},"A4":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=268,151","width":268,"height":151,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=536,302","width":536,"height":302,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=690,388","width":690,"height":388,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,776","width":840,"height":776,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=776&crop=1"},"XL":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=720,405","width":720,"height":405,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,810","width":840,"height":810,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=810&crop=1"},"social":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=840,628","width":840,"height":628,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=840&h=628&crop=1"},"chapter":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=270,405","width":270,"height":405,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=270"},"200-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=200,300","width":200,"height":300,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=200"},"260-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=260,390","width":260,"height":390,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=260"},"310-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=310,465","width":310,"height":465,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=310"},"420-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=420,630","width":420,"height":630,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=420"},"640-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=640,960","width":640,"height":960,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=640"},"740-wide":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=740,1110","width":740,"height":1110,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=740"},"75-square":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=75,75","width":75,"height":75,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=140,140","width":140,"height":140,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=260,260","width":260,"height":260,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=160,240","width":160,"height":240,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=160"},"320-portrait":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=320,480","width":320,"height":480,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=320"},"200-by-133":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=200,133","width":200,"height":133,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=740,416","width":740,"height":416,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PRC_2025.02.12_covid-5-year_1-02.png?resize=540,304","width":540,"height":304,"filesize":171809,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png?w=540&h=304&crop=1"},"full":{"file":"PRC_2025.02.12_covid-5-year_1-02.png","width":840,"height":1260,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"cdd4d0","has_transparency":false},"post":198513,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2025\/02\/PRC_2025.02.12_covid-5-year_1-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"60% of Democrats worry we\u2019re not taking COVID-19 seriously enough, 76% of Republicans disagree","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/199451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=199451"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":198513,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/198513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}