{"id":196044,"date":"2024-12-12T16:59:33","date_gmt":"2024-12-12T21:59:33","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png"},"modified":"2026-06-08T12:26:02","modified_gmt":"2026-06-08T16:26:02","slug":"pr_2024-12-18_restrictions-on-religion-2022_0-01","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/government-restrictions-on-religion-stayed-at-peak-levels-globally-in-2022\/pr_2024-12-18_restrictions-on-religion-2022_0-01\/","title":{"rendered":"How the index scores are classified"},"author":675,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_protected":false,"_prc_workspace_id":0},"class_list":["post-196044","attachment","type-attachment","status-inherit","hentry"],"_embeds":[],"prc_checklist":{},"table_of_contents":[{"id":196026,"title":"Government Restrictions on Religion Stayed at Peak Levels Globally in 2022","slug":"government-restrictions-on-religion-stayed-at-peak-levels-globally-in-2022","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/government-restrictions-on-religion-stayed-at-peak-levels-globally-in-2022\/","is_active":false},{"id":195897,"title":"1. Number of countries with \u2018very high\u2019 government restrictions increases in 2022","slug":"number-of-countries-with-very-high-government-restrictions-increases-in-2022","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/number-of-countries-with-very-high-government-restrictions-increases-in-2022\/","is_active":false},{"id":195993,"title":"2. Number of countries where religious groups were harassed reached new peak level in 2022","slug":"number-of-countries-where-religious-groups-were-harassed-reached-new-peak-level-in-2022","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/number-of-countries-where-religious-groups-were-harassed-reached-new-peak-level-in-2022\/","is_active":false},{"id":195916,"title":"3. Median scores for government restrictions and social hostilities stay the same in 2022","slug":"median-scores-for-government-restrictions-and-social-hostilities-stay-the-same-in-2022","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/median-scores-for-government-restrictions-and-social-hostilities-stay-the-same-in-2022\/","is_active":false},{"id":195920,"title":"4. Restrictions in the 25 most populous countries in 2022","slug":"restrictions-in-the-25-most-populous-countries-in-2022","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/restrictions-in-the-25-most-populous-countries-in-2022\/","is_active":false},{"id":196069,"title":"Acknowledgments","slug":"restrictions-on-religion-2022-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/restrictions-on-religion-2022-acknowledgments\/","is_active":false},{"id":196071,"title":"Methodology","slug":"restrictions-on-religion-2022-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/religion\/2024\/12\/18\/restrictions-on-religion-2022-methodology\/","is_active":false}],"datacite_doi":"Majumdar, Samirah.  2024.  \"Government Restrictions on Religion Stayed at Peak Levels Globally in 2022.\"  Pew Research Center. doi: 10.58094\/jkce-kx19.","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=270\" class=\"attachment-medium size-medium not-transparent\" alt=\"Table showing how the index scores are classified\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=270,300 270w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=364,405 364w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=200,223 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=260,289 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=310,345 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=420,467 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=160,178 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=320,356 320w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" data-has-transparency=\"false\" data-dominant-color=\"ebe2da\" style=\"--dominant-color: #ebe2da;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Table showing how the index scores are classified","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":690,"file":"2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png","filesize":234030,"sizes":{"thumbnail":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=150,150","width":150,"height":150,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=150&h=150&crop=1"},"medium":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=270,300","width":270,"height":300,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=270"},"A1":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=564,317","width":564,"height":317,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,634","width":620,"height":634,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,388","width":620,"height":388,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=388&crop=1"},"A2":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=268,151","width":268,"height":151,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=536,302","width":536,"height":302,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,388","width":620,"height":388,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=388&crop=1"},"A3":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=194,110","width":194,"height":110,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=388,220","width":388,"height":220,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=148,84","width":148,"height":84,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=296,168","width":296,"height":168,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=296&h=168&crop=1"},"A4":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=268,151","width":268,"height":151,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=536,302","width":536,"height":302,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,388","width":620,"height":388,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=388&crop=1"},"XL":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,405","width":620,"height":405,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=405&crop=1"},"social":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,628","width":620,"height":628,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=628&crop=1"},"chapter":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=364,405","width":364,"height":405,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=364"},"200-wide":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=200,223","width":200,"height":223,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=200"},"260-wide":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=260,289","width":260,"height":289,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=260"},"310-wide":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=310,345","width":310,"height":345,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=310"},"420-wide":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=420,467","width":420,"height":467,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=420"},"75-square":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=75,75","width":75,"height":75,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=140,140","width":140,"height":140,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=260,260","width":260,"height":260,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=160,178","width":160,"height":178,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=160"},"320-portrait":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=320,356","width":320,"height":356,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=320"},"200-by-133":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=200,133","width":200,"height":133,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=620,416","width":620,"height":416,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png?resize=540,304","width":540,"height":304,"filesize":234030,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png?w=540&h=304&crop=1"},"full":{"file":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png","width":620,"height":690,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ebe2da","has_transparency":false},"post":196026,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PR_2024.12.18_restrictions-on-religion-2022_0-01.png","filename":"PR_2024.12.18_restrictions-on-religion-2022_0-01.png","filesize":234030,"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/196044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/675"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=196044"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":196026,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/196026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}