{"id":195118,"date":"2024-12-03T15:13:21","date_gmt":"2024-12-03T20:13:21","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png"},"modified":"2024-12-03T15:23:50","modified_gmt":"2024-12-03T20:23:50","slug":"pp_2024-12-3_election-2024_00-03","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/voters-broadly-positive-about-how-elections-were-conducted-in-sharp-contrast-to-2020\/pp_2024-12-3_election-2024_00-03\/","title":{"rendered":"Most voters are confident that ineligible voters were kept from casting ballots \u2013 but Trump voters are more skeptical"},"author":581,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-195118","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2024.12.3_election-2024_00-03.png","filesize":141488,"_embeds":[],"table_of_contents":[{"id":195077,"title":"Voters Broadly Positive About How Elections Were Conducted, in Sharp Contrast to 2020","slug":"voters-broadly-positive-about-how-elections-were-conducted-in-sharp-contrast-to-2020","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/voters-broadly-positive-about-how-elections-were-conducted-in-sharp-contrast-to-2020\/","is_active":false},{"id":195087,"title":"1. Voters\u2019 evaluations of the 2024 election process","slug":"voters-evaluations-of-the-2024-election-process","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/voters-evaluations-of-the-2024-election-process\/","is_active":false},{"id":195094,"title":"2. Voters\u2019 and nonvoters\u2019 experiences with the 2024 election","slug":"voters-and-nonvoters-experiences-with-the-2024-election","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/voters-and-nonvoters-experiences-with-the-2024-election\/","is_active":false},{"id":195102,"title":"3. Voters\u2019 reflections on the 2024 campaign","slug":"voters-reflections-on-the-2024-campaign","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/voters-reflections-on-the-2024-campaign\/","is_active":false},{"id":195107,"title":"Acknowledgments","slug":"2024-election-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/2024-election-acknowledgments\/","is_active":false},{"id":195112,"title":"Methodology","slug":"2024-election-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/politics\/2024\/12\/04\/2024-election-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"294\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Most voters are confident that ineligible voters were kept from casting ballots \u2013 but Trump voters are more skeptical\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=300,294 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=413,405 413w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=200,196 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=260,255 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=310,304 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=420,412 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=75,75 75w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=160,157 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?resize=320,314 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"e8e7e2\" style=\"--dominant-color: #e8e7e2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Most voters are confident that ineligible voters were kept from casting ballots \u2013 but Trump voters are more skeptical","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":608,"file":"2024\/12\/PP_2024.12.3_election-2024_00-03.png","filesize":141488,"sizes":{"thumbnail":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=150,150","width":150,"height":150,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=300,294","width":300,"height":294,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=300"},"A1":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=564,317","width":564,"height":317,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=620,388","width":620,"height":388,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=620&h=388&crop=1"},"A2":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=268,151","width":268,"height":151,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=536,302","width":536,"height":302,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=620,388","width":620,"height":388,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=620&h=388&crop=1"},"A3":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=194,110","width":194,"height":110,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=388,220","width":388,"height":220,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=148,84","width":148,"height":84,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=296,168","width":296,"height":168,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=268,151","width":268,"height":151,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=536,302","width":536,"height":302,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=620,388","width":620,"height":388,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=620&h=388&crop=1"},"XL":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=620,405","width":620,"height":405,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=620&h=405&crop=1"},"chapter":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=413,405","width":413,"height":405,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=413"},"200-wide":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=200,196","width":200,"height":196,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=200"},"260-wide":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=260,255","width":260,"height":255,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=260"},"310-wide":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=310,304","width":310,"height":304,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=310"},"420-wide":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=420,412","width":420,"height":412,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=420"},"75-square":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=75,75","width":75,"height":75,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=140,140","width":140,"height":140,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=260,260","width":260,"height":260,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=160,157","width":160,"height":157,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=160"},"320-portrait":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=320,314","width":320,"height":314,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=320"},"200-by-133":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=200,133","width":200,"height":133,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=620,416","width":620,"height":416,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PP_2024.12.3_election-2024_00-03.png?resize=540,304","width":540,"height":304,"filesize":141488,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png?w=540&h=304&crop=1"},"full":{"file":"PP_2024.12.3_election-2024_00-03.png","width":620,"height":608,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e8e7e2","has_transparency":false},"post":195077,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/12\/PP_2024.12.3_election-2024_00-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Most voters are confident that ineligible voters were kept from casting ballots \u2013 but Trump voters are more skeptical","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/195118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=195118"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":195077,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/195077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}