{"id":189531,"date":"2024-10-14T13:42:28","date_gmt":"2024-10-14T17:42:28","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png"},"modified":"2024-10-14T14:25:29","modified_gmt":"2024-10-14T18:25:29","slug":"pst_2024-10-17_men-masculinity_5-02","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/social-trends\/2024\/10\/17\/how-americans-see-differences-between-men-and-women\/pst_2024-10-17_men-masculinity_5-02\/","title":{"rendered":"Men tend to point to biology, women cite societal expectations as basis for gender differences"},"author":581,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-189531","attachment","type-attachment","status-inherit","hentry"],"filename":"PST_2024.10.17_men-masculinity_5-02.png","filesize":142505,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"131\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=131\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Men tend to point to biology, women cite societal expectations as basis for gender differences\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=131,300 131w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=447,1024 447w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=177,405 177w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=200,458 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=260,595 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=310,710 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=420,962 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=140,320 140w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?resize=279,640 279w\" sizes=\"auto, (max-width: 131px) 100vw, 131px\" data-has-transparency=\"false\" data-dominant-color=\"e8eae4\" style=\"--dominant-color: #e8eae4;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Men tend to point to biology, women cite societal expectations as basis for gender differences","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":1420,"file":"2024\/10\/PST_2024.10.17_men-masculinity_5-02.png","filesize":142505,"sizes":{"thumbnail":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=150,150","width":150,"height":150,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=150&h=150&crop=1"},"medium":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=131,300","width":131,"height":300,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=131"},"large":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=447,1024","width":447,"height":1024,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=447"},"A1":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=564,317","width":564,"height":317,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,634","width":620,"height":634,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,388","width":620,"height":388,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,776","width":620,"height":776,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=776&crop=1"},"A2":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=268,151","width":268,"height":151,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=536,302","width":536,"height":302,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,388","width":620,"height":388,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,776","width":620,"height":776,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=776&crop=1"},"A3":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=194,110","width":194,"height":110,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=388,220","width":388,"height":220,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=148,84","width":148,"height":84,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=296,168","width":296,"height":168,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=296&h=168&crop=1"},"A4":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=268,151","width":268,"height":151,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=536,302","width":536,"height":302,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,388","width":620,"height":388,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,776","width":620,"height":776,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=776&crop=1"},"XL":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,405","width":620,"height":405,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,810","width":620,"height":810,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=810&crop=1"},"social":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,628","width":620,"height":628,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=628&crop=1"},"chapter":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=177,405","width":177,"height":405,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=177"},"200-wide":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=200,458","width":200,"height":458,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=200"},"260-wide":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=260,595","width":260,"height":595,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=260"},"310-wide":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=310,710","width":310,"height":710,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=310"},"420-wide":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=420,962","width":420,"height":962,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=420"},"75-square":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=75,75","width":75,"height":75,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=140,140","width":140,"height":140,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=260,260","width":260,"height":260,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=140,320","width":140,"height":320,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=140"},"320-portrait":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=279,640","width":279,"height":640,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=279"},"200-by-133":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=200,133","width":200,"height":133,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=620,416","width":620,"height":416,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PST_2024.10.17_men-masculinity_5-02.png?resize=540,304","width":540,"height":304,"filesize":142505,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png?w=540&h=304&crop=1"},"full":{"file":"PST_2024.10.17_men-masculinity_5-02.png","width":620,"height":1420,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e8eae4","has_transparency":false},"post":189439,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/10\/PST_2024.10.17_men-masculinity_5-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Men tend to point to biology, women cite societal expectations as basis for gender differences","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/189531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=189531"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":189439,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/189439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}