{"id":18380,"date":"2020-07-29T16:52:46","date_gmt":"2020-07-29T21:52:46","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png"},"modified":"2020-07-29T16:52:46","modified_gmt":"2020-07-29T21:52:46","slug":"ft_2020-07-30_china_01-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2020\/07\/30\/republicans-see-china-more-negatively-than-democrats-even-as-criticism-rises-in-both-parties\/ft_2020-07-30_china_01-png\/","title":{"rendered":"Republicans are more negative toward China than Democrats, though all partisans hold increasingly unfavorable views"},"author":584,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-18380","attachment","type-attachment","status-inherit","hentry"],"filename":"ft_2020.07.30_china_01.png","filesize":216196,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png'><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=284\" class=\"attachment-medium size-medium not-transparent\" alt=\"Republicans are more negative toward China than Democrats, though all partisans hold increasingly unfavorable views\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=284,300 284w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=768,810 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=384,405 384w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=200,211 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=260,274 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=310,327 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=420,443 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=640,675 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=740,781 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=160,169 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?resize=320,338 320w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" data-has-transparency=\"false\" data-dominant-color=\"f1efef\" style=\"--dominant-color: #f1efef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Republicans are more negative toward China than Democrats, though all partisans hold increasingly unfavorable views","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":886,"file":"2020\/07\/ft_2020.07.30_china_01.png","filesize":216196,"sizes":{"thumbnail":{"file":"ft_2020.07.30_china_01.png?resize=150,150","width":150,"height":150,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=150&h=150&crop=1"},"medium":{"file":"ft_2020.07.30_china_01.png?resize=284,300","width":284,"height":300,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=284"},"medium_large":{"file":"ft_2020.07.30_china_01.png?resize=768,810","width":768,"height":810,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=640"},"A1":{"file":"ft_2020.07.30_china_01.png?resize=564,317","width":564,"height":317,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=840,634","width":840,"height":634,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"ft_2020.07.30_china_01.png?resize=690,388","width":690,"height":388,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=840,776","width":840,"height":776,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=776&crop=1"},"A2":{"file":"ft_2020.07.30_china_01.png?resize=268,151","width":268,"height":151,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=536,302","width":536,"height":302,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"ft_2020.07.30_china_01.png?resize=690,388","width":690,"height":388,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=840,776","width":840,"height":776,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=776&crop=1"},"A3":{"file":"ft_2020.07.30_china_01.png?resize=194,110","width":194,"height":110,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=388,220","width":388,"height":220,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"ft_2020.07.30_china_01.png?resize=148,84","width":148,"height":84,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=296,168","width":296,"height":168,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=296&h=168&crop=1"},"A4":{"file":"ft_2020.07.30_china_01.png?resize=268,151","width":268,"height":151,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=536,302","width":536,"height":302,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"ft_2020.07.30_china_01.png?resize=690,388","width":690,"height":388,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"ft_2020.07.30_china_01.png?resize=840,776","width":840,"height":776,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=776&crop=1"},"XL":{"file":"ft_2020.07.30_china_01.png?resize=720,405","width":720,"height":405,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"ft_2020.07.30_china_01.png?resize=840,810","width":840,"height":810,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=810&crop=1"},"social":{"file":"ft_2020.07.30_china_01.png?resize=840,628","width":840,"height":628,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=840&h=628&crop=1"},"chapter":{"file":"ft_2020.07.30_china_01.png?resize=384,405","width":384,"height":405,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=384"},"200-wide":{"file":"ft_2020.07.30_china_01.png?resize=200,211","width":200,"height":211,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=200"},"260-wide":{"file":"ft_2020.07.30_china_01.png?resize=260,274","width":260,"height":274,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=260"},"310-wide":{"file":"ft_2020.07.30_china_01.png?resize=310,327","width":310,"height":327,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=310"},"420-wide":{"file":"ft_2020.07.30_china_01.png?resize=420,443","width":420,"height":443,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=420"},"640-wide":{"file":"ft_2020.07.30_china_01.png?resize=640,675","width":640,"height":675,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=640"},"740-wide":{"file":"ft_2020.07.30_china_01.png?resize=740,781","width":740,"height":781,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=740"},"75-square":{"file":"ft_2020.07.30_china_01.png?resize=75,75","width":75,"height":75,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=75&h=75&crop=1"},"140-square":{"file":"ft_2020.07.30_china_01.png?resize=140,140","width":140,"height":140,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=140&h=140&crop=1"},"260-square":{"file":"ft_2020.07.30_china_01.png?resize=260,260","width":260,"height":260,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"ft_2020.07.30_china_01.png?resize=160,169","width":160,"height":169,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=160"},"320-portrait":{"file":"ft_2020.07.30_china_01.png?resize=320,338","width":320,"height":338,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=320"},"200-by-133":{"file":"ft_2020.07.30_china_01.png?resize=200,133","width":200,"height":133,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"ft_2020.07.30_china_01.png?resize=740,416","width":740,"height":416,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=740&h=416&crop=1"},"540-by-304":{"file":"ft_2020.07.30_china_01.png?resize=540,304","width":540,"height":304,"filesize":216196,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png?w=540&h=304&crop=1"},"full":{"file":"ft_2020.07.30_china_01.png","width":840,"height":886,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1efef","has_transparency":false},"post":9818,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/07\/ft_2020.07.30_china_01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Republicans are more negative toward China than Democrats, though all partisans hold increasingly unfavorable views","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/18380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=18380"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":9818,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/9818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}