{"id":179085,"date":"2024-06-20T09:31:35","date_gmt":"2024-06-20T13:31:35","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png"},"modified":"2024-06-20T09:35:21","modified_gmt":"2024-06-20T13:35:21","slug":"sr_24-06-20_uk-election_3","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2024\/06\/20\/in-the-uk-dissatisfaction-with-economy-democracy-is-widespread-ahead-of-election\/sr_24-06-20_uk-election_3\/","title":{"rendered":"Few Britons think their country\u2019s economy is in good shape"},"author":658,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-179085","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_24.06.20_uk-election_3.png","filesize":309106,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png'><img loading=\"lazy\" decoding=\"async\" width=\"165\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=165\" class=\"attachment-medium size-medium not-transparent\" alt=\"A line chart showing that few Britons think their country\u2019s economy is in good shape.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=165,300 165w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=565,1024 565w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=223,405 223w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=200,363 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=260,471 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=310,562 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=420,761 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=160,290 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?resize=320,580 320w\" sizes=\"auto, (max-width: 165px) 100vw, 165px\" data-has-transparency=\"false\" data-dominant-color=\"f3f4f3\" style=\"--dominant-color: #f3f4f3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A line chart showing that few Britons think their country\u2019s economy is in good shape.","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":1124,"file":"2024\/06\/SR_24.06.20_uk-election_3.png","filesize":309106,"sizes":{"thumbnail":{"file":"SR_24.06.20_uk-election_3.png?resize=150,150","width":150,"height":150,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=150&h=150&crop=1"},"medium":{"file":"SR_24.06.20_uk-election_3.png?resize=165,300","width":165,"height":300,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=165"},"large":{"file":"SR_24.06.20_uk-election_3.png?resize=565,1024","width":565,"height":1024,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=565"},"A1":{"file":"SR_24.06.20_uk-election_3.png?resize=564,317","width":564,"height":317,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=620,634","width":620,"height":634,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"SR_24.06.20_uk-election_3.png?resize=620,388","width":620,"height":388,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=620,776","width":620,"height":776,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=776&crop=1"},"A2":{"file":"SR_24.06.20_uk-election_3.png?resize=268,151","width":268,"height":151,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=536,302","width":536,"height":302,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_24.06.20_uk-election_3.png?resize=620,388","width":620,"height":388,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=620,776","width":620,"height":776,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=776&crop=1"},"A3":{"file":"SR_24.06.20_uk-election_3.png?resize=194,110","width":194,"height":110,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=388,220","width":388,"height":220,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_24.06.20_uk-election_3.png?resize=148,84","width":148,"height":84,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=296,168","width":296,"height":168,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=296&h=168&crop=1"},"A4":{"file":"SR_24.06.20_uk-election_3.png?resize=268,151","width":268,"height":151,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=536,302","width":536,"height":302,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_24.06.20_uk-election_3.png?resize=620,388","width":620,"height":388,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=620,776","width":620,"height":776,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=776&crop=1"},"XL":{"file":"SR_24.06.20_uk-election_3.png?resize=620,405","width":620,"height":405,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"SR_24.06.20_uk-election_3.png?resize=620,810","width":620,"height":810,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=810&crop=1"},"social":{"file":"SR_24.06.20_uk-election_3.png?resize=620,628","width":620,"height":628,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=628&crop=1"},"chapter":{"file":"SR_24.06.20_uk-election_3.png?resize=223,405","width":223,"height":405,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=223"},"200-wide":{"file":"SR_24.06.20_uk-election_3.png?resize=200,363","width":200,"height":363,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=200"},"260-wide":{"file":"SR_24.06.20_uk-election_3.png?resize=260,471","width":260,"height":471,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=260"},"310-wide":{"file":"SR_24.06.20_uk-election_3.png?resize=310,562","width":310,"height":562,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=310"},"420-wide":{"file":"SR_24.06.20_uk-election_3.png?resize=420,761","width":420,"height":761,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=420"},"75-square":{"file":"SR_24.06.20_uk-election_3.png?resize=75,75","width":75,"height":75,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_24.06.20_uk-election_3.png?resize=140,140","width":140,"height":140,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_24.06.20_uk-election_3.png?resize=260,260","width":260,"height":260,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_24.06.20_uk-election_3.png?resize=160,290","width":160,"height":290,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=160"},"320-portrait":{"file":"SR_24.06.20_uk-election_3.png?resize=320,580","width":320,"height":580,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=320"},"200-by-133":{"file":"SR_24.06.20_uk-election_3.png?resize=200,133","width":200,"height":133,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_24.06.20_uk-election_3.png?resize=620,416","width":620,"height":416,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=620&h=416&crop=1"},"540-by-304":{"file":"SR_24.06.20_uk-election_3.png?resize=540,304","width":540,"height":304,"filesize":309106,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png?w=540&h=304&crop=1"},"full":{"file":"SR_24.06.20_uk-election_3.png","width":620,"height":1124,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f3f4f3","has_transparency":false},"post":179082,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/SR_24.06.20_uk-election_3.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Few Britons think their country\u2019s economy is in good shape","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/179085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=179085"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":179082,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/179082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}