{"id":178975,"date":"2024-06-18T13:42:58","date_gmt":"2024-06-18T17:42:58","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png"},"modified":"2024-06-18T13:45:16","modified_gmt":"2024-06-18T17:45:16","slug":"pj_2024-07-25_local-political-news-0-02","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/how-americans-get-local-political-news\/pj_2024-07-25_local-political-news-0-02\/","title":{"rendered":"Majority of Americans are interested in election news, but not as many have an easy time finding voting information"},"author":675,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-178975","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2024.07.25_local-political-news-0-02.png","filesize":178763,"_embeds":[],"table_of_contents":[{"id":178866,"title":"How Americans Get Local Political News","slug":"how-americans-get-local-political-news","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/how-americans-get-local-political-news\/","is_active":false},{"id":178946,"title":"1.\u00a0 Consumption and sources of local political news","slug":"consumption-and-sources-of-local-political-news","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/consumption-and-sources-of-local-political-news\/","is_active":false},{"id":178952,"title":"2. Attitudes toward local political news: Interest, satisfaction and ease of access","slug":"attitudes-toward-local-political-news-interest-satisfaction-and-ease-of-access","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/attitudes-toward-local-political-news-interest-satisfaction-and-ease-of-access\/","is_active":false},{"id":178958,"title":"3. Community attachment and local political news","slug":"community-attachment-and-local-political-news","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/community-attachment-and-local-political-news\/","is_active":false},{"id":178964,"title":"Acknowledgments","slug":"local-political-news-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/local-political-news-acknowledgments\/","is_active":false},{"id":178969,"title":"Methodology","slug":"local-political-news-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/journalism\/2024\/07\/24\/local-political-news-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=216\" class=\"attachment-medium size-medium not-transparent\" alt=\"Bar chart showing a majority of Americans are interested in election news, but not as many have an easy time finding voting information\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=216,300 216w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=291,405 291w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=200,278 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=260,361 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=310,431 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=420,584 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=160,222 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?resize=320,445 320w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" data-has-transparency=\"false\" data-dominant-color=\"e1dbd6\" style=\"--dominant-color: #e1dbd6;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Bar chart showing a majority of Americans are interested in election news, but not as many have an easy time finding voting information","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":862,"file":"2024\/06\/PJ_2024.07.25_local-political-news-0-02.png","filesize":178763,"sizes":{"thumbnail":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=150,150","width":150,"height":150,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=150&h=150&crop=1"},"medium":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=216,300","width":216,"height":300,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=216"},"A1":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=564,317","width":564,"height":317,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,634","width":620,"height":634,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,388","width":620,"height":388,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,776","width":620,"height":776,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=776&crop=1"},"A2":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=268,151","width":268,"height":151,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=536,302","width":536,"height":302,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,388","width":620,"height":388,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,776","width":620,"height":776,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=776&crop=1"},"A3":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=194,110","width":194,"height":110,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=388,220","width":388,"height":220,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=148,84","width":148,"height":84,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=296,168","width":296,"height":168,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=296&h=168&crop=1"},"A4":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=268,151","width":268,"height":151,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=536,302","width":536,"height":302,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,388","width":620,"height":388,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,776","width":620,"height":776,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=776&crop=1"},"XL":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,405","width":620,"height":405,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,810","width":620,"height":810,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=810&crop=1"},"social":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,628","width":620,"height":628,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=628&crop=1"},"chapter":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=291,405","width":291,"height":405,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=291"},"200-wide":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=200,278","width":200,"height":278,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=200"},"260-wide":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=260,361","width":260,"height":361,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=260"},"310-wide":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=310,431","width":310,"height":431,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=310"},"420-wide":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=420,584","width":420,"height":584,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=420"},"75-square":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=75,75","width":75,"height":75,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=140,140","width":140,"height":140,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=260,260","width":260,"height":260,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=160,222","width":160,"height":222,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=160"},"320-portrait":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=320,445","width":320,"height":445,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=320"},"200-by-133":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=200,133","width":200,"height":133,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=620,416","width":620,"height":416,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PJ_2024.07.25_local-political-news-0-02.png?resize=540,304","width":540,"height":304,"filesize":178763,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png?w=540&h=304&crop=1"},"full":{"file":"PJ_2024.07.25_local-political-news-0-02.png","width":620,"height":862,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e1dbd6","has_transparency":false},"post":178866,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PJ_2024.07.25_local-political-news-0-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Majority of Americans are interested in election news, but not as many have an easy time finding voting information","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/178975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/675"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=178975"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":178866,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/178866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}