{"id":14050,"date":"2021-10-01T11:51:15","date_gmt":"2021-10-01T16:51:15","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png"},"modified":"2021-10-01T11:51:15","modified_gmt":"2021-10-01T16:51:15","slug":"ft_21-09-28_homeworkgap-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2021\/10\/01\/what-we-know-about-online-learning-and-the-homework-gap-amid-the-pandemic\/ft_21-09-28_homeworkgap-png\/","title":{"rendered":"In 2018, Black teens and those from lower-income households were especially likely to be impacted by the digital &#8216;homework gap&#8217;"},"author":584,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-14050","attachment","type-attachment","status-inherit","hentry"],"filename":"FT_21.09.28_HomeworkGap.png","filesize":73755,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that in 2018, Black teens and those from lower-income households were especially likely to be impacted by the digital &#039;homework gap&#039;\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=300,200 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=768,511 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=1024,682 1024w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=608,405 608w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=200,133 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=260,173 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=310,206 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=420,280 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=640,426 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=740,493 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=160,107 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?resize=320,213 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"e1e8ed\" style=\"--dominant-color: #e1e8ed;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that in 2018, Black teens and those from lower-income households were especially likely to be impacted by the digital 'homework gap'","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":852,"file":"2021\/10\/FT_21.09.28_HomeworkGap.png","filesize":73755,"sizes":{"thumbnail":{"file":"FT_21.09.28_HomeworkGap.png?resize=150,150","width":150,"height":150,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=150&h=150&crop=1"},"medium":{"file":"FT_21.09.28_HomeworkGap.png?resize=300,200","width":300,"height":200,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=300"},"medium_large":{"file":"FT_21.09.28_HomeworkGap.png?resize=768,511","width":768,"height":511,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=640"},"large":{"file":"FT_21.09.28_HomeworkGap.png?resize=1024,682","width":1024,"height":682,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=640"},"A1":{"file":"FT_21.09.28_HomeworkGap.png?resize=564,317","width":564,"height":317,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=1128,634","width":1128,"height":634,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"FT_21.09.28_HomeworkGap.png?resize=690,388","width":690,"height":388,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=1280,776","width":1280,"height":776,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1280&h=776&crop=1"},"A2":{"file":"FT_21.09.28_HomeworkGap.png?resize=268,151","width":268,"height":151,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=536,302","width":536,"height":302,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"FT_21.09.28_HomeworkGap.png?resize=690,388","width":690,"height":388,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=1280,776","width":1280,"height":776,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1280&h=776&crop=1"},"A3":{"file":"FT_21.09.28_HomeworkGap.png?resize=194,110","width":194,"height":110,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=388,220","width":388,"height":220,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"FT_21.09.28_HomeworkGap.png?resize=148,84","width":148,"height":84,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=296,168","width":296,"height":168,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=296&h=168&crop=1"},"A4":{"file":"FT_21.09.28_HomeworkGap.png?resize=268,151","width":268,"height":151,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=536,302","width":536,"height":302,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"FT_21.09.28_HomeworkGap.png?resize=690,388","width":690,"height":388,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=1280,776","width":1280,"height":776,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1280&h=776&crop=1"},"XL":{"file":"FT_21.09.28_HomeworkGap.png?resize=720,405","width":720,"height":405,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"FT_21.09.28_HomeworkGap.png?resize=1280,810","width":1280,"height":810,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1280&h=810&crop=1"},"social":{"file":"FT_21.09.28_HomeworkGap.png?resize=1200,628","width":1200,"height":628,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=1200&h=628&crop=1"},"chapter":{"file":"FT_21.09.28_HomeworkGap.png?resize=608,405","width":608,"height":405,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=608"},"200-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=200,133","width":200,"height":133,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=200"},"260-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=260,173","width":260,"height":173,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=260"},"310-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=310,206","width":310,"height":206,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=310"},"420-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=420,280","width":420,"height":280,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=420"},"640-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=640,426","width":640,"height":426,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=640"},"740-wide":{"file":"FT_21.09.28_HomeworkGap.png?resize=740,493","width":740,"height":493,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=740"},"75-square":{"file":"FT_21.09.28_HomeworkGap.png?resize=75,75","width":75,"height":75,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=75&h=75&crop=1"},"140-square":{"file":"FT_21.09.28_HomeworkGap.png?resize=140,140","width":140,"height":140,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=140&h=140&crop=1"},"260-square":{"file":"FT_21.09.28_HomeworkGap.png?resize=260,260","width":260,"height":260,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=260&h=260&crop=1"},"160-portrait":{"file":"FT_21.09.28_HomeworkGap.png?resize=160,107","width":160,"height":107,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=160"},"320-portrait":{"file":"FT_21.09.28_HomeworkGap.png?resize=320,213","width":320,"height":213,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=320"},"200-by-133":{"file":"FT_21.09.28_HomeworkGap.png?resize=200,133","width":200,"height":133,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=200&h=133&crop=1"},"740-by-416":{"file":"FT_21.09.28_HomeworkGap.png?resize=740,416","width":740,"height":416,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=740&h=416&crop=1"},"540-by-304":{"file":"FT_21.09.28_HomeworkGap.png?resize=540,304","width":540,"height":304,"filesize":73755,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png?w=540&h=304&crop=1"},"full":{"file":"FT_21.09.28_HomeworkGap.png","width":1200,"height":799,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e1e8ed","has_transparency":false},"post":8800,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/10\/FT_21.09.28_HomeworkGap.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"In 2018, Black teens and those from lower-income households were especially likely to be impacted by the digital 'homework gap'","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/14050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=14050"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":8800,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/8800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}