{"id":12704,"date":"2022-03-01T13:59:13","date_gmt":"2022-03-01T18:59:13","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png"},"modified":"2022-03-01T13:59:13","modified_gmt":"2022-03-01T18:59:13","slug":"ft_2022-03-02_indiagender_02-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/short-reads\/2022\/03\/02\/key-findings-on-indian-attitudes-toward-gender-roles\/ft_2022-03-02_indiagender_02-png\/","title":{"rendered":"Nearly three-quarters of adults in India say both men and women should make financial decisions in a family"},"author":584,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-12704","attachment","type-attachment","status-inherit","hentry"],"filename":"ft_2022.03.02_indiagender_02.png","filesize":79522,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"132\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that nearly three-quarters of adults in India say both men and women should make financial decisions in a family\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=300,132 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=768,337 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=1024,450 1024w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=922,405 922w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=200,88 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=260,114 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=310,136 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=420,184 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=640,281 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=740,325 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=160,70 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?resize=320,141 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"d1e0e7\" style=\"--dominant-color: #d1e0e7;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that nearly three-quarters of adults in India say both men and women should make financial decisions in a family","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":562,"file":"2022\/03\/ft_2022.03.02_indiagender_02.png","filesize":79522,"sizes":{"thumbnail":{"file":"ft_2022.03.02_indiagender_02.png?resize=150,150","width":150,"height":150,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=150&h=150&crop=1"},"medium":{"file":"ft_2022.03.02_indiagender_02.png?resize=300,132","width":300,"height":132,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=300"},"medium_large":{"file":"ft_2022.03.02_indiagender_02.png?resize=768,337","width":768,"height":337,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=640"},"large":{"file":"ft_2022.03.02_indiagender_02.png?resize=1024,450","width":1024,"height":450,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=640"},"A1":{"file":"ft_2022.03.02_indiagender_02.png?resize=564,317","width":564,"height":317,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"ft_2022.03.02_indiagender_02.png?resize=1128,562","width":1128,"height":562,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=1128&h=562&crop=1"},"A1-SMALL":{"file":"ft_2022.03.02_indiagender_02.png?resize=690,388","width":690,"height":388,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=690&h=388&crop=1"},"A2":{"file":"ft_2022.03.02_indiagender_02.png?resize=268,151","width":268,"height":151,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"ft_2022.03.02_indiagender_02.png?resize=536,302","width":536,"height":302,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"ft_2022.03.02_indiagender_02.png?resize=690,388","width":690,"height":388,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=690&h=388&crop=1"},"A3":{"file":"ft_2022.03.02_indiagender_02.png?resize=194,110","width":194,"height":110,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"ft_2022.03.02_indiagender_02.png?resize=388,220","width":388,"height":220,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"ft_2022.03.02_indiagender_02.png?resize=148,84","width":148,"height":84,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"ft_2022.03.02_indiagender_02.png?resize=296,168","width":296,"height":168,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=296&h=168&crop=1"},"A4":{"file":"ft_2022.03.02_indiagender_02.png?resize=268,151","width":268,"height":151,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"ft_2022.03.02_indiagender_02.png?resize=536,302","width":536,"height":302,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"ft_2022.03.02_indiagender_02.png?resize=690,388","width":690,"height":388,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=690&h=388&crop=1"},"XL":{"file":"ft_2022.03.02_indiagender_02.png?resize=720,405","width":720,"height":405,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=720&h=405&crop=1"},"social":{"file":"ft_2022.03.02_indiagender_02.png?resize=1200,562","width":1200,"height":562,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=1200&h=562&crop=1"},"chapter":{"file":"ft_2022.03.02_indiagender_02.png?resize=922,405","width":922,"height":405,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=922"},"200-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=200,88","width":200,"height":88,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=200"},"260-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=260,114","width":260,"height":114,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=260"},"310-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=310,136","width":310,"height":136,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=310"},"420-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=420,184","width":420,"height":184,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=420"},"640-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=640,281","width":640,"height":281,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=640"},"740-wide":{"file":"ft_2022.03.02_indiagender_02.png?resize=740,325","width":740,"height":325,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=740"},"75-square":{"file":"ft_2022.03.02_indiagender_02.png?resize=75,75","width":75,"height":75,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=75&h=75&crop=1"},"140-square":{"file":"ft_2022.03.02_indiagender_02.png?resize=140,140","width":140,"height":140,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=140&h=140&crop=1"},"260-square":{"file":"ft_2022.03.02_indiagender_02.png?resize=260,260","width":260,"height":260,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"ft_2022.03.02_indiagender_02.png?resize=160,70","width":160,"height":70,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=160"},"320-portrait":{"file":"ft_2022.03.02_indiagender_02.png?resize=320,141","width":320,"height":141,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=320"},"200-by-133":{"file":"ft_2022.03.02_indiagender_02.png?resize=200,133","width":200,"height":133,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"ft_2022.03.02_indiagender_02.png?resize=740,416","width":740,"height":416,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=740&h=416&crop=1"},"540-by-304":{"file":"ft_2022.03.02_indiagender_02.png?resize=540,304","width":540,"height":304,"filesize":79522,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png?w=540&h=304&crop=1"},"full":{"file":"ft_2022.03.02_indiagender_02.png","width":1200,"height":527,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d1e0e7","has_transparency":false},"post":8625,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/03\/ft_2022.03.02_indiagender_02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Nearly three-quarters of adults in India say both men and women should make financial decisions in a family","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/12704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=12704"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":8625,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/8625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}