{"id":124006,"date":"2023-11-29T13:16:36","date_gmt":"2023-11-29T18:16:36","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png"},"modified":"2023-11-29T13:16:36","modified_gmt":"2023-11-29T18:16:36","slug":"re_2023-11-30_asian-american-discrimination_1-04-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2023\/11\/30\/asian-americans-experiences-with-discrimination-in-their-daily-lives\/re_2023-11-30_asian-american-discrimination_1-04-png\/","title":{"rendered":"About 1 in 5 Asian adults say strangers have acted  like they are dishonest"},"author":578,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-124006","attachment","type-attachment","status-inherit","hentry"],"filename":"RE_2023.11.30_Asian-American-Discrimination_1-04.png","filesize":394591,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png'><img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=178\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing 18% of Asian adults say strangers have acted like they are dishonest in day-to-day encounters. 12% of Asian adults say people have acted as if they are afraid of them. Across ethnic origin groups, 37% of those who belong to less populous Asian origins say they have had at least one of the two experiences, higher than the shares among the six largest Asian origin groups, which range from 12% to 24%.\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=178,300 178w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=768,1296 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=607,1024 607w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=240,405 240w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=200,338 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=260,439 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=310,523 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=420,709 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=640,1080 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=740,1249 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=160,270 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=320,540 320w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" data-has-transparency=\"false\" data-dominant-color=\"eaebea\" style=\"--dominant-color: #eaebea;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing 18% of Asian adults say strangers have acted like they are dishonest in day-to-day encounters. 12% of Asian adults say people have acted as if they are afraid of them. Across ethnic origin groups, 37% of those who belong to less populous Asian origins say they have had at least one of the two experiences, higher than the shares among the six largest Asian origin groups, which range from 12% to 24%.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1418,"file":"2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png","filesize":394591,"sizes":{"thumbnail":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=150,150","width":150,"height":150,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=150&h=150&crop=1"},"medium":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=178,300","width":178,"height":300,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=178"},"medium_large":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=768,1296","width":768,"height":1296,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=640"},"large":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=607,1024","width":607,"height":1024,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=607"},"A1":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=564,317","width":564,"height":317,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,634","width":840,"height":634,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=690,388","width":690,"height":388,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,776","width":840,"height":776,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=776&crop=1"},"A2":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=268,151","width":268,"height":151,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=536,302","width":536,"height":302,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=690,388","width":690,"height":388,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,776","width":840,"height":776,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=776&crop=1"},"A3":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=194,110","width":194,"height":110,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=388,220","width":388,"height":220,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=148,84","width":148,"height":84,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=296,168","width":296,"height":168,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=296&h=168&crop=1"},"A4":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=268,151","width":268,"height":151,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=536,302","width":536,"height":302,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=690,388","width":690,"height":388,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,776","width":840,"height":776,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=776&crop=1"},"XL":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=720,405","width":720,"height":405,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,810","width":840,"height":810,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=810&crop=1"},"social":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=840,628","width":840,"height":628,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=840&h=628&crop=1"},"chapter":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=240,405","width":240,"height":405,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=240"},"200-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=200,338","width":200,"height":338,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=200"},"260-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=260,439","width":260,"height":439,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=260"},"310-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=310,523","width":310,"height":523,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=310"},"420-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=420,709","width":420,"height":709,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=420"},"640-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=640,1080","width":640,"height":1080,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=640"},"740-wide":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=740,1249","width":740,"height":1249,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=740"},"75-square":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=75,75","width":75,"height":75,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=75&h=75&crop=1"},"140-square":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=140,140","width":140,"height":140,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=140&h=140&crop=1"},"260-square":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=260,260","width":260,"height":260,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=260&h=260&crop=1"},"160-portrait":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=160,270","width":160,"height":270,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=160"},"320-portrait":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=320,540","width":320,"height":540,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=320"},"200-by-133":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=200,133","width":200,"height":133,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=200&h=133&crop=1"},"740-by-416":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=740,416","width":740,"height":416,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=740&h=416&crop=1"},"540-by-304":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png?resize=540,304","width":540,"height":304,"filesize":394591,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png?w=540&h=304&crop=1"},"full":{"file":"RE_2023.11.30_Asian-American-Discrimination_1-04.png","width":840,"height":1418,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eaebea","has_transparency":false},"post":109265,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/RE_2023.11.30_Asian-American-Discrimination_1-04.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"About 1 in 5 Asian adults say strangers have acted  like they are dishonest","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/124006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/578"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=124006"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":109265,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/109265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}