{"id":123897,"date":"2024-01-31T23:16:35","date_gmt":"2024-02-01T04:16:35","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png"},"modified":"2024-01-31T23:16:35","modified_gmt":"2024-02-01T04:16:35","slug":"re_2024-02-08_black-views-success_2_05-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2024\/02\/08\/how-black-americans-view-financial-success\/re_2024-02-08_black-views-success_2_05-png\/","title":{"rendered":"Bills, debt and saving for retirement are the top three economic worries Black adults experience on a daily or near daily basis"},"author":648,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-123897","attachment","type-attachment","status-inherit","hentry"],"filename":"re_2024.02.08_black-views-success_2_05.png","filesize":638901,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png'><img loading=\"lazy\" decoding=\"async\" width=\"286\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=286\" class=\"attachment-medium size-medium not-transparent\" alt=\"A table showing that Bills, debt and saving for retirement are the top three economic worries Black adults experience on a daily or near daily basis\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=286,300 286w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=768,806 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=975,1024 975w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=386,405 386w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=200,210 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=260,273 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=310,326 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=420,441 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=640,672 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=740,777 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=160,168 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?resize=320,336 320w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" data-has-transparency=\"false\" data-dominant-color=\"e6e8e2\" style=\"--dominant-color: #e6e8e2;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A table showing that Bills, debt and saving for retirement are the top three economic worries Black adults experience on a daily or near daily basis","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":1344,"file":"2024\/01\/re_2024.02.08_black-views-success_2_05.png","filesize":638901,"sizes":{"thumbnail":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=150,150","width":150,"height":150,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=150&h=150&crop=1"},"medium":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=286,300","width":286,"height":300,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=286"},"medium_large":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=768,806","width":768,"height":806,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=640"},"large":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=975,1024","width":975,"height":1024,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=640"},"A1":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=564,317","width":564,"height":317,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1128,634","width":1128,"height":634,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=690,388","width":690,"height":388,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1280,776","width":1280,"height":776,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1280&h=776&crop=1"},"A2":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=268,151","width":268,"height":151,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=536,302","width":536,"height":302,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=690,388","width":690,"height":388,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1280,776","width":1280,"height":776,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1280&h=776&crop=1"},"A3":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=194,110","width":194,"height":110,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=388,220","width":388,"height":220,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=148,84","width":148,"height":84,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=296,168","width":296,"height":168,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=296&h=168&crop=1"},"A4":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=268,151","width":268,"height":151,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=536,302","width":536,"height":302,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=690,388","width":690,"height":388,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1280,776","width":1280,"height":776,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1280&h=776&crop=1"},"XL":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=720,405","width":720,"height":405,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1280,810","width":1280,"height":810,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1280&h=810&crop=1"},"social":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=1200,628","width":1200,"height":628,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=1200&h=628&crop=1"},"chapter":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=386,405","width":386,"height":405,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=386"},"200-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=200,210","width":200,"height":210,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=200"},"260-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=260,273","width":260,"height":273,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=260"},"310-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=310,326","width":310,"height":326,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=310"},"420-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=420,441","width":420,"height":441,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=420"},"640-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=640,672","width":640,"height":672,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=640"},"740-wide":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=740,777","width":740,"height":777,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=740"},"75-square":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=75,75","width":75,"height":75,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=75&h=75&crop=1"},"140-square":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=140,140","width":140,"height":140,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=140&h=140&crop=1"},"260-square":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=260,260","width":260,"height":260,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=260&h=260&crop=1"},"160-portrait":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=160,168","width":160,"height":168,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=160"},"320-portrait":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=320,336","width":320,"height":336,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=320"},"200-by-133":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=200,133","width":200,"height":133,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=200&h=133&crop=1"},"740-by-416":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=740,416","width":740,"height":416,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=740&h=416&crop=1"},"540-by-304":{"file":"re_2024.02.08_black-views-success_2_05.png?resize=540,304","width":540,"height":304,"filesize":638901,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png?w=540&h=304&crop=1"},"full":{"file":"re_2024.02.08_black-views-success_2_05.png","width":1200,"height":1260,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e6e8e2","has_transparency":false},"post":109205,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/re_2024.02.08_black-views-success_2_05.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Bills, debt and saving for retirement are the top three economic worries Black adults experience on a daily or near daily basis","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/123897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=123897"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":109205,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/109205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}