{"id":123817,"date":"2023-09-19T15:47:34","date_gmt":"2023-09-19T20:47:34","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png"},"modified":"2024-05-03T16:20:22","modified_gmt":"2024-05-03T20:20:22","slug":"re_2023-09-20_latinos-speaking-spanish_0-08-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2023\/09\/20\/latinos-views-of-and-experiences-with-the-spanish-language\/re_2023-09-20_latinos-speaking-spanish_0-08-png\/","title":{"rendered":"Importance of one\u2019s Hispanic identity reflects how Hispanics view speaking Spanish"},"author":578,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-123817","attachment","type-attachment","status-inherit","hentry"],"filename":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png","filesize":139049,"_embeds":[],"table_of_contents":[{"id":109165,"title":"Latinos\u2019 Views of and Experiences With the Spanish Language","slug":"latinos-views-of-and-experiences-with-the-spanish-language","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2023\/09\/20\/latinos-views-of-and-experiences-with-the-spanish-language\/","is_active":false},{"id":109174,"title":"Acknowledgments","slug":"latinos-speaking-spanish-acknowledgments","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2023\/09\/20\/latinos-speaking-spanish-acknowledgments\/","is_active":false},{"id":109180,"title":"Methodology","slug":"latinos-speaking-spanish-methodology","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/race-and-ethnicity\/2023\/09\/20\/latinos-speaking-spanish-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"179\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Bar charts showing the importance of one\u2019s Hispanic identity reflects how Hispanics view speaking Spanish\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png 1280w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=300,179 300w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=768,458 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=1024,611 1024w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=679,405 679w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=200,119 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=260,155 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=310,185 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=420,251 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=640,382 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=740,442 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=160,96 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=320,191 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"eae6e3\" style=\"--dominant-color: #eae6e3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Bar charts showing the importance of one\u2019s Hispanic identity reflects how Hispanics view speaking Spanish","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":764,"file":"2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png","filesize":139049,"sizes":{"thumbnail":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=150,150","width":150,"height":150,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=150&h=150&crop=1"},"medium":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=300,179","width":300,"height":179,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=300"},"medium_large":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=768,458","width":768,"height":458,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=640"},"large":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=1024,611","width":1024,"height":611,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=640"},"A1":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=564,317","width":564,"height":317,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=1128,634","width":1128,"height":634,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=690,388","width":690,"height":388,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=690&h=388&crop=1"},"A2":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=268,151","width":268,"height":151,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=536,302","width":536,"height":302,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=690,388","width":690,"height":388,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=690&h=388&crop=1"},"A3":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=194,110","width":194,"height":110,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=388,220","width":388,"height":220,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=148,84","width":148,"height":84,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=296,168","width":296,"height":168,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=296&h=168&crop=1"},"A4":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=268,151","width":268,"height":151,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=536,302","width":536,"height":302,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=690,388","width":690,"height":388,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=690&h=388&crop=1"},"XL":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=720,405","width":720,"height":405,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=720&h=405&crop=1"},"social":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=1200,628","width":1200,"height":628,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=1200&h=628&crop=1"},"chapter":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=679,405","width":679,"height":405,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=679"},"200-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=200,119","width":200,"height":119,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=200"},"260-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=260,155","width":260,"height":155,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=260"},"310-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=310,185","width":310,"height":185,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=310"},"420-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=420,251","width":420,"height":251,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=420"},"640-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=640,382","width":640,"height":382,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=640"},"740-wide":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=740,442","width":740,"height":442,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=740"},"75-square":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=75,75","width":75,"height":75,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=75&h=75&crop=1"},"140-square":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=140,140","width":140,"height":140,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=140&h=140&crop=1"},"260-square":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=260,260","width":260,"height":260,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=260&h=260&crop=1"},"160-portrait":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=160,96","width":160,"height":96,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=160"},"320-portrait":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=320,191","width":320,"height":191,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=320"},"200-by-133":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=200,133","width":200,"height":133,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=200&h=133&crop=1"},"740-by-416":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=740,416","width":740,"height":416,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=740&h=416&crop=1"},"540-by-304":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?resize=540,304","width":540,"height":304,"filesize":139049,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png?w=540&h=304&crop=1"},"full":{"file":"RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png","width":1200,"height":716,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eae6e3","has_transparency":false},"post":109165,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/RE_2023.09.20_Latinos-Speaking-Spanish_0-08.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Importance of one\u2019s Hispanic identity reflects how Hispanics view speaking Spanish","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/123817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/578"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=123817"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":109165,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/109165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}