{"id":122660,"date":"2021-03-03T14:57:40","date_gmt":"2021-03-03T19:57:40","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png"},"modified":"2021-03-03T14:57:40","modified_gmt":"2021-03-03T19:57:40","slug":"ps_2021-03-05_covid-19-vaccines_00-018-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2021\/03\/05\/growing-share-of-americans-say-they-plan-to-get-a-covid-19-vaccine-or-already-have\/ps_2021-03-05_covid-19-vaccines_00-018-png\/","title":{"rendered":"19% of U.S. adults say they\u2019ve received at least one dose of a COVID-19 vaccine"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-122660","attachment","type-attachment","status-inherit","hentry"],"filename":"PS_2021.03.05_covid-19-vaccines_00-018.png","filesize":105305,"_embeds":[],"table_of_contents":[{"id":104845,"title":"Growing Share of Americans Say They Plan To Get a COVID-19 Vaccine \u2013 or Already Have","slug":"growing-share-of-americans-say-they-plan-to-get-a-covid-19-vaccine-or-already-have","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2021\/03\/05\/growing-share-of-americans-say-they-plan-to-get-a-covid-19-vaccine-or-already-have\/","is_active":false},{"id":104857,"title":"Acknowledgments","slug":"acknowledgments-5-9","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2021\/03\/05\/acknowledgments-5-9\/","is_active":false},{"id":104869,"title":"Methodology","slug":"covid-19-vaccine-methodology-2","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2021\/03\/05\/covid-19-vaccine-methodology-2\/","is_active":false},{"id":104883,"title":"Appendix A: Detailed charts and tables","slug":"covid-19-vaccine-appendix-a","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2021\/03\/05\/covid-19-vaccine-appendix-a\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png'><img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=152\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows 19% of U.S. adults say they\u2019ve received at least one dose of a COVID-19 vaccine\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png 620w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=152,300 152w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=520,1024 520w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=206,405 206w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=200,394 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=260,512 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=310,610 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=420,826 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=160,315 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?resize=320,630 320w\" sizes=\"auto, (max-width: 152px) 100vw, 152px\" data-has-transparency=\"false\" data-dominant-color=\"e3e6e8\" style=\"--dominant-color: #e3e6e8;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows 19% of U.S. adults say they\u2019ve received at least one dose of a COVID-19 vaccine","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":1220,"file":"2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png","filesize":105305,"sizes":{"thumbnail":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=150,150","width":150,"height":150,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=150&h=150&crop=1"},"medium":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=152,300","width":152,"height":300,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=152"},"large":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=520,1024","width":520,"height":1024,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=520"},"A1":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=564,317","width":564,"height":317,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,634","width":620,"height":634,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,388","width":620,"height":388,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,776","width":620,"height":776,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=776&crop=1"},"A2":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=268,151","width":268,"height":151,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=536,302","width":536,"height":302,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,388","width":620,"height":388,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,776","width":620,"height":776,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=776&crop=1"},"A3":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=194,110","width":194,"height":110,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=388,220","width":388,"height":220,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=148,84","width":148,"height":84,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=296,168","width":296,"height":168,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=296&h=168&crop=1"},"A4":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=268,151","width":268,"height":151,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=536,302","width":536,"height":302,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,388","width":620,"height":388,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,776","width":620,"height":776,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=776&crop=1"},"XL":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,405","width":620,"height":405,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,810","width":620,"height":810,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=810&crop=1"},"social":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,628","width":620,"height":628,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=628&crop=1"},"chapter":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=206,405","width":206,"height":405,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=206"},"200-wide":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=200,394","width":200,"height":394,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=200"},"260-wide":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=260,512","width":260,"height":512,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=260"},"310-wide":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=310,610","width":310,"height":610,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=310"},"420-wide":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=420,826","width":420,"height":826,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=420"},"75-square":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=75,75","width":75,"height":75,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=75&h=75&crop=1"},"140-square":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=140,140","width":140,"height":140,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=140&h=140&crop=1"},"260-square":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=260,260","width":260,"height":260,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=160,315","width":160,"height":315,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=160"},"320-portrait":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=320,630","width":320,"height":630,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=320"},"200-by-133":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=200,133","width":200,"height":133,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=620,416","width":620,"height":416,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png?resize=540,304","width":540,"height":304,"filesize":105305,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png?w=540&h=304&crop=1"},"full":{"file":"PS_2021.03.05_covid-19-vaccines_00-018.png","width":620,"height":1220,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e3e6e8","has_transparency":false},"post":104845,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PS_2021.03.05_covid-19-vaccines_00-018.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"19% of U.S. adults say they\u2019ve received at least one dose of a COVID-19 vaccine","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/122660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=122660"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":104845,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/104845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}