{"id":122447,"date":"2020-09-21T23:08:06","date_gmt":"2020-09-22T04:08:06","guid":{"rendered":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png"},"modified":"2020-09-21T23:08:06","modified_gmt":"2020-09-22T04:08:06","slug":"ps_2020-09-29_global-science_04-05-png","status":"inherit","type":"attachment","link":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/science\/2020\/09\/29\/publics-express-a-mix-of-views-on-ai-childhood-vaccines-food-and-space-issues\/ps_2020-09-29_global-science_04-05-png\/","title":{"rendered":"In most places surveyed, majorities see preventive health benefits in childhood vaccines"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-122447","attachment","type-attachment","status-inherit","hentry"],"filename":"PS_2020.09.29_global-science_04-05.png","filesize":135454,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png'><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"300\" src=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=177\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows in most places surveyed, majorities see preventive health benefits in childhood vaccines\" srcset=\"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png 840w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=177,300 177w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=768,1304 768w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=603,1024 603w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=239,405 239w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=200,340 200w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=260,441 260w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=310,526 310w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=420,713 420w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=640,1086 640w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=740,1256 740w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=160,272 160w, https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?resize=320,543 320w\" sizes=\"auto, (max-width: 177px) 100vw, 177px\" data-has-transparency=\"false\" data-dominant-color=\"d7dddb\" style=\"--dominant-color: #d7dddb;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows in most places surveyed, majorities see preventive health benefits in childhood vaccines","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1426,"file":"2020\/09\/PS_2020.09.29_global-science_04-05.png","filesize":135454,"sizes":{"thumbnail":{"file":"PS_2020.09.29_global-science_04-05.png?resize=150,150","width":150,"height":150,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=150&h=150&crop=1"},"medium":{"file":"PS_2020.09.29_global-science_04-05.png?resize=177,300","width":177,"height":300,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=177"},"medium_large":{"file":"PS_2020.09.29_global-science_04-05.png?resize=768,1304","width":768,"height":1304,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=640"},"large":{"file":"PS_2020.09.29_global-science_04-05.png?resize=603,1024","width":603,"height":1024,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=603"},"A1":{"file":"PS_2020.09.29_global-science_04-05.png?resize=564,317","width":564,"height":317,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,634","width":840,"height":634,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PS_2020.09.29_global-science_04-05.png?resize=690,388","width":690,"height":388,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,776","width":840,"height":776,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=776&crop=1"},"A2":{"file":"PS_2020.09.29_global-science_04-05.png?resize=268,151","width":268,"height":151,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=536,302","width":536,"height":302,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PS_2020.09.29_global-science_04-05.png?resize=690,388","width":690,"height":388,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,776","width":840,"height":776,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=776&crop=1"},"A3":{"file":"PS_2020.09.29_global-science_04-05.png?resize=194,110","width":194,"height":110,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=388,220","width":388,"height":220,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PS_2020.09.29_global-science_04-05.png?resize=148,84","width":148,"height":84,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=296,168","width":296,"height":168,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=296&h=168&crop=1"},"A4":{"file":"PS_2020.09.29_global-science_04-05.png?resize=268,151","width":268,"height":151,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=536,302","width":536,"height":302,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PS_2020.09.29_global-science_04-05.png?resize=690,388","width":690,"height":388,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,776","width":840,"height":776,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=776&crop=1"},"XL":{"file":"PS_2020.09.29_global-science_04-05.png?resize=720,405","width":720,"height":405,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,810","width":840,"height":810,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=810&crop=1"},"social":{"file":"PS_2020.09.29_global-science_04-05.png?resize=840,628","width":840,"height":628,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=840&h=628&crop=1"},"chapter":{"file":"PS_2020.09.29_global-science_04-05.png?resize=239,405","width":239,"height":405,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=239"},"200-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=200,340","width":200,"height":340,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=200"},"260-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=260,441","width":260,"height":441,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=260"},"310-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=310,526","width":310,"height":526,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=310"},"420-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=420,713","width":420,"height":713,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=420"},"640-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=640,1086","width":640,"height":1086,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=640"},"740-wide":{"file":"PS_2020.09.29_global-science_04-05.png?resize=740,1256","width":740,"height":1256,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=740"},"75-square":{"file":"PS_2020.09.29_global-science_04-05.png?resize=75,75","width":75,"height":75,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=75&h=75&crop=1"},"140-square":{"file":"PS_2020.09.29_global-science_04-05.png?resize=140,140","width":140,"height":140,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=140&h=140&crop=1"},"260-square":{"file":"PS_2020.09.29_global-science_04-05.png?resize=260,260","width":260,"height":260,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PS_2020.09.29_global-science_04-05.png?resize=160,272","width":160,"height":272,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=160"},"320-portrait":{"file":"PS_2020.09.29_global-science_04-05.png?resize=320,543","width":320,"height":543,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=320"},"200-by-133":{"file":"PS_2020.09.29_global-science_04-05.png?resize=200,133","width":200,"height":133,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PS_2020.09.29_global-science_04-05.png?resize=740,416","width":740,"height":416,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PS_2020.09.29_global-science_04-05.png?resize=540,304","width":540,"height":304,"filesize":135454,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png?w=540&h=304&crop=1"},"full":{"file":"PS_2020.09.29_global-science_04-05.png","width":840,"height":1426,"mime_type":"image\/png","source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d7dddb","has_transparency":false},"post":104770,"source_url":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_global-science_04-05.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"In most places surveyed, majorities see preventive health benefits in childhood vaccines","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/122447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=122447"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":104770,"href":"https:\/\/alpha.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/104770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}